{"id":44050,"count":1,"description":"Auto Added by WPeMatico","link":"https:\/\/redept.com.br\/blogosfera\/category\/alienacao-de-bens-publicos\/","name":"aliena\u00e7\u00e3o de bens p\u00fablicos","slug":"alienacao-de-bens-publicos","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories\/44050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts?categories=44050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}