{"id":10132,"date":"2025-01-09T12:52:17","date_gmt":"2025-01-09T15:52:17","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/governo-quer-expandir-comercio-eletronico-no-norte-nordeste-e-centro-oeste\/"},"modified":"2025-01-09T12:52:17","modified_gmt":"2025-01-09T15:52:17","slug":"governo-quer-expandir-comercio-eletronico-no-norte-nordeste-e-centro-oeste","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/governo-quer-expandir-comercio-eletronico-no-norte-nordeste-e-centro-oeste\/","title":{"rendered":"Governo quer expandir com\u00e9rcio eletr\u00f4nico no Norte, Nordeste e Centro-Oeste"},"content":{"rendered":"<p><img loading=\"lazy\" width=\"1024\" height=\"613\"src=\"https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/01\/compra_online2411203173.jpg\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vermelho.org.br\/wp-content\/uploads\/2023\/07\/compra_online2411203173-1024x613.jpg 1024w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2023\/07\/compra_online2411203173-300x179.jpg 300w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2023\/07\/compra_online2411203173-768x459.jpg 768w, https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/01\/compra_online2411203173.jpg 1170w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/p>\n<p>Continuam abertas at\u00e9 o dia 17 de fevereiro as inscri\u00e7\u00f5es para o edital E-commerce.BR, que pretende fomentar o com\u00e9rcio eletr\u00f4nico no Norte, Nordeste e Centro-Oeste. Com investimento de R$ 4,92 milh\u00f5es, o governo federal vai selecionar projetos nas tr\u00eas regi\u00f5es.<\/p>\n<p>Lan\u00e7ado no m\u00eas passado pelo Minist\u00e9rio do Desenvolvimento, Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (MDIC) e pela Ag\u00eancia Brasileira de Desenvolvimento Industrial (ABDI), o edital vai premiar solu\u00e7\u00f5es inovadoras que ajudem as micro, pequenas e m\u00e9dias empresas a superar desafios relacionados \u00e0 log\u00edstica, capacita\u00e7\u00e3o digital e comunica\u00e7\u00e3o online.<\/p>\n<p>O MDIC avisa que as propostas dever\u00e3o ser apresentadas por redes de inova\u00e7\u00e3o, compostas por, no m\u00ednimo, tr\u00eas institui\u00e7\u00f5es p\u00fablicas ou privadas de \u00e2mbito estadual ou municipal.<\/p>\n<p>Leia mais: <a href=\"https:\/\/vermelho.org.br\/2023\/07\/13\/cenario-economico-melhora-e-vendas-de-eletroeletronicos-crescem-13\/\">Cen\u00e1rio econ\u00f4mico melhora e vendas de eletroeletr\u00f4nicos crescem 13%<\/a><\/p>\n<p>O secret\u00e1rio executivo do MDIC, M\u00e1rcio Elias Rosa, afirma que a iniciativa visa n\u00e3o s\u00f3 reduzir as desigualdades regionais no acesso ao mercado digital, mas tamb\u00e9m promover a inclus\u00e3o digital das micro, pequenas e m\u00e9dias empresa no pa\u00eds.<\/p>\n<p>\u201c\u00c9 preciso levar ou oferecer essas ferramentas de com\u00e9rcio eletr\u00f4nico para todas as regi\u00f5es. At\u00e9 porque elas s\u00e3o absolutamente estrat\u00e9gicas. N\u00f3s estamos falando de cerca de 70% do PIB. Mais de 60% de toda a for\u00e7a de trabalho no Brasil \u00e9 atrelada ao com\u00e9rcio e servi\u00e7o. E s\u00e3o setores que v\u00eam respondendo muito positivamente nesse novo crescimento da economia no Brasil\u201d, avalia o secret\u00e1rio.<\/p>\n<p>De acordo com ele, o governo federal trabalha permanentemente na perspectiva da integra\u00e7\u00e3o da economia em todo o Brasil. \u201cQuanto mais n\u00f3s conseguimos fazer isso, mais n\u00f3s aceleramos o desenvolvimento econ\u00f4mico e garantimos o desenvolvimento social\u201d, diz.<\/p>\n<p>A decis\u00e3o do governo levou em conta um levantamento realizado pelo MDIC por meio do Observat\u00f3rio do Com\u00e9rcio Eletr\u00f4nico Nacional. Nele, consta que somente o Sudeste concentra 73,5% das vendas online no pa\u00eds contra 7% do Nordeste, 3% do Centro-Oeste e 1,3% do Norte.<\/p>\n<p>A ABDI espera impactar mais de 800 empresas nas tr\u00eas regi\u00f5es, que ser\u00e3o atendidas com a inclus\u00e3o digital e gera\u00e7\u00e3o de empregos.<\/p>\n<p>O presidente da ABDI, Ricardo Capelli, refor\u00e7a a necessidade de participa\u00e7\u00e3o das universidades, institutos, statups e centros tecn\u00f3gicos, entre outros.<\/p>\n<p>\u201cCom isso, a gente consegue analisar e selecionar projetos voltados para capacita\u00e7\u00e3o profissional e de pessoal das empresas, quest\u00f5es relacionadas \u00e0 entrega e distribui\u00e7\u00e3o, log\u00edstica e tamb\u00e9m comunica\u00e7\u00e3o digital\u201d, explica.<\/p>\n<p><em>Com informa\u00e7\u00f5es da Ascom\/MDIC<\/em><\/p>\n<\/p>\n<p>O post <a href=\"https:\/\/vermelho.org.br\/2025\/01\/09\/governo-quer-expandir-comercio-eletronico-no-norte-nordeste-e-centro-oeste\/\">Governo quer expandir com\u00e9rcio eletr\u00f4nico no Norte, Nordeste e Centro-Oeste<\/a> apareceu primeiro em <a href=\"https:\/\/vermelho.org.br\/\">Vermelho<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/critica-da-teoria-do-valor-atencao\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/09\/7-16-25-v1-800x450-1-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Cr\u00edtica da teoria do valor-aten\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/inspirado-em-ideias-do-papa-francisco-encontro-em-pe-discute-novos-modelos-de-economia-e-sociedade\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Inspirado em ideias do Papa Francisco, encontro em...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/apos-pressao-do-mst-governo-promete-solucao-para-maior-acampamento-sem-terra-do-pais\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ap\u00f3s press\u00e3o do MST, governo promete solu\u00e7\u00e3o para ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/reeleicao-de-noboa-reforca-desuniao-da-america-do-sul-que-fica-mais-dependente-de-paises-ricos-diz-professora\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Reelei\u00e7\u00e3o de Noboa refor\u00e7a desuni\u00e3o da Am\u00e9rica do ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Continuam abertas at\u00e9 o dia 17 de fevereiro as inscri\u00e7\u00f5es para o edital E-commerce.BR, que pretende fomentar o com\u00e9rcio eletr\u00f4nico no Norte, Nordeste e Centro-Oeste. Com investimento de R$ 4,92 milh\u00f5es, o governo federal vai selecionar projetos nas tr\u00eas regi\u00f5es. Lan\u00e7ado no m\u00eas passado pelo Minist\u00e9rio do Desenvolvimento, Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os (MDIC) e pela [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10133,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[3095,221,2337,17],"tags":[],"class_list":["post-10132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comercio-eletronico","category-economia","category-expansao","category-governo-lula"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/10132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=10132"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/10132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media\/10133"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=10132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=10132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=10132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}