{"id":23031,"date":"2025-04-19T16:05:21","date_gmt":"2025-04-19T19:05:21","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/suprema-corte-proibe-trump-de-usar-lei-de-inimigos-para-deportacoes\/"},"modified":"2025-04-19T16:05:21","modified_gmt":"2025-04-19T19:05:21","slug":"suprema-corte-proibe-trump-de-usar-lei-de-inimigos-para-deportacoes","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/suprema-corte-proibe-trump-de-usar-lei-de-inimigos-para-deportacoes\/","title":{"rendered":"Suprema Corte pro\u00edbe Trump de usar Lei de Inimigos para deporta\u00e7\u00f5es"},"content":{"rendered":"<p><img loading=\"lazy\" width=\"1024\" height=\"576\"src=\"https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/04\/cecot-elsavador_prensagrafica_wikimedia-cc.jpg\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/04\/cecot-elsavador_prensagrafica_wikimedia-cc-1024x576.jpg 1024w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/04\/cecot-elsavador_prensagrafica_wikimedia-cc-300x169.jpg 300w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/04\/cecot-elsavador_prensagrafica_wikimedia-cc-768x432.jpg 768w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/04\/cecot-elsavador_prensagrafica_wikimedia-cc-1536x864.jpg 1536w, https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/04\/cecot-elsavador_prensagrafica_wikimedia-cc.jpg 1890w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/p>\n<p>O presidente dos EUA, Donald Trump, foi proibido neste s\u00e1bado (19), pela Suprema Corte do pa\u00eds, de usar a Lei de Inimigos Estrangeiros, de 1798, para deportar venezuelanos para uma pris\u00e3o em El Salvador.<\/p>\n<p>A decis\u00e3o contou com o voto de sete dos nove magistrados da Corte e \u00e9 tempor\u00e1ria \u2014 sua validade se estende at\u00e9 que o caso seja analisado de forma definitiva.<\/p>\n<p>\u201cO governo \u00e9 instru\u00eddo a n\u00e3o remover nenhum membro da suposta classe de detentos dos Estados Unidos at\u00e9 nova ordem deste tribunal\u201d, diz a senten\u00e7a.<\/p>\n<p>A lei em quest\u00e3o tem sido usado pelo republicano para respaldar a deporta\u00e7\u00e3o de 238 imigrantes do pa\u00eds latino-americano, sem que eles tenham tido direito de apela\u00e7\u00e3o, sob a acusa\u00e7\u00e3o deles supostamente fazerem parte de uma organiza\u00e7\u00e3o criminosa.<\/p>\n<p>Familiares dos imigrantes deportados sob essa lei negam as acusa\u00e7\u00f5es e o governo da Venezuela recorreu ao Conselho de Direitos Humanos da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) contra as deporta\u00e7\u00f5es.<\/p>\n<p>No dia 7 de abril, a Suprema Corte dos EUA autorizou o uso da lei desde que os imigrantes tivessem o direito de contestar a deporta\u00e7\u00e3o. Por\u00e9m, organiza\u00e7\u00f5es de direitos humanos recorreram aos tribunais alegando que o governo Trump n\u00e3o estava respeitando a decis\u00e3o.<\/p>\n<p>O governo de El Salvador, que h\u00e1 tr\u00eas anos governa por meio de decretos de estado de exce\u00e7\u00e3o, tem recebido prisioneiros enviados pelos EUA em troca de ajuda financeira e de \u201cintelig\u00eancia\u201d do governo Trump.<\/p>\n<p>O Centro de Confinamento de Terroristas (Cecot) de El Salvador, conhecida como maior pris\u00e3o da Am\u00e9rica Latina, constru\u00edda pelo presidente Nayib Bukele, \u00e9 alvo de den\u00fancias de viola\u00e7\u00f5es de direitos humanos com pr\u00e1tica sistem\u00e1tica de tortura, incluindo contra crian\u00e7as, e por n\u00e3o conceder aos suspeitos direitos \u00e0 defesa e julgamento justo, com condena\u00e7\u00f5es em massa.<\/p>\n<p>Com Ag\u00eancia Brasil<\/p>\n<p>O post <a href=\"https:\/\/vermelho.org.br\/2025\/04\/19\/suprema-corte-proibe-trump-de-usar-lei-de-inimigos-para-deportacoes\/\">Suprema Corte pro\u00edbe Trump de usar Lei de Inimigos para deporta\u00e7\u00f5es<\/a> apareceu primeiro em <a href=\"https:\/\/vermelho.org.br\/\">Vermelho<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/lei-de-alienacao-parental-completa-15-anos-sob-criticas-de-silenciamento-de-mulheres-e-criancas\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/08\/image_processing20241219-2385620-lmlmbl-150x150.webp') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Lei de Aliena\u00e7\u00e3o Parental completa 15 anos sob cr\u00ed...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/ira-estaria-disposto-a-dar-garantias-de-que-nao-produz-armas-nucleares\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/04\/Aragchi-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ir\u00e3 estaria disposto a dar garantias de que n\u00e3o pr...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/onze-anos-de-teimosia-como-o-bixiga-ensina-o-circuito-comercial\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/02\/Banner_site_HP_900x450_2026-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Onze anos de teimosia: como o Bixiga ensina o circ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/sul21.com.br\/noticias\/geral\/2025\/11\/mais-de-150-mil-clientes-da-ceee-equatorial-seguem-sem-energia-apos-ciclone\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Mais de 150 mil clientes da CEEE Equatorial seguem...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>O presidente dos EUA, Donald Trump, foi proibido neste s\u00e1bado (19), pela Suprema Corte do pa\u00eds, de usar a Lei de Inimigos Estrangeiros, de 1798, para deportar venezuelanos para uma pris\u00e3o em El Salvador. A decis\u00e3o contou com o voto de sete dos nove magistrados da Corte e \u00e9 tempor\u00e1ria \u2014 sua validade se estende [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23032,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[307,1077,50,5194,1453],"tags":[],"class_list":["post-23031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-direitos-humanos","category-el-salvador","category-internacional","category-nayib-bukele","category-trump"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/23031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=23031"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/23031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media\/23032"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=23031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=23031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=23031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}