{"id":26395,"date":"2025-05-08T18:08:03","date_gmt":"2025-05-08T21:08:03","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/congresso-internacional-destaca-papel-dos-irmaos-leigos-na-ordem-dos-frades-menores\/"},"modified":"2025-05-08T18:08:03","modified_gmt":"2025-05-08T21:08:03","slug":"congresso-internacional-destaca-papel-dos-irmaos-leigos-na-ordem-dos-frades-menores","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/congresso-internacional-destaca-papel-dos-irmaos-leigos-na-ordem-dos-frades-menores\/","title":{"rendered":"Congresso Internacional destaca papel dos irm\u00e3os leigos na Ordem dos Frades Menores"},"content":{"rendered":"<p>A cidade de Assis, na It\u00e1lia, foi palco de um encontro da <a href=\"https:\/\/franciscanos.org.br\/\">Ordem dos Frades Menores (OFM)<\/a>: o Congresso Internacional de Irm\u00e3os Leigos. O encontro se deu ap\u00f3s dois anos de prepara\u00e7\u00e3o em todo o mundo, em n\u00edvel de confer\u00eancia, de 28 de abril a 2 de maio, apontando os representantes eleitos para o congresso onde foram debatidos os temas <a href=\"https:\/\/www.brasildefato.com.br\/2025\/03\/05\/campanha-da-fraternidade-convida-a-reflexao-sobre-crise-socioambiental\/\">Fraternidade <\/a>e Minoridade, Miss\u00f5es e Evangeliza\u00e7\u00e3o, Forma\u00e7\u00e3o e Estudos.<\/p>\n<p>As atividades tiveram como foco a reflex\u00e3o sobre a identidade e a miss\u00e3o dos irm\u00e3os leigos na contemporaneidade, com destaque para a viv\u00eancia da fraternidade, o est\u00edmulo \u00e0 forma\u00e7\u00e3o cont\u00ednua e o fortalecimento do <a href=\"https:\/\/www.brasildefato.com.br\/2024\/11\/21\/nao-existe-uma-crise-ecologica-e-outra-social-e-uma-crise-socioambiental-diz-bispo-da-cnbb\/\">compromisso<\/a> com a evangeliza\u00e7\u00e3o e o servi\u00e7o aos mais necessitados. <\/p>\n<p>Durante os cinco dias de programa\u00e7\u00e3o, os participantes compartilharam experi\u00eancias, testemunhos e pr\u00e1ticas que refor\u00e7am o carisma franciscano na vida cotidiana. A comiss\u00e3o organizadora ressaltou a riqueza da diversidade cultural dos frades presentes e apontou o evento como oportunidade valiosa de integra\u00e7\u00e3o e fortalecimento da vida comunit\u00e1ria dentro da Ordem.<\/p>\n<figure><\/figure>\n<h4>Destaque para a presen\u00e7a brasileira<\/h4>\n<p>O Brasil esteve fortemente representado no congresso, com a participa\u00e7\u00e3o de frades de v\u00e1rias prov\u00edncias. O <strong>Brasil de Fato RS<\/strong> e o <a href=\"https:\/\/padrejosimo.com.br\/\">Instituto Cultural Padre Josimo<\/a> mantiveram contato com o frei Patr\u00edcio Ceretta, que acompanhou todas as atividades do encontro. Segundo ele, a participa\u00e7\u00e3o brasileira refor\u00e7ou o empenho das prov\u00edncias em fortalecer a voca\u00e7\u00e3o dos irm\u00e3os leigos e renovar sua presen\u00e7a nas comunidades locais, mantendo viva a heran\u00e7a de S\u00e3o Francisco de Assis no contexto brasileiro e latino-americano.<\/p>\n<p>Na din\u00e2mica proposta foram realizadas palestras seguidas de debates em grupo, retornando \u00e0 assembleia com propostas a serem apresentadas ao governo geral da ordem que em sua quase totalidade se fazia presente. Conforme explicou frei Patr\u00edcio, esse encontro tem a tarefa de propor algo concreto para o cap\u00edtulo geral que vai acontecer em 2026, justamente com uma preocupa\u00e7\u00e3o da ordem com a quest\u00e3o da <a href=\"https:\/\/www.ihu.unisinos.br\/categorias\/593357-papa-francisco-contra-a-clericalizacao-do-laicato\">clericaliza\u00e7\u00e3o<\/a> e a necessidade de propor processos formativos, de evangeliza\u00e7\u00e3o e de vida fraterna a partir dessa primeira experi\u00eancia nossa comum, que \u00e9 o \u201cser irm\u00e3o\u201d.<\/p>\n<figure><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\"src=\"https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-28-at-161303-960x570-1.jpeg\" alt=\"\" srcset=\"https:\/\/assets.brasildefato.com.br\/2025\/05\/WhatsApp-Image-2025-04-28-at-16.13.03-300x225.jpeg 300w, https:\/\/assets.brasildefato.com.br\/2025\/05\/WhatsApp-Image-2025-04-28-at-16.13.03-768x576.jpeg 768w, https:\/\/assets.brasildefato.com.br\/2025\/05\/WhatsApp-Image-2025-04-28-at-16.13.03-750x536.jpeg 750w, https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-04-28-at-161303-960x570-1.jpeg 960w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\"><figcaption>Freis Fabio Lamour (Brasil), Nicolas Aguilar (Argentina), Patr\u00edcio Ceretta (Brasil), C\u00e9sar Kilquen (Brasil), Bruno Laviola (Argentina) e Diego Omar Figueroa (Argentina) \u2013 Foto: Comunica\u00e7\u00e3o OFM<\/figcaption><\/figure>\n<p>Frei Patr\u00edcio apresenta o recorte final da fala do Ministro Geral, que destacou a import\u00e2ncia da identidade dos Frades Menores como irm\u00e3os, para al\u00e9m de qualquer distin\u00e7\u00e3o entre cl\u00e9rigos e leigos. Em sua mensagem, ele recordou as palavras do Testamento de S\u00e3o Francisco: \u201cO Senhor me deu irm\u00e3os\u201d, destacando como essa fraternidade \u00e9 o cora\u00e7\u00e3o do carisma franciscano.<\/p>\n<p>O ministro tamb\u00e9m refletiu sobre a necessidade de uma profunda convers\u00e3o de mentalidade e cultura na Ordem, alertando contra o clericalismo que pode deformar o carisma franciscano. Ele convidou todos os frades a retornarem \u00e0s suas fraternidades com o cora\u00e7\u00e3o renovado, levando consigo a vis\u00e3o e a proximidade de Jesus a servi\u00e7o do povo de Deus.<\/p>\n<h4>Resultados e encaminhamentos<\/h4>\n<p>O congresso deixou frutos concretos para a caminhada da Ordem. Entre os principais resultados est\u00e1 o reconhecimento renovado da voca\u00e7\u00e3o dos irm\u00e3os leigos, com valoriza\u00e7\u00e3o do seu papel na miss\u00e3o franciscana.<\/p>\n<p>Tamb\u00e9m pode ser destacado o fortalecimento dos la\u00e7os internacionais, promovendo interc\u00e2mbio entre frades de diferentes regi\u00f5es e culturas e o compromisso com a forma\u00e7\u00e3o permanente, visando uma atua\u00e7\u00e3o mais qualificada e espiritualmente enraizada.<\/p>\n<p>Ainda se aponta como destaques o encorajamento \u00e0 evangeliza\u00e7\u00e3o e a\u00e7\u00e3o social, especialmente entre os mais pobres e vulner\u00e1veis, bem como a defini\u00e7\u00e3o de diretrizes para o futuro, com propostas para sustentar e aprofundar a miss\u00e3o dos irm\u00e3os leigos nos pr\u00f3ximos anos.<\/p>\n<p>Com ampla repercuss\u00e3o entre as fraternidades da Ordem dos Frades Menores, o congresso serviu para reafirmar o compromisso com uma vida fraterna, simples e comprometida com o Evangelho \u2013 alicer\u00e7ada no exemplo de <a href=\"https:\/\/www.brasildefato.com.br\/2019\/10\/04\/artigo-or-francisco-de-assis-um-antecipador-da-historia\/\">S\u00e3o Francisco de Assis<\/a> e voltada aos desafios do mundo atual.<\/p>\n<figure><a href=\"https:\/\/api.whatsapp.com\/send?phone=5551998132796&amp;text=Quero%20receber%20not%C3%ADcias%20do%20Brasil%20de%20Fato%20RS\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"92\"src=\"https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/05\/image-2-9.png\" alt=\"\" srcset=\"https:\/\/assets.brasildefato.com.br\/2025\/05\/image-2-300x35.png 300w, https:\/\/assets.brasildefato.com.br\/2025\/05\/image-2-768x88.png 768w, https:\/\/assets.brasildefato.com.br\/2025\/05\/image-2-750x92.png 750w, https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/05\/image-2-9.png 800w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\"><\/a><\/figure>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/groenlandia-e-dinamarca-realizam-protestos-contra-as-ambicoes-territoriais-de-trump\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/01\/g-3pzcew8aauy89-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Groenl\u00e2ndia e Dinamarca realizam protestos contra ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/qual-e-a-importancia-da-companhia-de-desenvolvimento-economico-de-mg-na-transicao-energetica\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Qual \u00e9 a import\u00e2ncia da Companhia de Desenvolvimen...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/pago-luz-e-agua-ha-mais-de-um-ano-e-eles-vem-e-derrubam-a-casa-da-gente\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/05\/P8-_-Joinville-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">\u201cPago luz e \u00e1gua h\u00e1 mais de um ano, e eles v\u00eam e d...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/justica-agenda-vistoria-em-obras-de-captacao-de-agua-subterranea-em-viamao\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Justi\u00e7a agenda vistoria em obras de capta\u00e7\u00e3o de \u00e1g...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>A cidade de Assis, na It\u00e1lia, foi palco de um encontro da Ordem dos Frades Menores (OFM): o Congresso Internacional de Irm\u00e3os Leigos. O encontro se deu ap\u00f3s dois anos de prepara\u00e7\u00e3o em todo o mundo, em n\u00edvel de confer\u00eancia, de 28 de abril a 2 de maio, apontando os representantes eleitos para o congresso [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":26396,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[94,201],"tags":[],"class_list":["post-26395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-papa-francisco"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/26395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=26395"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/26395\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media\/26396"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=26395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=26395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=26395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}