{"id":26427,"date":"2025-05-08T20:47:39","date_gmt":"2025-05-08T23:47:39","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/papa-leao-14-renova-a-esperanca-e-sinaliza-continuidade-do-legado-de-francisco-acredita-bispo\/"},"modified":"2025-05-08T20:47:39","modified_gmt":"2025-05-08T23:47:39","slug":"papa-leao-14-renova-a-esperanca-e-sinaliza-continuidade-do-legado-de-francisco-acredita-bispo","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/papa-leao-14-renova-a-esperanca-e-sinaliza-continuidade-do-legado-de-francisco-acredita-bispo\/","title":{"rendered":"Papa Le\u00e3o 14 \u2018renova a esperan\u00e7a\u2019 e sinaliza continuidade do legado de Francisco, acredita bispo"},"content":{"rendered":"<p>Em entrevista ao programa <em><a href=\"https:\/\/www.youtube.com\/watch?v=473cK0KcNb0\">Conex\u00e3o BdF<\/a>, <\/em>da <strong>R\u00e1dio Brasil de Fato<\/strong>, o bispo auxiliar da Arquidiocese de Olinda e Recife, Dom Nereudo Freire Henrique, avaliou que a escolha de Robert Prevost como <a href=\"https:\/\/www.brasildefato.com.br\/2025\/05\/08\/missionario-e-estadunidense-novo-papa-se-chamara-leao-14\/\">o novo papa Le\u00e3o 14 <\/a>traz sinais de continuidade do <a href=\"https:\/\/www.brasildefato.com.br\/?s=papa+francisco\">legado de Francisco<\/a>, especialmente na defesa da paz, da vida e do acolhimento aos mais pobres e marginalizados. O religioso acredita que a escolha surpreendente \u2013 uma vez que Prevost n\u00e3o era apontado como favorito \u2013 refor\u00e7a a l\u00f3gica divina e, assim, espera que o pont\u00edfice eleito siga o evangelho, como seu antecessor.<\/p>\n<p>\u201c<a href=\"https:\/\/www.brasildefato.com.br\/2025\/04\/21\/papa-francisco-morre-mas-deixa-legado-da-alegria-do-evangelho-da-verdade-e-do-amor\/\">Papa Francisco<\/a> conseguiu ser o verdadeiro disc\u00edpulo de Jesus como papa. Ele sinalizou para o mundo e convocou a igreja a ser aberta para acolher a todos, os pobres, os indefesos, os migrantes, o povo sofrido que vive nas periferias existenciais, nas periferias geogr\u00e1ficas. O papa Le\u00e3o 14 tamb\u00e9m sinaliza para que a vida seja respeitada\u201d, disse. \u201cEnt\u00e3o, eu particularmente vivo um momento de renova\u00e7\u00e3o da esperan\u00e7a porque eu tenho certeza de que Deus est\u00e1 agindo. E com o novo papa, n\u00f3s vamos continuar\u201d, concluiu.<\/p>\n<p>\u201cEstamos vivendo uma profunda emo\u00e7\u00e3o. O papa inicia sua fala dizendo: \u2018A paz esteja conosco\u2019. \u00c9 a mesma paz anunciada por Jesus aos disc\u00edpulos\u201d, afirmou.<\/p>\n<p>Prevost, que foi bispo no Peru antes de ser nomeado cardeal, tem um \u201colhar diferenciado\u201d para a Am\u00e9rica Latina, segundo Dom Nereudo, e demonstra compromisso com uma igreja mission\u00e1ria e voltada aos que vivem nas periferias. \u201cDesde sua primeira fala como papa, mostra ser sens\u00edvel \u00e0 vida e comprometido com um mundo mais fraterno e justo\u201d, observa.<\/p>\n<p>Para o bispo, o novo papa \u00e9 um homem \u201cm\u00edstico\u201d, com profundo conhecimento teol\u00f3gico. A refer\u00eancia \u00e0 espiritualidade de santo Agostinho, ordem \u00e0 qual Prevost pertence, refor\u00e7a essa dimens\u00e3o. \u201c\u00c9 um homem de Deus. A forma como se apresentou, pedindo a intercess\u00e3o de Nossa Senhora, sinaliza isso\u201d, afirma. \u201cMe parece que o papa Le\u00e3o 14 pode dar continuidade ao evangelho, vai coincidir com o testemunho de Francisco\u201d.\u00a0<\/p>\n<figure>\n<div>\n<div><\/div>\n<\/div>\n<\/figure>\n<h4>Novo papa herda miss\u00e3o de manter fi\u00e9is conquistados por Francisco<\/h4>\n<p>A estabilidade recente no n\u00famero de <a href=\"https:\/\/www.brasildefato.com.br\/?s=catolicos\">fi\u00e9is cat\u00f3licos<\/a>, ap\u00f3s anos de queda, pode ser explicada pelo testemunho de figuras como o papa Francisco. Para Dom Nereudo, o pont\u00edfice argentino teve um papel essencial em reacender a f\u00e9 de muitos: \u201cEle conseguiu dar exemplo de que era um homem de Deus aberto para acolher. Quando voc\u00ea acolhe, quando voc\u00ea \u00e9 sens\u00edvel, quando voc\u00ea vai aos necessitados, aos pequenos, voc\u00ea vai dar um testemunho de amor\u201d.<\/p>\n<p>O bispo defende que o exemplo vale tanto quanto a prega\u00e7\u00e3o: \u201cN\u00f3s entendemos, \u00e0s vezes, que a evangeliza\u00e7\u00e3o passa apenas pelo an\u00fancio, pela palavra, que \u00e9 fundamental. Mas \u00e9 fundamental tamb\u00e9m o testemunho\u201d.<\/p>\n<p>Na sua avalia\u00e7\u00e3o, a postura de servi\u00e7o do papa Francisco, que relembrou durante a Semana Santa um momento em que Jesus teria lavado os p\u00e9s dos seus disc\u00edpulos, sinaliza que a Igreja deve abandonar posturas autorit\u00e1rias e se aproximar da compaix\u00e3o: \u201cO disc\u00edpulo de Jesus \u00e9 aquele que serve. Quem quiser ser o maior tem que ser o menor\u201d, resume.<\/p>\n<p>Le\u00e3o 14, deve dar continuidade a esse caminho iniciado por Francisco, indica o religioso. \u201cA miss\u00e3o da Igreja \u00e9 cada vez mais dar um testemunho de que \u00e9 poss\u00edvel construir um mundo diferente. Mas n\u00e3o podemos continuar com a arrog\u00e2ncia, com a viol\u00eancia, nos tornarmos pessoas indiferentes ao outro irm\u00e3o. Temos que ter compaix\u00e3o\u201d, afirma. \u201cO papel do bispo \u00e9 construir a unidade, o homem de comunh\u00e3o com Deus, com o episcopado, com o clero e com o povo\u201d.<\/p>\n<h4>Para ouvir e assistir<\/h4>\n<p>O jornal\u00a0<em>Conex\u00e3o BdF<\/em>\u00a0vai ao ar em duas edi\u00e7\u00f5es, de segunda a sexta-feira, uma \u00e0s 9h e outra \u00e0s 17h, na\u00a0<strong><a href=\"https:\/\/radiobrasildefato.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">R\u00e1dio Brasil de Fato<\/a><\/strong>,\u00a0<strong>98.9 FM<\/strong>\u00a0na Grande S\u00e3o Paulo, com transmiss\u00e3o simult\u00e2nea tamb\u00e9m pelo\u00a0<a href=\"https:\/\/www.youtube.com\/@brasildefato\/playlists\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube do\u00a0<strong>Brasil de Fato<\/strong><\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/video-do-ano-lula-79-comanda-corrida-com-ministros-para-comemorar-os-95-anos-do-mec\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">V\u00eddeo do ano: Lula, 79, comanda corrida com minist...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/oposicao-tenta-boicotar-projeto-de-isencao-do-ir-mas-nao-deve-encontrar-apoio-dizem-analistas\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Oposi\u00e7\u00e3o tenta boicotar projeto de isen\u00e7\u00e3o do IR m...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/feira-do-livro-da-rocha-ocupa-bairro-do-bixiga-em-sp-com-programacao-gratuita-e-debate-sobre-bem-viver\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Feira do Livro da Rocha ocupa bairro do Bixiga, em...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/coreia-e-japao-2002-o-penta-que-consagrou-a-volta-do-fenomeno\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/06\/IMG-20260612-WA0038-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Coreia e Jap\u00e3o, 2002: o penta que consagrou a volt...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Em entrevista ao programa Conex\u00e3o BdF, da R\u00e1dio Brasil de Fato, o bispo auxiliar da Arquidiocese de Olinda e Recife, Dom Nereudo Freire Henrique, avaliou que a escolha de Robert Prevost como o novo papa Le\u00e3o 14 traz sinais de continuidade do legado de Francisco, especialmente na defesa da paz, da vida e do acolhimento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[50],"tags":[],"class_list":["post-26427","post","type-post","status-publish","format-standard","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/26427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=26427"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/26427\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=26427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=26427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=26427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}