{"id":29609,"date":"2025-05-23T18:53:15","date_gmt":"2025-05-23T21:53:15","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/moraes-ameaca-prender-aldo-rebelo-por-desacato-em-depoimento-sobre-trama-golpista\/"},"modified":"2025-05-23T18:53:15","modified_gmt":"2025-05-23T21:53:15","slug":"moraes-ameaca-prender-aldo-rebelo-por-desacato-em-depoimento-sobre-trama-golpista","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/moraes-ameaca-prender-aldo-rebelo-por-desacato-em-depoimento-sobre-trama-golpista\/","title":{"rendered":"Moraes amea\u00e7a prender Aldo Rebelo por desacato em depoimento sobre trama golpista"},"content":{"rendered":"<p>Depoimento de Aldo Rebelo foi o mais conturbado da sequ\u00eancia de audi\u00eancias do processo, iniciada na segunda-feira (19).<\/p>\n<p>O ministro Alexandre de Moraes, do STF (Supremo Tribunal Federal), amea\u00e7ou nesta sexta-feira (23) prender Aldo Rebelo por desacato durante depoimento do ex-ministro da Defesa como testemunha do processo pela trama golpista.<\/p>\n<p>\u201cSe o senhor n\u00e3o se comportar, vai ser preso por desacato\u201d, disse Moraes depois de pedir que Aldo fosse objetivo nas perguntas e o ex-ministro afirmasse que \u201cn\u00e3o admito censura\u201d. \u201cEstou me comportando\u201d, respondeu o ex-ministro.<\/p>\n<p>O imbr\u00f3glio surgiu ap\u00f3s Aldo fazer coment\u00e1rios sobre a l\u00edngua portuguesa para questionar a inten\u00e7\u00e3o do ex-chefe da Marinha Almir Garnier Santos ao dizer, segundo testemunhas, que teria colocado tropas \u00e0 disposi\u00e7\u00e3o do ex-presidente Jair Bolsonaro na tentativa de golpe de 2022, de acordo com Cezar Feitoza, ICL.<\/p>\n<p>\u201cNa l\u00edngua portuguesa n\u00f3s conhecemos aquilo que se usa muitas vezes como a for\u00e7a da express\u00e3o. Ela nunca pode ser tomada literalmente. Quando algu\u00e9m diz que est\u00e1 frito, n\u00e3o significa que esteja dentro da frigideira. Ou que est\u00e1 apertado, n\u00e3o significa que esteja sendo submetido a um tipo de press\u00e3o literal\u201d, disse Aldo.<\/p>\n<p><imgsrc=\"\" alt=\"moraes\"><\/p>\n<p>O ex-ministro disse que, com essa premissa, n\u00e3o se poderia concluir que a suposta fala de Garnier sobre dar apoio armado aos planos de manter Bolsonaro no poder n\u00e3o poderia ser entendida de forma literal.<\/p>\n<p>Moraes interveio. Ele disse que Aldo n\u00e3o estava na reuni\u00e3o em que Garnier teria declarado anu\u00eancia a um golpe de Estado e, por isso, n\u00e3o poderia dar declara\u00e7\u00f5es sobre fatos que n\u00e3o testemunhou.<\/p>\n<p>\u201cA minha aprecia\u00e7\u00e3o da l\u00edngua portuguesa \u00e9 minha e n\u00e3o admito censura\u201d, respondeu o ex-ministro. O ministro do Supremo, em seguida, fez o comunicado sobre a poss\u00edvel pris\u00e3o por desacato.<\/p>\n<p><strong>Moraes e os depoimentos da trama golpista<\/strong><br \/>\nO depoimento de Aldo Rebelo foi o mais conturbado da sequ\u00eancia de audi\u00eancias do processo, iniciada na segunda-feira (19).<\/p>\n<p>R\u00e9us do n\u00facleo central da trama golpista<\/p>\n<p>\u2013 Jair Bolsonaro, ex-presidente da Rep\u00fablica<br \/>\n\u2013 Alexandre Ramagem, deputado federal e ex-chefe da Abin<br \/>\n\u2013 Almir Garnier, ex-comandante da Marinha<br \/>\n\u2013 Anderson Torres, ex-ministro da Justi\u00e7a<br \/>\n\u2013 Augusto Heleno, ex-ministro do GSI<br \/>\n\u2013 Mauro Cid, ex-ajudante de ordens de Bolsonaro<br \/>\n\u2013 Paulo S\u00e9rgio Nogueira, ex-ministro da Defesa<br \/>\n\u2013 Walter Braga Netto, ex-ministro da Casa Civil e da Defesa<\/p>\n<p><strong>Siga-nos no Whatsapp:<a href=\"https:\/\/chat.whatsapp.com\/HlpAeWDAUrD8Qq1AjWiCK5\"> https:\/\/chat.whatsapp.com\/HlpAeWDAUrD8Qq1AjWiCK5<\/a><\/strong><\/p>\n<p><strong>Siga-nos no Facebook:<a href=\"https:\/\/www.facebook.com\/profile.php?id=100070790366110\"> https:\/\/www.facebook.com\/profile.php?id=100070790366110<\/a><\/strong><\/p>\n<p><strong>Siga-nos no X: <a href=\"https:\/\/x.com\/Antropofagista1\">https:\/\/x.com\/Antropofagista1<\/a><\/strong><\/p>\n<p>\u00a0<\/p>\n<p>The post <a href=\"https:\/\/antropofagista.com.br\/2025\/05\/23\/moraes-ameaca-prender-aldo-rebelo-por-desacato-em-depoimento-sobre-trama-golpista\/\">Moraes amea\u00e7a prender Aldo Rebelo por desacato em depoimento sobre trama golpista<\/a> first appeared on <a href=\"https:\/\/antropofagista.com.br\/\">Antropofagista<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/senadores-condenam-abusos-de-trump-com-brasileiros-chega-de-viralatismo\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Senadores condenam abusos de Trump com brasileiros...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/lider-do-governo-esta-otimista-com-aprovacao-do-pacote-fiscal-e-orcamento\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2024\/12\/Randolfe-1-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">L\u00edder do governo est\u00e1 otimista com aprova\u00e7\u00e3o do pa...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/o-cocar-sagrado-o-tarifaco-de-trump-e-a-democracia-brasileira\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">O cocar sagrado, o tarifa\u00e7o de Trump e a democraci...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/chacina-no-rio-pt-pcdob-e-psol-pedem-ao-stf-acesso-das-familias-aos-corpos\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/IML-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Chacina no Rio: PT, PCdoB e PSOL pedem ao STF aces...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Depoimento de Aldo Rebelo foi o mais conturbado da sequ\u00eancia de audi\u00eancias do processo, iniciada na segunda-feira (19). O ministro Alexandre de Moraes, do STF (Supremo Tribunal Federal), amea\u00e7ou nesta sexta-feira (23) prender Aldo Rebelo por desacato durante depoimento do ex-ministro da Defesa como testemunha do processo pela trama golpista. \u201cSe o senhor n\u00e3o se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[6829,1795,6830,2143,132],"tags":[],"class_list":["post-29609","post","type-post","status-publish","format-standard","hentry","category-aldo-rebelo","category-depoimento","category-desacato","category-moraes","category-politica"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/29609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=29609"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/29609\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=29609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=29609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=29609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}