{"id":34291,"date":"2025-06-19T13:16:23","date_gmt":"2025-06-19T16:16:23","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/com-35-do-territorio-atingido-pelas-chuvas-canoas-decreta-situacao-de-emergencia\/"},"modified":"2025-06-19T13:16:23","modified_gmt":"2025-06-19T16:16:23","slug":"com-35-do-territorio-atingido-pelas-chuvas-canoas-decreta-situacao-de-emergencia","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/com-35-do-territorio-atingido-pelas-chuvas-canoas-decreta-situacao-de-emergencia\/","title":{"rendered":"Com 35% do territ\u00f3rio atingido pelas chuvas, Canoas decreta situa\u00e7\u00e3o de emerg\u00eancia"},"content":{"rendered":"<section>\n<div>\n<p>A Prefeitura de Canoas decretou, nesta quarta-feira (18), situa\u00e7\u00e3o de emerg\u00eancia no munic\u00edpio em raz\u00e3o dos alagamentos e das chuvas intensas que atingem a cidade desde a noite de ter\u00e7a-feira (17).\u00a0De acordo com levantamento da Defesa Civil, cerca de 35% do territ\u00f3rio de Canoas foi atingido, com registro preliminar de mais de 100 pessoas desabrigadas e 500 desalojadas, em decorr\u00eancia de um volume de chuva que superou 80 mil\u00edmetros em poucas horas.<\/p>\n<p><strong>Leia mais:<br \/>\n<\/strong><a href=\"https:\/\/sul21.com.br\/noticias\/geral\/2025\/06\/foi-mais-um-dia-de-terror-diz-moradora-de-canoas-sobre-chuva-no-rs\/\">\u2018Foi mais um dia de terror\u2019, diz moradora de Canoas sobre chuva no RS<\/a><\/p>\n<p>Com a declara\u00e7\u00e3o de situa\u00e7\u00e3o de emerg\u00eancia, a Prefeitura pode mobilizar todos os \u00f3rg\u00e3os municipais para atuarem na resposta ao desastre, sob coordena\u00e7\u00e3o da Secretaria Municipal de Defesa Civil e Resili\u00eancia Clim\u00e1tica (SMDCRC). A medida tamb\u00e9m permite a convoca\u00e7\u00e3o de volunt\u00e1rios, realiza\u00e7\u00e3o de campanhas de arrecada\u00e7\u00e3o de donativos e a dispensa de processos licitat\u00f3rios para a contrata\u00e7\u00e3o de servi\u00e7os, obras e aquisi\u00e7\u00e3o de materiais emergenciais, conforme previsto na legisla\u00e7\u00e3o federal.<\/p>\n<p>O decreto, que tem validade inicial de at\u00e9 180 dias, tamb\u00e9m autoriza, em situa\u00e7\u00f5es de risco iminente, que agentes da Defesa Civil possam acessar resid\u00eancias para prestar socorro ou realizar evacua\u00e7\u00e3o, al\u00e9m do uso provis\u00f3rio de bens p\u00fablicos ou privados, sempre com indeniza\u00e7\u00e3o posterior caso haja danos.<\/p>\n<\/p><\/div>\n<\/section>\n<p>O post <a href=\"https:\/\/sul21.com.br\/noticias\/geral\/2025\/06\/com-35-do-territorio-atingido-pelas-chuvas-canoas-decreta-situacao-de-emergencia\/\">Com 35% do territ\u00f3rio atingido pelas chuvas, Canoas decreta situa\u00e7\u00e3o de emerg\u00eancia<\/a> apareceu primeiro em <a href=\"https:\/\/sul21.com.br\/\">Sul 21<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/china-reafirma-apoio-a-cuba-e-a-venezuela-as-vesperas-de-cupula-xi-trump-em-pequim\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">China reafirma apoio a Cuba e \u00e0 Venezuela \u00e0s v\u00e9spe...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/7-de-abril-e-o-dia-nacional-de-combate-ao-bullying-entenda-a-importancia-na-tvt-news\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">7 de abril \u00e9 o Dia Nacional de Combate ao Bullying...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/mst-cobra-respostas-do-incra-e-mda-sobre-infraestrutura-educacao-e-politicas-para-mulheres\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/07\/MST-RS-audiencia-semana-camponesa-8-150x150.jpeg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">MST cobra respostas do Incra e MDA sobre infraestr...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/resultado-mega-sena-2938-ninguem-acertou-e-premio-esta-acumulado-em-r-67-milhoes\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/11\/Mega-Sena-da-Virada-1-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Resultado Mega Sena 2938: ningu\u00e9m acertou e pr\u00eamio...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Canoas decretou, nesta quarta-feira (18), situa\u00e7\u00e3o de emerg\u00eancia no munic\u00edpio em raz\u00e3o dos alagamentos e das chuvas intensas que atingem a cidade desde a noite de ter\u00e7a-feira (17).\u00a0De acordo com levantamento da Defesa Civil, cerca de 35% do territ\u00f3rio de Canoas foi atingido, com registro preliminar de mais de 100 pessoas desabrigadas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[8457,141,87,94,5541],"tags":[],"class_list":["post-34291","post","type-post","status-publish","format-standard","hentry","category-alagamento","category-canoas","category-enchente","category-geral","category-topo1"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/34291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=34291"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/34291\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=34291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=34291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=34291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}