{"id":38669,"date":"2025-07-16T21:44:29","date_gmt":"2025-07-17T00:44:29","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/camara-aprova-urgencia-para-projeto-que-permite-acao-da-policia-sem-ordem-judicial-em-ocupacoes\/"},"modified":"2025-07-16T21:44:29","modified_gmt":"2025-07-17T00:44:29","slug":"camara-aprova-urgencia-para-projeto-que-permite-acao-da-policia-sem-ordem-judicial-em-ocupacoes","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/camara-aprova-urgencia-para-projeto-que-permite-acao-da-policia-sem-ordem-judicial-em-ocupacoes\/","title":{"rendered":"C\u00e2mara aprova urg\u00eancia para projeto que permite a\u00e7\u00e3o da pol\u00edcia sem ordem judicial em ocupa\u00e7\u00f5es"},"content":{"rendered":"<p>Na noite desta quarta-feira (16), a C\u00e2mara dos Deputados aprovou o regime de urg\u00eancia para o <a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/fichadetramitacao?idProposicao=2147513\">PL 8262\/2017<\/a>, que permite o uso da for\u00e7a policial para retirada de ocupa\u00e7\u00f5es em propriedades privadas sem a necessidade de decis\u00e3o judicial. O texto, defendido pela bancada ruralista, altera o artigo 1.210 do C\u00f3digo Civil para autorizar o propriet\u00e1rio a solicitar a pol\u00edcia diretamente, desde que apresente escritura p\u00fablica que comprove a titularidade do im\u00f3vel. <\/p>\n<p>A tramita\u00e7\u00e3o acelerada foi aprovada com 347 votos favor\u00e1veis e 107 contr\u00e1rios. O presidente da casa, Hugo Motta (Republicanos-PB), n\u00e3o informou quando ir\u00e1 incluir o tema na pauta.<\/p>\n<p>A vota\u00e7\u00e3o foi marcada por ataques de parlamentares da direita ao Movimento dos Trabalhadores Rurais Sem Terra (MST), sob a alega\u00e7\u00e3o de \u201cdefesa da propriedade\u201d e de que o projeto seria uma forma de garantir \u201cpaz no campo\u201d. O argumento foi rebatido por deputados progressistas, que sinalizaram que a reforma agr\u00e1ria como um meio para cessar os conflitos. <\/p>\n<p>\u201cQuerem a paz no campo? Deixem acontecer a reforma agr\u00e1ria. Distribuam terra para quem quer produzir. O que est\u00e1 sendo votado n\u00e3o trar\u00e1 paz no campo, vai aumentar os epis\u00f3dios de viol\u00eancia no campo, e sem o devido processo legal\u201d, disse o deputado Tarc\u00edsio Motta (Psol-RJ). <\/p>\n<p>No momento em que o Brasil discute temas como a taxa\u00e7\u00e3o de super-ricos, o deputado Marcel Van Hattem (Novo-RS), que defendeu a urg\u00eancia, disse ver \u201cpoucas coisas mais urgentes no Brasil neste momento do que garantir o direito de propriedade \u00e0queles que t\u00eam seus terrenos e suas propriedades invadidas\u201d. Para ele, a \u201catividade mais importante da pol\u00edcia\u201d \u00e9 \u201cretirar invasores de terra\u201d, em refer\u00eancia \u00e0s ocupa\u00e7\u00f5es realizadas por movimentos populares como instrumento de press\u00e3o pelo cumprimento da reforma agr\u00e1ria. <\/p>\n<p>Em nome da maioria, a deputada Camila Jara (PT-MS) marcou posi\u00e7\u00e3o contra a urg\u00eancia e se posicionou pela defesa da agricultura familiar e do uso de terras improdutivas que, segundo a parlamentar, \u201cservem apenas a especula\u00e7\u00e3o\u201d. <\/p>\n<p>\u201cComo neta orgulhosa de agricultores familiares vindos dos movimentos de luta pela terra e que hoje se sustentam e sustentam um munic\u00edpio com agricultura familiar, eu digo que agora, sim, aquela terra, que antes era improdutiva, se tornou produtiva. N\u00f3s acreditamos que toda terra brasileira deve ser destinada a quem quer produzir, e n\u00e3o a um pequeno grupo que s\u00f3 quer ter lucro\u201d, declarou a parlamentar.<\/p>\n<h4>Ocupa\u00e7\u00f5es urbanas e rurais <\/h4>\n<p>O projeto amplia as possibilidades de repress\u00e3o a ocupa\u00e7\u00f5es urbanas e rurais ao prever o uso da for\u00e7a policial antes da an\u00e1lise judicial dos casos, o que \u00e9 interpretado como uma viola\u00e7\u00e3o de garantias constitucionais como o contradit\u00f3rio, a ampla defesa e o devido processo legal. Al\u00e9m disso, o texto prop\u00f5e mudan\u00e7as no C\u00f3digo Penal e no C\u00f3digo de Processo Civil para endurecer penas contra ocupa\u00e7\u00f5es, inclusive com a cria\u00e7\u00e3o do crime de \u201cesbulho possess\u00f3rio coletivo\u201d, punido com at\u00e9 oito anos de pris\u00e3o.<\/p>\n<p>A aprova\u00e7\u00e3o da urg\u00eancia integra uma <a href=\"https:\/\/www.brasildefato.com.br\/2024\/05\/23\/comissao-pastoral-da-terra-e-mst-repudiam-projeto-que-criminaliza-ocupacoes-muito-cruel-com-camponeses-diz-ativista\/\">ofensiva da C\u00e2mara contra movimentos pela terra<\/a>. Projetos em discuss\u00e3o nesta semana na Casa incluem tamb\u00e9m o \u201cPL da Devasta\u00e7\u00e3o\u201d, que <a href=\"https:\/\/www.brasildefato.com.br\/2025\/07\/16\/pl-da-devastacao-fragiliza-licenciamento-ambiental-e-amplia-efeitos-da-crise-climatica\/\">dispensa o agroneg\u00f3cio de licenciamento ambiental<\/a>, e o chamado \u201cPL anti-MST\u201d, que dificulta a desapropria\u00e7\u00e3o de propriedades produtivas que n\u00e3o cumpram a fun\u00e7\u00e3o social da terra.<\/p>\n<p>O post <a href=\"https:\/\/www.brasildefato.com.br\/2025\/07\/16\/camara-aprova-urgencia-para-projeto-que-permite-acao-da-policia-sem-ordem-judicial-em-ocupacoes\/\">C\u00e2mara aprova urg\u00eancia para projeto que permite a\u00e7\u00e3o da pol\u00edcia sem ordem judicial em ocupa\u00e7\u00f5es<\/a> apareceu primeiro em <a href=\"https:\/\/www.brasildefato.com.br\/\">Brasil de Fato<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/sul21.com.br\/noticias\/politica\/2025\/11\/marcha-funebre-e-champanhe-prisao-de-bolsonaro-atrai-manifestantes-a-sede-da-pf\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1669075&amp;o=node') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Marcha f\u00fanebre e champanhe: pris\u00e3o de Bolsonaro at...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/o-que-e-noticia-no-jornal-tvt-news-primeira-edicao-04-07-2025\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/07\/jornal_tvt_news-6-150x150.jpeg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">O que \u00e9 not\u00edcia no Jornal TVT News Primeira Edi\u00e7\u00e3o...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/ameaca-nuclear-os-acordos-nao-valem-mais\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/06\/Screenshot-2025-06-12-at-18-43-07-4jun2025-imagens-de-satelite-mostram-bombardeiros-russos-destruidos-na-base-aerea-de-belaya-1749129456873_v2_900x506jpg-imagem-JPEG-900-506-pixels-150x150.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Amea\u00e7a nuclear: Os acordos n\u00e3o valem mais?<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/retrocesso-perverso-pl-que-amplia-internacao-de-reus-com-transtornos-mentais-ameaca-avancos-da-reforma-psiquiatrica-avaliam-especialistas\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">\u2018Retrocesso perverso\u2019: PL que amplia i...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Na noite desta quarta-feira (16), a C\u00e2mara dos Deputados aprovou o regime de urg\u00eancia para o PL 8262\/2017, que permite o uso da for\u00e7a policial para retirada de ocupa\u00e7\u00f5es em propriedades privadas sem a necessidade de decis\u00e3o judicial. O texto, defendido pela bancada ruralista, altera o artigo 1.210 do C\u00f3digo Civil para autorizar o propriet\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[2791,302,6501,195],"tags":[],"class_list":["post-38669","post","type-post","status-publish","format-standard","hentry","category-lutas","category-mst","category-pl-da-devastacao","category-reforma-agraria"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/38669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=38669"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/38669\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=38669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=38669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=38669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}