{"id":39133,"date":"2025-07-18T14:50:51","date_gmt":"2025-07-18T17:50:51","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/o-exercito-contra-os-pracinhas-a-outra-luta-da-feb\/"},"modified":"2025-07-18T14:50:51","modified_gmt":"2025-07-18T17:50:51","slug":"o-exercito-contra-os-pracinhas-a-outra-luta-da-feb","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/o-exercito-contra-os-pracinhas-a-outra-luta-da-feb\/","title":{"rendered":"O Ex\u00e9rcito contra os pracinhas: a outra luta da FEB"},"content":{"rendered":"<p>H\u00e1 80 anos, em 18 de julho de 1945, uma multid\u00e3o saiu \u00e0s ruas do Rio de Janeiro para celebrar o retorno dos soldados da For\u00e7a Expedicion\u00e1ria Brasileira (FEB) ap\u00f3s o t\u00e9rmino da Segunda Guerra Mundial. Vitoriosos na luta contra o nazifascismo, os pracinhas foram saudados pelo povo como verdadeiros her\u00f3is.<\/p>\n<p>A rever\u00eancia dos populares contrastava fortemente com o tratamento que os combatentes receberam do governo brasileiro do oficialato das For\u00e7as Armadas. Vinculada \u00e0 luta pelos princ\u00edpios democr\u00e1ticos e com comunistas em suas fileiras, a FEB era vista com enorme desconfian\u00e7a pelo regime de Vargas e causava inc\u00f4modo \u00e0 c\u00fapula do Ex\u00e9rcito<\/p>\n<p>A unidade foi dissolvida imediatamente ap\u00f3s retornar ao Brasil e seus membros receberam certificados de dispensa quando ainda estavam na Europa. De volta \u00e0 terra natal, os volunt\u00e1rios da FEB n\u00e3o obtiveram nenhum tipo de assist\u00eancia governamental \u2014 e at\u00e9 os que estavam feridos e doentes foram largados \u00e0 pr\u00f3pria sorte.<\/p>\n<h3>A FEB<\/h3>\n<p>O Brasil foi a \u00fanica na\u00e7\u00e3o latino-americana a enviar soldados sob sua pr\u00f3pria bandeira para lutar contra as for\u00e7as nazifascistas na Segunda Guerra Mundial. A princ\u00edpio, o pa\u00eds, ent\u00e3o sob governo de Get\u00falio Vargas, tentou manter a neutralidade no conflito, em conson\u00e2ncia com o tradicional pragmatismo de sua pol\u00edtica externa.<\/p>\n<p>Ap\u00f3s o ingresso dos Estados Unidos no conflito, o Brasil passou a ser pressionado a auxiliar as tropas aliadas. Em 1942, ap\u00f3s autorizar o uso das bases a\u00e9reas do Nordeste pelas For\u00e7as Armadas dos Estados Unidos, o Brasil se tornou alvo de ataques retaliat\u00f3rios, tendo seus navios torpedeados por submarinos alem\u00e3es.<\/p>\n<p>A entrada do Brasil na guerra tamb\u00e9m foi impulsionada pela forte press\u00e3o popular. Indignada com os ataques alem\u00e3es, a popula\u00e7\u00e3o saiu \u00e0s ruas em peso exigindo que Vargas declarasse guerra aos nazistas. Em agosto de 1943, cumprindo a promessa de envio de uma unidade militar para auxiliar os aliados na Europa, Vargas criou a For\u00e7a Expedicion\u00e1ria Brasileira.<\/p>\n<p>A FEB congregava mais de 25 mil soldados, ditos \u201cpracinhas\u201d. Eles eram jovens recrutados junto \u00e0s classes populares, a grande maioria sem qualquer experi\u00eancia militar pr\u00e9via. Eram pedreiros, carpinteiros, oper\u00e1rios de f\u00e1bricas, trabalhadores rurais e at\u00e9 mesmo desempregados que enxergavam no alistamento uma oportunidade de mobilidade social ou estabilidade econ\u00f4mica.<\/p>\n<p>Outros se voluntariaram para lutar por raz\u00f5es ideol\u00f3gicas \u2014 caso de militantes egressos de organiza\u00e7\u00f5es nacionalistas ou vinculados ao Partido Comunista Brasileiro (PCB).<\/p>\n<p>A FEB desembarcou na It\u00e1lia em julho de 1944. Mesmo diante das dificuldades log\u00edsticas, das condi\u00e7\u00f5es adversas e da inexperi\u00eancia em conflitos militares, os pracinhas se destacaram, triunfando sobre as for\u00e7as nazistas em uma s\u00e9rie de batalhas importantes, como Castelnuovo, Monte Castello, Montese e Fornovo di Taro.<\/p>\n<p>A colabora\u00e7\u00e3o brasileira foi fundamental para romper a Linha G\u00f3tica e garantir o avan\u00e7o aliado rumo ao norte da Pen\u00ednsula It\u00e1lica. Em Fornovo di Taro, a FEB realizou uma fa\u00e7anha in\u00e9dita, tornando-se a \u00fanica for\u00e7a aliada que conseguiu capturar integralmente uma divis\u00e3o alem\u00e3 durante a Campanha da It\u00e1lia.<\/p>\n<h3>As tens\u00f5es com o governo<\/h3>\n<p>Ap\u00f3s retornarem ao Brasil, os pracinhas foram recepcionados com uma grande festa. O governo decretou feriado nacional para que a popula\u00e7\u00e3o pudesse prestigiar os eventos. V\u00e1rias cidades organizaram atos c\u00edvicos, paradas e festejos populares.<\/p>\n<p>No Rio de Janeiro, um grande desfile reuniu milhares de pessoas. Um palanque foi montado na Avenida Rio Branco, para abrigar o presidente Get\u00falio Vargas e outras autoridades. Ao longo do percurso, os combatentes foram saudados com aplausos e com uma chuva de pap\u00e9is picados lan\u00e7ados pelos moradores dos pr\u00e9dios.<\/p>\n<p>Os atos mascaravam uma realidade bem menos glamourosa. Ap\u00f3s as celebra\u00e7\u00f5es pelo retorno, os pracinhas seriam tratados com absoluto desprezo e neglig\u00eancia pelo governo brasileiro e pela c\u00fapula das For\u00e7as Armadas.<\/p>\n<p>O governo Vargas e o oficialato consideravam que a FEB n\u00e3o era politicamente confi\u00e1vel. Como mencionado, parte dos soldados que lutaram pela FEB eram militantes do Partido Comunista ou simpatizantes do socialismo. Outros eram admiradores de Luiz Carlos Prestes e das lideran\u00e7as egressas do tenentismo.<\/p>\n<p>A FEB tamb\u00e9m abrigava muitos militares que defendiam a concep\u00e7\u00e3o de democracia liberal \u2014 um discurso que constrangia o establishment autorit\u00e1rio e ditatorial do Estado Novo. Um dos jornais de trincheira publicados pelos pracinhas trazia uma provoca\u00e7\u00e3o a Vargas j\u00e1 na capa, estampando a frase \u201cN\u00e3o \u00e9 registrado no DIP\u201d, em refer\u00eancia ao \u00f3rg\u00e3o oficial de censura e controle da informa\u00e7\u00e3o.<\/p>\n<p>Ainda em 1945, um grupo de 200 oficiais da FEB produziu um manifesto afirmando que a luta contra o nazifascismo na Europa era contradit\u00f3ria diante da persist\u00eancia de um regime autorit\u00e1rio no Brasil. A iniciativa enfureceu Eurico Gaspar Dutra, ent\u00e3o Ministro da Guerra do gabinete de Vargas.<\/p>\n<figure aria-describedby=\"caption-attachment-225792\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\"src=\"https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/07\/16989.jpeg\" alt=\"\" width=\"900\" height=\"638\" srcset=\"https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/07\/16989.jpeg 900w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/07\/16989-300x213.jpeg 300w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/07\/16989-768x544.jpeg 768w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/07\/16989-150x106.jpeg 150w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/07\/16989-120x86.jpeg 120w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/07\/16989-750x532.jpeg 750w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\"><figcaption>Pracinhas da FEB desfilam na avenida Rio Branco, no Rio de Janeiro, ap\u00f3s regressarem da It\u00e1lia <br \/>Memorial da Democracia<\/figcaption><\/figure>\n<h3>O mal estar na caserna<\/h3>\n<p>Al\u00e9m de questionarem o regime antidemocr\u00e1tico e sofrerem cr\u00edticas dos setores anticomunistas, os pracinhas tamb\u00e9m desagradavam a elite militar por outros motivos.<\/p>\n<p>O alto comando das For\u00e7as Armadas, tradicionalmente muito elitizado, se ressentia do fato de que soldados de baixa patente, a grande maioria proveniente das classes populares, fossem tratados como her\u00f3is pela popula\u00e7\u00e3o.<\/p>\n<p>Temendo os riscos no campo de batalha, os oficiais oriundos de fam\u00edlias ricas e influentes articularam meios de evitar que fossem enviados para a guerra. A convoca\u00e7\u00e3o de expedicion\u00e1rios sem qualquer experi\u00eancia militar pr\u00e9via foi motivo de chacota.<\/p>\n<p>Quando os pracinhas retornaram, vitoriosos e cobertos de gl\u00f3ria, os oficiais n\u00e3o conseguiam esconder o preconceito, a inveja e o inc\u00f4modo. Eles tamb\u00e9m ficaram preocupados com a possibilidade de serem preteridos em favor dos combatentes da FEB nas promo\u00e7\u00f5es e indica\u00e7\u00f5es da carreira militar.<\/p>\n<p>Os febianos profissionais que seguiram vinculados ao Ex\u00e9rcito foram tratados com hostilidade pelos oficiais dentro dos quart\u00e9is. Eram submetidos a boicotes e frequentemente transferidos para guarni\u00e7\u00f5es long\u00ednquas, em regi\u00f5es isoladas<\/p>\n<h3>O fim da FEB<\/h3>\n<p>Ap\u00f3s a vit\u00f3ria na Segunda Guerra Mundial, quase todas as na\u00e7\u00f5es aliadas criaram programas de reintegra\u00e7\u00e3o e apoio aos veteranos. A Uni\u00e3o Sovi\u00e9tica, por exemplo, criou pens\u00f5es e programas de requalifica\u00e7\u00e3o profissional. Os Estados Unidos aprovaram a \u201cG.I. Bill of Rights\u201d, uma legisla\u00e7\u00e3o que concedia aos ex-combatentes o direito a frequentar o ensino superior gratuito, receber assist\u00eancia m\u00e9dica e acessar linhas de cr\u00e9dito.<\/p>\n<p>O Brasil foi uma exce\u00e7\u00e3o. Em 6 de julho de 1945, no mesmo per\u00edodo em que os pracinhas come\u00e7aram a voltar para o Brasil, o governo Vargas ordenou a dissolu\u00e7\u00e3o da FEB. Paradoxalmente, em vez de se tornar uma divis\u00e3o de refer\u00eancia para o treinamento das tropas, a unidade mais experiente do pa\u00eds, part\u00edcipe do maior conflito militar da hist\u00f3ria, foi extinta.<\/p>\n<p>Os combatentes da FEB que eram militares profissionais foram reintegrados ao ex\u00e9rcito, mas os volunt\u00e1rios civis receberam seus certificados de dispensa quando ainda estavam na Europa. Eles ganharam apenas a passagem de volta para suas cidades de origem, sendo mandados embora sem nenhum tipo de benef\u00edcio ou aux\u00edlio do governo. N\u00e3o foram sequer submetidos a exames m\u00e9dicos.<\/p>\n<p>Centenas de pracinhas que voltaram mutilados, feridos, doentes, sofrendo de traumas psicol\u00f3gicos, sem condi\u00e7\u00f5es f\u00edsicas de exercer qualquer tipo de trabalho, foram largados \u00e0 pr\u00f3pria sorte. N\u00e3o foram poucos os casos de ex-combatentes que passaram a viver nas ruas.<\/p>\n<p>Os soldados profissionais reintegrados ap\u00f3s a dissolu\u00e7\u00e3o da FEB foram proibidos pelo alto comando de fazerem declara\u00e7\u00f5es pol\u00edticas ou concederem entrevistas sem autoriza\u00e7\u00e3o pr\u00e9via do Minist\u00e9rio da Guerra.<\/p>\n<p>A fim de reivindicar seus direitos, os veteranos da FEB criaram v\u00e1rias associa\u00e7\u00f5es, mas essas organiza\u00e7\u00f5es tamb\u00e9m seriam boicotadas e perseguidas pelas autoridades brasileiras \u2014 sobretudo em fun\u00e7\u00e3o da forte presen\u00e7a de militantes comunistas em seus quadros. Isso ocorreu, por exemplo, com Sampaio de Lacerda, militante comunista que presidia o Conselho Nacional da AECB (Associa\u00e7\u00f5es de Ex-Combatentes do Brasil), destitu\u00eddo em uma a\u00e7\u00e3o coordenada pelo Minist\u00e9rio da Guerra.<\/p>\n<p>O Ex\u00e9rcito levou mais de uma d\u00e9cada para erguer os primeiros monumentos em homenagem aos soldados da FEB que tombaram na luta contra o regime nazista. Preferiam reservar \u00e0 gl\u00f3ria dos bustos apenas os militares oriundos das tradicionais elites brasileiras.<\/p>\n<p>O post <a href=\"https:\/\/operamundi.uol.com.br\/pensar-a-historia\/o-exercito-contra-os-pracinhas-a-outra-luta-da-feb\/\">O Ex\u00e9rcito contra os pracinhas: a outra luta da FEB<\/a> apareceu primeiro em <a href=\"https:\/\/operamundi.uol.com.br\/\">Opera Mundi<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/atividade-economica-brasileira-cresce-09-em-janeiro\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Atividade econ\u00f4mica brasileira cresce 0,9% em jane...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/ex-prefeito-de-lajeado-marcelo-caumo-pp-e-preso-na-operacao-lamacal-que-apura-desvio-milionario-nas-enchentes-do-rs\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ex-prefeito de Lajeado Marcelo Caumo (PP) \u00e9 preso ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/ativista-thiago-avila-chega-ao-brasil-nesta-segunda-11-apos-10-dias-preso-em-israel\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ativista Thiago \u00c1vila chega ao Brasil nesta segund...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/trump-trai-coreia-do-sul-e-reprime-operarios-em-fabrica-bilionaria-na-georgia\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/09\/IMG-20250908-WA0034-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Trump trai Coreia do Sul e reprime oper\u00e1rios em f\u00e1...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>H\u00e1 80 anos, em 18 de julho de 1945, uma multid\u00e3o saiu \u00e0s ruas do Rio de Janeiro para celebrar o retorno dos soldados da For\u00e7a Expedicion\u00e1ria Brasileira (FEB) ap\u00f3s o t\u00e9rmino da Segunda Guerra Mundial. Vitoriosos na luta contra o nazifascismo, os pracinhas foram saudados pelo povo como verdadeiros her\u00f3is. A rever\u00eancia dos populares [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[536,10151,10152,2314,1627,5622,10153],"tags":[],"class_list":["post-39133","post","type-post","status-publish","format-standard","hentry","category-democracia","category-feb","category-forca-expedicionaria-brasileira","category-forcas-armadas","category-getulio-vargas","category-pensar-a-historia","category-pracinhas"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/39133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=39133"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/39133\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=39133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=39133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=39133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}