{"id":39869,"date":"2025-07-23T16:06:35","date_gmt":"2025-07-23T19:06:35","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/ministra-de-israel-assume-plano-de-expulsao-de-palestinos-com-video-de-ia\/"},"modified":"2025-07-23T16:06:35","modified_gmt":"2025-07-23T19:06:35","slug":"ministra-de-israel-assume-plano-de-expulsao-de-palestinos-com-video-de-ia","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/ministra-de-israel-assume-plano-de-expulsao-de-palestinos-com-video-de-ia\/","title":{"rendered":"Ministra de Israel assume plano de expuls\u00e3o de palestinos com v\u00eddeo de IA"},"content":{"rendered":"<p><img loading=\"lazy\" width=\"1024\" height=\"576\"src=\"https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-23-as-161007-2048x1151-1.png\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-23-as-16.10.07-1024x576.png 1024w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-23-as-16.10.07-300x169.png 300w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-23-as-16.10.07-768x432.png 768w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-23-as-16.10.07-1536x863.png 1536w, https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-23-as-161007-2048x1151-1.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/p>\n<p>\u201c\u00c9 assim que Gaza ser\u00e1 no futuro.\u201d A frase, publicada pela ministra da Inova\u00e7\u00e3o, Ci\u00eancia e Tecnologia de Israel, Gila Gamliel, acompanha um v\u00eddeo feito com intelig\u00eancia artificial (IA) que mostra uma Gaza futurista, \u00e0 beira-mar, repleta de arranha-c\u00e9us, turistas e um enorme edif\u00edcio com o nome \u201cTrump\u201d. Na pe\u00e7a de propaganda, a ministra aparece ao lado do ex-presidente dos Estados Unidos Donald Trump e do premi\u00ea israelense Benjamin Netanyahu, promovendo o que seria a \u201cnova Riviera do Oriente M\u00e9dio\u201d.<\/p>\n<p>Segundo Gamliel, o v\u00eddeo representa uma \u201cvis\u00e3o poss\u00edvel\u201d para Gaza, vi\u00e1vel apenas com a \u201cmigra\u00e7\u00e3o volunt\u00e1ria dos moradores\u201d \u2014 um eufemismo para a expuls\u00e3o da popula\u00e7\u00e3o palestina do territ\u00f3rio. \u201cSomos n\u00f3s ou eles\u201d, declarou. Ela afirma ter apresentado oficialmente o plano ao gabinete de governo menos de uma semana ap\u00f3s o ataque do Hamas a Israel, em outubro de 2023.<\/p>\n<figure>\n<div>\n<\/div>\n<\/figure>\n<p><strong>A propaganda do apagamento: IA e limpeza \u00e9tnica<\/strong><\/p>\n<p>O v\u00eddeo postado por Gamliel segue a mesma linha de outra montagem j\u00e1 divulgada por Donald Trump em fevereiro de 2025, sob o t\u00edtulo \u201cGaza 2025\u201d. A pe\u00e7a mostra uma Gaza totalmente reconstru\u00edda \u2014 e completamente esvaziada de palestinos. Desta vez, com uma est\u00e1tua dourada de Trump no centro da cidade, Netanyahu em uma piscina, e Elon Musk distribuindo d\u00f3lares a crian\u00e7as na praia. A trilha sonora repete: \u201cTrump vai te libertar\u201d.<\/p>\n<p>As imagens n\u00e3o s\u00e3o apenas aleg\u00f3ricas. Elas ilustram um projeto pol\u00edtico concreto: a remo\u00e7\u00e3o definitiva de todos os 2,3 milh\u00f5es de palestinos da Faixa de Gaza. Sem mencionar os 2,7 milh\u00f5es de palestinos da Cisjord\u00e2nia que vivem sob a instabilidade permanente da invas\u00e3o violenta de 700 mil colonos israelenses. A proposta foi apresentada por Israel e conta com o entusiasmado apoio de Trump, que disse desejar \u201climpar\u201d a regi\u00e3o, encaminhando seus habitantes para pa\u00edses vizinhos, como Egito e Jord\u00e2nia.<\/p>\n<p><em><sup>Desde que os v\u00eddeos de IA come\u00e7aram a circular com uma Gaza fict\u00edcia, os pr\u00f3prios palestinos come\u00e7aram a divulgar imagens da Gaza real antes da guerra destacando seus locais favoritos para lazer, demonstrando como a cidade j\u00e1 era um belo balne\u00e1rio cheio de vida e belezas, como pode ser visto no v\u00eddeo abaixo:<\/sup><\/em><\/p>\n<figure>\n<div>\n<\/div>\n<\/figure>\n<p><strong>ONU: \u201cexpulsar palestinos \u00e9 crime de guerra\u201d<\/strong><\/p>\n<p>A proposta gerou forte rea\u00e7\u00e3o internacional. A Ag\u00eancia de Direitos Humanos da ONU alertou que qualquer tentativa de expuls\u00e3o em massa seria considerada crime de guerra. A Federa\u00e7\u00e3o \u00c1rabe Palestina classificou o plano como \u201climpeza \u00e9tnica escandalosa\u201d.<\/p>\n<p>A den\u00fancia remete a um memorando sigiloso do Instituto Misgav, um centro de estudos israelense ligado ao governo Netanyahu, que vazou em outubro de 2023. O documento descrevia o momento p\u00f3s-ataques do Hamas como uma \u201coportunidade rara\u201d para a realoca\u00e7\u00e3o definitiva dos palestinos em Gaza. O Egito seria o principal destino dos deslocados, em troca de investimentos maci\u00e7os em sua economia.<\/p>\n<p><strong>\u201cCampo de concentra\u00e7\u00e3o\u201d no Sul de Gaza<\/strong><\/p>\n<p>Na pr\u00e1tica, a limpeza j\u00e1 come\u00e7ou. O ministro da Defesa de Israel, Yoav Gallant, anunciou planos para isolar a popula\u00e7\u00e3o palestina em uma \u201czona humanit\u00e1ria\u201d nas ru\u00ednas de Rafah, no sul da Faixa de Gaza. A \u00e1rea ser\u00e1 militarmente cercada, e os deslocados \u2014 cerca de 600 mil no in\u00edcio \u2014 passar\u00e3o por triagem para excluir supostos membros do Hamas, como sempre s\u00e3o classificados os homens palestinos, mesmo na adolesc\u00eancia. Segundo o governo, todos os 2 milh\u00f5es de habitantes da Faixa de Gaza devem ser transferidos \u00e0 for\u00e7a para esta \u00e1rea controlada.<\/p>\n<p>Para o presidente da Federa\u00e7\u00e3o \u00c1rabe Palestina no Brasil, Ualid Rabah, o plano se assemelha a um \u201ccampo de concentra\u00e7\u00e3o moderno\u201d, com controle absoluto sobre comida, abrigo e mobilidade. \u201cEstamos agora na fase final da solu\u00e7\u00e3o final\u201d, disse ele, em refer\u00eancia direta ao Holocausto.<\/p>\n<p><strong>Um plano antigo, agora em voz alta<\/strong><\/p>\n<p>Em maio de 2025, Netanyahu assumiu publicamente, durante reuni\u00e3o no Parlamento, que o objetivo de Israel \u00e9 tornar Gaza inabit\u00e1vel para os palestinos. \u201cEles n\u00e3o ter\u00e3o para onde voltar. O \u00fanico desfecho l\u00f3gico ser\u00e1 o desejo de emigra\u00e7\u00e3o\u201d, afirmou o premi\u00ea, que espera encontrar pa\u00edses dispostos a receb\u00ea-los.<\/p>\n<p>Desde outubro de 2023, o governo israelense j\u00e1 havia dado ordens ao Ex\u00e9rcito para elaborar um plano de \u201cp\u00f3s-guerra\u201d prevendo a expuls\u00e3o de toda a popula\u00e7\u00e3o da Faixa de Gaza. A opera\u00e7\u00e3o militar chamada \u201cCarruagens de Gide\u00e3o\u201d consolidou a ocupa\u00e7\u00e3o de cerca de 70% do territ\u00f3rio, com 92% das edifica\u00e7\u00f5es destru\u00eddas, segundo a ONU.<\/p>\n<p><strong>\u201cIlegal \u00e0 luz do direito internacional\u201d<\/strong><\/p>\n<p>Especialistas em direito internacional alertam que a expuls\u00e3o planejada de palestinos \u00e9 flagrantemente ilegal. O professor Kai Lehmann, da USP, lembra que a Conven\u00e7\u00e3o de Genebra pro\u00edbe o deslocamento for\u00e7ado de civis em \u00e1reas de conflito. \u201cO que vemos \u00e9 uma tentativa deliberada de limpeza \u00e9tnica\u201d, afirma. Segundo ele, esse processo j\u00e1 ocorre h\u00e1 d\u00e9cadas na Cisjord\u00e2nia, com a expans\u00e3o de assentamentos israelenses.<\/p>\n<p>Com 1,9 milh\u00e3o de deslocados e mais de 57 mil mortos em nove meses de guerra, segundo dados do Minist\u00e9rio da Sa\u00fade de Gaza, a situa\u00e7\u00e3o humanit\u00e1ria \u00e9 catastr\u00f3fica. Apesar da tr\u00e9gua firmada em julho, Israel impede a entrada cont\u00ednua de ajuda humanit\u00e1ria e realiza triagens militares que restringem a movimenta\u00e7\u00e3o de civis, frequentemente fuzilados conforme procurem alimentos em \u00e1reas de distribui\u00e7\u00e3o controladas por Israel. <\/p>\n<p>Diplomatas internacionais temem que a expuls\u00e3o em massa dos palestinos cause uma crise geopol\u00edtica sem precedentes. O Egito j\u00e1 sinalizou que n\u00e3o aceitar\u00e1 refugiados, o que pode abalar o hist\u00f3rico Acordo de Camp David. Tamb\u00e9m h\u00e1 preocupa\u00e7\u00e3o com novos fluxos migrat\u00f3rios em dire\u00e7\u00e3o \u00e0 Europa e um poss\u00edvel ressurgimento do terrorismo jihadista.<\/p>\n<p>O post <a href=\"https:\/\/vermelho.org.br\/2025\/07\/23\/ministra-de-israel-assume-plano-de-expulsao-de-palestinos-com-video-de-ia\/\">Ministra de Israel assume plano de expuls\u00e3o de palestinos com v\u00eddeo de IA<\/a> apareceu primeiro em <a href=\"https:\/\/vermelho.org.br\/\">Vermelho<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/ccj-da-camara-volta-a-debater-agenda-punitivista-nesta-terca-26-pec-antiaborto-e-combo-anti-mst-estao-no-roteiro\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">CCJ da C\u00e2mara volta a debater agenda punitivista n...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/plebiscito-popular-2025-comeca-na-terca-1o-veja-como-sera-a-votacao\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/06\/plebiscitopop-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Plebiscito Popular 2025 come\u00e7a na ter\u00e7a (1\u00ba); veja...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/cpt-celebra-50-anos-com-homenagem-na-camara-e-denuncia-impunidade-em-casos-de-violencia-no-campo\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">CPT celebra 50 anos com homenagem na C\u00e2mara e denu...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/como-o-congresso-sabota-o-fim-da-6x1\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/05\/photo_4927356176589065395_y-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Como o Congresso sabota o fim da 6\u00d71<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>\u201c\u00c9 assim que Gaza ser\u00e1 no futuro.\u201d A frase, publicada pela ministra da Inova\u00e7\u00e3o, Ci\u00eancia e Tecnologia de Israel, Gila Gamliel, acompanha um v\u00eddeo feito com intelig\u00eancia artificial (IA) que mostra uma Gaza futurista, \u00e0 beira-mar, repleta de arranha-c\u00e9us, turistas e um enorme edif\u00edcio com o nome \u201cTrump\u201d. Na pe\u00e7a de propaganda, a ministra aparece [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[4398,10369,1023,402,1228,50,25,3551,54,10370],"tags":[],"class_list":["post-39869","post","type-post","status-publish","format-standard","hentry","category-crimes-de-guerra","category-deslocamento-forcado","category-donald-trump","category-faixa-de-gaza","category-inteligencia-artificial","category-internacional","category-israel","category-limpeza-etnica","category-palestina","category-riviera-do-oriente"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/39869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=39869"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/39869\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=39869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=39869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=39869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}