{"id":42159,"date":"2025-08-03T14:34:10","date_gmt":"2025-08-03T17:34:10","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/estudantes-convocam-atos-no-11-de-agosto-para-defender-a-educacao\/"},"modified":"2025-08-03T14:34:10","modified_gmt":"2025-08-03T17:34:10","slug":"estudantes-convocam-atos-no-11-de-agosto-para-defender-a-educacao","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/estudantes-convocam-atos-no-11-de-agosto-para-defender-a-educacao\/","title":{"rendered":"Estudantes convocam atos no 11 de agosto para defender a educa\u00e7\u00e3o"},"content":{"rendered":"<p><span>Professores e estudantes das escolas de S\u00e3o Paulo estavam apreensivos com a volta \u00e0s aulas no \u00faltimo dia 28 de julho. Isso porque tudo indicava que nesta data ter\u00edamos a presen\u00e7a de policiais nas mais de 100 unidades escolares que entraram no projeto fascista de militariza\u00e7\u00e3o aprovado pelo governo. Entretanto, a press\u00e3o popular conquistou uma nova decis\u00e3o judicial que suspendeu o edital de contrata\u00e7\u00e3o dos policiais. Um al\u00edvio certamente, mas ainda n\u00e3o representa o fim dos problemas nas escolas: a educa\u00e7\u00e3o p\u00fablica est\u00e1 amea\u00e7ada por uma onda neoliberal que soma medidas de privatiza\u00e7\u00e3o, desmonte da carreira dos professores, reformula\u00e7\u00e3o dos modelos pedag\u00f3gicos, implementa\u00e7\u00e3o de plataformas digitais e autoritarismo com estudantes e funcion\u00e1rios.<\/span><\/p>\n<p><span>N\u00e3o faltam motivos para lutar por melhores condi\u00e7\u00f5es de ensino e por isso milhares de estudantes brasileiros, reunidos no 60\u00ba Congresso da Uni\u00e3o Nacional dos Estudantes (UNE), que ocorreu em Goi\u00e2nia nos dias 16 a 20 de julho, aprovaram a data nacional de lutas para o dia 11 de agosto.<\/span><\/p>\n<figure aria-describedby=\"caption-attachment-227276\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\"src=\"https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/08\/educacao.webp\" alt=\"S\u00e3o Paulo - Alunos de escolas t\u00e9cnicas estaduais protestam contra desvios de merenda escolar e contra os cortes nos Centros de Ensino T\u00e9cnico, em abril de 2016. (Foto: Rovena Rosa\/Ag\u00eancia Brasil)\" width=\"1024\" height=\"678\" srcset=\"https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/08\/educacao.webp 1024w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/08\/educacao-300x199.webp 300w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/08\/educacao-768x509.webp 768w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/08\/educacao-150x99.webp 150w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/08\/educacao-750x497.webp 750w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><figcaption>S\u00e3o Paulo \u2013 Alunos de escolas t\u00e9cnicas estaduais protestam contra desvios de merenda escolar e contra os cortes nos Centros de Ensino T\u00e9cnico, em abril de 2016. (Foto: Rovena Rosa\/Ag\u00eancia Brasil)<\/figcaption><\/figure>\n<h3><b>Autoritarismo nas escolas serve para reprimir os gr\u00eamios<\/b><\/h3>\n<p><span>A Lei do Gr\u00eamio Livre (Lei n\u00ba 7.398 de 1985) garante a organiza\u00e7\u00e3o dos estudantes secundaristas nas suas escolas e assegura a autonomia das suas entidades representativas. Entretanto, essa n\u00e3o \u00e9 a realidade em todas as escolas brasileiras. De fato, existem gr\u00eamios estudantis em apenas 14% das escolas p\u00fablicas, conforme levantamento da Campanha Nacional pelo Direito \u00e0 Educa\u00e7\u00e3o. A consequ\u00eancia inevit\u00e1vel da baixa presen\u00e7a dos gr\u00eamios nas escolas \u00e9 a dificuldade na organiza\u00e7\u00e3o estudantil que forma jovens conscientes para defender seus direitos nas salas de aula e na vida. N\u00e3o h\u00e1 d\u00favidas de que esse dado est\u00e1 diretamente ligado ao aumento do autoritarismo.<\/span><\/p>\n<p><span>Em S\u00e3o Paulo, representantes das entidades estudantis relatam abusos e repress\u00e3o por parte das dire\u00e7\u00f5es sob orienta\u00e7\u00e3o da Secretaria Estadual de Educa\u00e7\u00e3o. \u201cNa campanha de conscientiza\u00e7\u00e3o sobre a privatiza\u00e7\u00e3o e a militariza\u00e7\u00e3o do ensino, chegaram a chamar a pol\u00edcia para nos impedir de passar nas salas de aula e fazer reuni\u00f5es dentro da escola\u201d relata Ana Leite, presidente da Associa\u00e7\u00e3o Regional de Estudantes do ABC Paulista (ARES-ABC) e diretora da Uni\u00e3o Brasileira dos Estudantes Secundaristas (UBES).<\/span><\/p>\n<p><span>Por outro lado, se tornou comum que a pr\u00f3pria dire\u00e7\u00e3o da escola assuma o processo de organiza\u00e7\u00e3o dos gr\u00eamios, controlando a elei\u00e7\u00e3o do in\u00edcio ao fim e ferindo a autonomia dos estudantes. Para Ana, \u201ca ajuda da escola n\u00e3o seria exatamente um problema, mas o que tem acontecido \u00e9 que algumas dire\u00e7\u00f5es impedem chapas consideradas \u2018questionadoras\u2019 de se inscreverem para participar da elei\u00e7\u00e3o, pro\u00edbem a passagem em sala e a distribui\u00e7\u00e3o de panfletos e chegam at\u00e9 mesmo a suspender alunos da diretoria do gr\u00eamio por \u2018mal comportamento\u2019. Em outros casos, a dire\u00e7\u00e3o exerce uma tutela dos gr\u00eamios, transformando-os em meros zeladores da escola. Imagine como vai ser com um policial aqui dentro?\u201d<\/span><\/p>\n<h2><span>\u00a0Leia tamb\u00e9m \u2013 Militariza\u00e7\u00e3o das escolas \u00e9 propaganda enganosa\u00a0<\/span><\/h2>\n<p><span>Esse contexto faz parte de um processo que precisa suprimir a organiza\u00e7\u00e3o estudantil e sindical para implementar sem questionamentos os projetos do governador e dos empres\u00e1rios na educa\u00e7\u00e3o.<\/span><\/p>\n<h3><b>Plataformiza\u00e7\u00e3o atende aos interesses privados<\/b><\/h3>\n<p><span>Como tudo nessa vida tem explica\u00e7\u00e3o, professores e estudantes querem entender o motivo da pressa do governo em implementar uma enxurrada de novas plataformas digitais no ensino, sendo que muitas vezes ainda faltam recursos b\u00e1sicos, como papel higi\u00eanico e sabonete nos banheiros, nas salas h\u00e1 goteiras e aulas s\u00e3o canceladas pela falta de ventiladores.\u00a0<\/span><\/p>\n<p><span>De fato, h\u00e1 uma grande insatisfa\u00e7\u00e3o com a plataformiza\u00e7\u00e3o nas escolas: professores sentem-se pressionados a atender um ritmo de trabalho sobrehumano, que consiste em avalia\u00e7\u00f5es a partir do tempo de acesso \u00e0s plataformas e metas de atividades por aluno\/semana, al\u00e9m de terem a sua liberdade de c\u00e1tedra tolhida pela ado\u00e7\u00e3o de aulas preparadas com intelig\u00eancia artificial. Essas ferramentas privadas custam uma fortuna ao Estado e, apesar de aparentarem um avan\u00e7o tecnol\u00f3gico necess\u00e1rio, na realidade t\u00eam rebaixado a qualidade do aprendizado dos nossos jovens.\u00a0<\/span><\/p>\n<p><span>A coincid\u00eancia por tr\u00e1s dessa grande inova\u00e7\u00e3o tecnol\u00f3gica \u00e9 que Renato Feder, al\u00e9m de ser o atual Secret\u00e1rio Estadual de Educa\u00e7\u00e3o de S\u00e3o Paulo, \u00e9 tamb\u00e9m acionista da empresa Multilaser, que tem contratos com o governo paulista que fornecem os computadores para o setor de educa\u00e7\u00e3o.\u00a0<\/span><\/p>\n<p><b>No 11 de agosto a aula \u00e9 na rua<\/b><\/p>\n<p><span>Em resumo: a militariza\u00e7\u00e3o n\u00e3o foi completamente enterrada, a plataformiza\u00e7\u00e3o do ensino \u00e9 um aspecto da privatiza\u00e7\u00e3o e o governo tenta minar a organiza\u00e7\u00e3o estudantil com autoritarismo nas escolas. Tudo isso somado \u00e0s p\u00e9ssimas condi\u00e7\u00f5es estruturais das salas de aula e \u00e0 falta de professores indicam que a crise da educa\u00e7\u00e3o se agrava cada dia mais.\u00a0\u00a0<\/span><\/p>\n<p><span>No Dia do Estudantes, a juventude vai \u00e0s ruas para exigir que sua voz seja ouvida e mostrar para a sociedade que a educa\u00e7\u00e3o e o nosso futuro est\u00e3o amea\u00e7ados pelas garras do fascista Tarc\u00edsio de Freitas.<\/span><\/p>\n<p><b><i>(*) Isis Mustafa<\/i><\/b><i><span> \u00e9 dirigente do partido Unidade Popular pelo Socialismo.<\/span><\/i><\/p>\n<p>O post Estudantes convocam atos no 11 de agosto para defender a educa\u00e7\u00e3o apareceu primeiro em Opera Mundi.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/porto-alegre-e-uma-das-capitais-com-a-maior-inflacao-no-brasil-em-2025\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Porto Alegre \u00e9 uma das capitais com a maior infla\u00e7...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/nova-alta-dos-juros-volta-a-gerar-criticas-por-prejudicar-o-povo-e-o-pais\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/05\/juros_Lilian-Milena_Contraf-CUT-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Nova alta dos juros volta a gerar cr\u00edticas por pre...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/doi-essa-recolonizacao-artista-indigena-denuncia-pirataria-de-obras-em-plataformas-online\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">\u2018D\u00f3i essa recoloniza\u00e7\u00e3o\u2019: artista ind\u00edgena denunci...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/negociacoes-sobre-acordo-global-contra-poluicao-plastica-acabam-em-novo-fracasso\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/08\/plastic_waste_99922-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Negocia\u00e7\u00f5es sobre acordo global contra polui\u00e7\u00e3o pl...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Professores e estudantes das escolas de S\u00e3o Paulo estavam apreensivos com a volta \u00e0s aulas no \u00faltimo dia 28 de julho. Isso porque tudo indicava que nesta data ter\u00edamos a presen\u00e7a de policiais nas mais de 100 unidades escolares que entraram no projeto fascista de militariza\u00e7\u00e3o aprovado pelo governo. Entretanto, a press\u00e3o popular conquistou uma [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/operamundi.uol.com.br\/opiniao\/estudantes-convocam-atos-no-11-de-agosto-para-defender-a-educacao\/\">Estudantes convocam atos no 11 de agosto para defender a educa\u00e7\u00e3o<\/a> apareceu primeiro em <a href=\"https:\/\/operamundi.uol.com.br\/\">Opera Mundi<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":42160,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[95,2298,2977,153,1712,29,254],"tags":[],"class_list":["post-42159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","category-escola","category-estudantes","category-opiniao","category-renato-feder","category-sao-paulo","category-tarcisio-de-freitas"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/42159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=42159"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/42159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media\/42160"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=42159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=42159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=42159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}