{"id":42879,"date":"2025-08-06T14:11:41","date_gmt":"2025-08-06T17:11:41","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/a-bandeira-do-brasil-entre-o-falso-patriotismo-e-a-luta-pela-soberania\/"},"modified":"2025-08-06T14:11:41","modified_gmt":"2025-08-06T17:11:41","slug":"a-bandeira-do-brasil-entre-o-falso-patriotismo-e-a-luta-pela-soberania","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/a-bandeira-do-brasil-entre-o-falso-patriotismo-e-a-luta-pela-soberania\/","title":{"rendered":"A bandeira do Brasil entre o falso patriotismo e a luta pela soberania"},"content":{"rendered":"<p><img loading=\"lazy\" width=\"800\" height=\"530\"src=\"https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/08\/bandeira-do-brasil.jpg\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/redept.org\/blogosfera\/wp-content\/uploads\/2025\/08\/bandeira-do-brasil.jpg 800w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2024\/11\/bandeira-do-brasil-300x199.jpg 300w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2024\/11\/bandeira-do-brasil-768x509.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\"><\/p>\n<p>A hist\u00f3ria do Brasil \u00e9 marcada por lutas que se refletem nas cores de nossa bandeira. Nos anos 1990, o movimento dos Caras Pintadas, protagonizado pela juventude brasileira, tomou as ruas com os rostos pintados de verde e amarelo, transformando essas cores em um s\u00edmbolo de resist\u00eancia contra a corrup\u00e7\u00e3o e as pol\u00edticas neoliberais do governo Collor. Era um patriotismo cr\u00edtico, que n\u00e3o se limitava a celebrar o pa\u00eds, mas o desafiava a ser melhor.<\/p>\n<p>Tr\u00eas d\u00e9cadas depois, enfrentamos uma disputa ideol\u00f3gica que se caracteriza pelas cores de nossa bandeira, fortalecendo uma grande divis\u00e3o na sociedade e nos trazendo questionamentos norteadores: Quem carrega a bandeira do Brasil \u00e9 realmente patriota? Ser\u00e1 que todos que vestem o manto verde e amarelo defendem o Brasil soberano pelo qual tanto lutamos diariamente para conquistar?<\/p>\n<p>O verde e amarelo, que um dia representou a luta por um Brasil mais justo, hoje \u00e9 disputado por vis\u00f5es antag\u00f4nicas de na\u00e7\u00e3o. De um lado, um nacionalismo superficial, reduzido a slogans e bandeiras tremuladas em defesa de um projeto que entrega nossas riquezas, precariza o trabalho e amea\u00e7a a democracia. De outro, um patriotismo insurgente, que resgata o sentido original da bandeira: um chamado \u00e0 soberania popular, \u00e0 defesa dos direitos sociais e \u00e0 constru\u00e7\u00e3o de um pa\u00eds verdadeiramente independente.<\/p>\n<p>Com a guerra comercial de Trump contra o Brasil, muitos debates foram levantados nas redes e ruas. O momento foi prop\u00edcio para que a extrema direita brasileira tomasse protagonismo em defesa de um Brasil submetido ao imperialismo. Do outro lado, ascendeu a bandeira de quem veste a democracia e o pa\u00eds soberano. Mas a disputa \u00e9 somente sobre as cores? Ser\u00e1 que Trump se importa tanto com a \u201cliberdade\u201d de Bolsonaro? Muitas narrativas foram constru\u00eddas sobre a ideia de que Trump estaria defendendo Bolsonaro, mas isso, para quem pensa que manda no mundo, \u00e9 c\u00f4modo e apenas uma cortina de fuma\u00e7a para o que est\u00e1 por tr\u00e1s. Quais s\u00e3o os reais motivos do ataque comercial dos EUA ao nosso pa\u00eds?<\/p>\n<p>Quando Trump atacou o Brasil em guerras comerciais, n\u00e3o foi por acaso. O agroneg\u00f3cio brasileiro, nossa capacidade energ\u00e9tica (do pr\u00e9-sal ao potencial verde) e nosso papel nos BRICS representam uma amea\u00e7a aos interesses imperialistas. A China, que sofreu san\u00e7\u00f5es por avan\u00e7ar em 5G e intelig\u00eancia artificial, mostra o que acontece quando um pa\u00eds do Sul Global ousa competir em tecnologia. E o Brasil?<\/p>\n<p>O Brasil, com sua vasta biodiversidade, recursos naturais e potencial energ\u00e9tico, sempre foi cobi\u00e7ado por pot\u00eancias estrangeiras. Nosso agroneg\u00f3cio competitivo, nossa capacidade em energia renov\u00e1vel (do pr\u00e9-sal ao potencial verde) e nossa posi\u00e7\u00e3o estrat\u00e9gica nos BRICS representam tanto uma oportunidade quanto um risco para a ordem econ\u00f4mica global dominante.<\/p>\n<p>A Embraer, por exemplo, foi alvo de press\u00f5es quando se tornou competitiva no setor aeroespacial. Nossa pesquisa em biocombust\u00edveis e energia renov\u00e1vel poderia colocar o Brasil na vanguarda da transi\u00e7\u00e3o energ\u00e9tica, mas esbarra em interesses de grandes corpora\u00e7\u00f5es internacionais. At\u00e9 a soberania sobre a Amaz\u00f4nia \u00e9 constantemente questionada por aqueles que, sob o discurso ambiental, escondem a cobi\u00e7a por nossa biodiversidade e recursos h\u00eddricos.<\/p>\n<p>O Brasil carrega grandes constru\u00e7\u00f5es que amea\u00e7am a economia global dominante, como exemplo o SUS. Enquanto muitos pa\u00edses mant\u00eam sistemas de sa\u00fade privatizados e excludentes, o Brasil construiu o SUS \u2013 o maior sistema p\u00fablico de sa\u00fade do mundo, refer\u00eancia internacional no tratamento universal e gratuito. Defender o SUS \u00e9 defender um projeto de Brasil que coloca a vida acima do lucro. \u00c9 soberania sanit\u00e1ria em um mundo onde pandemias e crises clim\u00e1ticas s\u00e3o cada vez mais frequentes.<\/p>\n<p>Celebrando o que torna o Brasil um pa\u00eds diverso e soberano, encontramos em nossa cultura um grande celeiro de resist\u00eancia, como \u00e9 o caso do hip-hop e do cinema nacional. A verdadeira ess\u00eancia brasileira n\u00e3o est\u00e1 nos slogans vazios como \u201cDeus, p\u00e1tria e fam\u00edlia\u201d, mas vive na cultura que emerge das periferias. O hip-hop nacional, que denuncia a viol\u00eancia policial e exige direitos, mostra mais patriotismo do que qualquer discurso de \u00f3dio. O cinema brasileiro, que revela nossas contradi\u00e7\u00f5es (de \u201cCentral do Brasil\u201d a \u201cAinda Estamos Aqui\u201d), constr\u00f3i uma narrativa cr\u00edtica sobre nosso pa\u00eds, resgatando mem\u00f3ria, hist\u00f3ria e resist\u00eancia.<\/p>\n<p>Enquanto alguns se autointitulam \u201cpatriotas\u201d e enchem as redes sociais de bandeiras, apoiam pol\u00edticas que:<\/p>\n<ul>\n<li>Entregam nossas empresas p\u00fablicas a grupos estrangeiros;<\/li>\n<li>Cortam investimentos em educa\u00e7\u00e3o e ci\u00eancia, condenando o pa\u00eds ao atraso;<\/li>\n<li>Apoiam agendas que beneficiam o agroneg\u00f3cio predat\u00f3rio, em detrimento da reforma agr\u00e1ria e da agricultura familiar.<\/li>\n<\/ul>\n<p>Esse falso patriotismo n\u00e3o defende o Brasil \u2013 defende os privil\u00e9gios de uma minoria.<\/p>\n<p>Mas h\u00e1 outro verde e amarelo, que \u00e9 constru\u00eddo pela juventude brasileira, por quem se encontra nas salas de aula desse pa\u00eds, dentro das escolas e universidades; o Brasil das comunidades ind\u00edgenas, dos cientistas, de quem acredita em:<\/p>\n<ul>\n<li>Um Brasil que domine tecnologia, n\u00e3o s\u00f3 exporte min\u00e9rio;<\/li>\n<li>Um Brasil que proteja seu povo, n\u00e3o s\u00f3 o lucro das elites;<\/li>\n<li>Um Brasil que n\u00e3o se curve a interesses estrangeiros, mantendo sua autonomia pol\u00edtica e econ\u00f4mica;<\/li>\n<li>Um Brasil com \u201cS\u201d de soberania.<\/li>\n<\/ul>\n<p>De que lado estamos? Negar o cen\u00e1rio pol\u00edtico atual \u00e9 se ausentar de um processo que necessita da democracia de todos os brasileiros. Qual pa\u00eds defendemos? Qual pa\u00eds queremos? Vestir a bandeira n\u00e3o \u00e9 gesto vazio: \u00e9 escolher entre um Brasil col\u00f4nia ou um Brasil pot\u00eancia. E a participa\u00e7\u00e3o efetiva da popula\u00e7\u00e3o brasileira nortear\u00e1 que Brasil teremos num futuro breve: um Brasil forte e soberano ou um Brasil que bate contin\u00eancia a imperador?<\/p>\n<p>Compreender a import\u00e2ncia pol\u00edtica de cada brasileiro hoje para a constru\u00e7\u00e3o do nosso pa\u00eds nos leva ao chamado do plebiscito popular que est\u00e1 em constru\u00e7\u00e3o e \u00e9 uma ferramenta de mobiliza\u00e7\u00e3o direta da popula\u00e7\u00e3o, uma resposta democr\u00e1tica e combativa \u00e0s estruturas de poder que historicamente oprimem o povo brasileiro. Ele surge como um contraponto ao sistema pol\u00edtico-econ\u00f4mico dominante, questionando as bases do capitalismo neoliberal, o imperialismo financeiro e a concentra\u00e7\u00e3o de poder nas m\u00e3os de uma elite que governa em benef\u00edcio pr\u00f3prio, n\u00e3o do povo.<\/p>\n<p>Este \u00e9 o Brasil que devemos escolher. E essa escolha n\u00e3o se faz apenas com palavras, mas com a\u00e7\u00e3o organizada. O plebiscito popular que se constr\u00f3i nas bases \u00e9 nossa ferramenta hist\u00f3rica para:<\/p>\n<ul>\n<li>Reduzir a jornada de trabalho sem redu\u00e7\u00e3o salarial \u2013 enfrentando a l\u00f3gica perversa da superexplora\u00e7\u00e3o;<\/li>\n<li>Acabar com a escala 6\u00d71 \u2013 resgatando a dignidade da classe trabalhadora;<\/li>\n<li>Taxar as grandes fortunas \u2013 isentando quem ganha at\u00e9 5 mil reais e fazendo os ricos pagarem a conta que sempre fugiram.<\/li>\n<\/ul>\n<p>Participar da constru\u00e7\u00e3o do plebiscito \u00e9 uma forma de vestir a camisa verde e amarela do lado de quem defende um Brasil forte e soberano, um jeito novo de ser Cara Pintada e mudar o Brasil do nosso tempo. \u00c9 como hoje se manifesta o verdadeiro amor ao Brasil \u2013 n\u00e3o com bandeiras na janela, mas com as m\u00e3os na massa da transforma\u00e7\u00e3o. A hist\u00f3ria nos julgar\u00e1: de que lado estivemos quando foi preciso escolher entre um Brasil col\u00f4nia e um Brasil soberano?<\/p>\n<p>O post <a href=\"https:\/\/vermelho.org.br\/2025\/08\/06\/a-bandeira-do-brasil-entre-o-falso-patriotismo-e-a-luta-pela-soberania\/\">A bandeira do Brasil entre o falso patriotismo e a luta pela soberania<\/a> apareceu primeiro em <a href=\"https:\/\/vermelho.org.br\/\">Vermelho<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/hemobras-comemora-20-anos-com-pleno-fornecimento-ao-sus-e-recorde-historico\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Hemobr\u00e1s comemora 20 anos com pleno fornecimento a...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/solidariedade-a-deputada-camila-jara\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Solidariedade \u00e0 deputada Camila\u00a0Jara<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/lula-apoia-explorar-petroleo-na-foz-do-amazonas-para-transicao-energetica\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/Indonesia-Lula-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Lula apoia explorar petr\u00f3leo na Foz do Amazonas pa...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/beto-faro-diz-que-mp-combate-fraudes-e-garante-beneficios-aos-pescadores-artesanais\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Beto Faro diz que MP combate fraudes e garante ben...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>A hist\u00f3ria do Brasil \u00e9 marcada por lutas que se refletem nas cores de nossa bandeira. Nos anos 1990, o movimento dos Caras Pintadas, protagonizado pela juventude brasileira, tomou as ruas com os rostos pintados de verde e amarelo, transformando essas cores em um s\u00edmbolo de resist\u00eancia contra a corrup\u00e7\u00e3o e as pol\u00edticas neoliberais do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[12532,12533,132,1048],"tags":[],"class_list":["post-42879","post","type-post","status-publish","format-standard","hentry","category-bandeira-nacional","category-patriotismo","category-politica","category-soberania"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/42879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=42879"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/42879\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=42879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=42879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=42879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}