{"id":47068,"date":"2025-08-24T22:22:07","date_gmt":"2025-08-25T01:22:07","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/moro-e-fraude-do-inss-no-governo-bolsonaro-sao-uma-coisa-so\/"},"modified":"2025-08-24T22:22:07","modified_gmt":"2025-08-25T01:22:07","slug":"moro-e-fraude-do-inss-no-governo-bolsonaro-sao-uma-coisa-so","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/moro-e-fraude-do-inss-no-governo-bolsonaro-sao-uma-coisa-so\/","title":{"rendered":"Moro e fraude do INSS no governo Bolsonaro s\u00e3o uma coisa s\u00f3"},"content":{"rendered":"<p>Um ex-assessor do senador Sergio Moro (Uni\u00e3o Brasil-PR) foi citado nas investiga\u00e7\u00f5es da Pol\u00edcia Federal (PF) sobre o esc\u00e2ndalo de fraudes no INSS, conhecido como \u201cFarra do INSS\u201d ou \u201cAposent\u00e3o\u201d.<\/p>\n<p>As apura\u00e7\u00f5es, conduzidas pela Opera\u00e7\u00e3o Sem Desconto, apontam para um esquema de descontos indevidos em benef\u00edcios de aposentados e pensionistas, que teria causado preju\u00edzos de cerca de R$ 4 bilh\u00f5es.<\/p>\n<p>As men\u00e7\u00f5es ao ex-assessor referem-se \u00e0 altera\u00e7\u00f5es na regula\u00e7\u00e3o de sindicatos e associa\u00e7\u00f5es patronais de trabalhadores, implementadas durante o per\u00edodo em que Sergio Moro era ministro da Justi\u00e7a (2019-2020) no governo Jair Bolsonaro.<\/p>\n<p>Essas mudan\u00e7as teriam enfraquecido sindicatos tradicionais, criando brechas para que entidades de fachada realizassem cobran\u00e7as irregulares nos benef\u00edcios do INSS.<\/p>\n<p>N\u00e3o h\u00e1 detalhes p\u00fablicos sobre a identidade do ex-assessor ou sobre o grau de envolvimento dele no esquema.<\/p>\n<p>Moro negou qualquer rela\u00e7\u00e3o do Minist\u00e9rio da Justi\u00e7a, sob sua gest\u00e3o, com contribui\u00e7\u00f5es associativas ou descontos em aposentadorias, afirmando que as fraudes ocorreram no \u00e2mbito do Minist\u00e9rio da Previd\u00eancia e do pr\u00f3prio INSS.<\/p>\n<p>O caso foi remetido ao Supremo Tribunal Federal (STF) devido ao envolvimento de figuras com foro privilegiado.<\/p>\n<hr>\n<h5>Apoie o Antropofagista com qualquer valor<br \/>\nPIX: 45013993768<br \/>\nAgradecemos imensamente<\/h5>\n<div>\n<div>\n<hr>\n<p><strong>Siga-nos no Whatsapp:<\/strong>\u00a0https:\/\/chat.whatsapp.com\/EDwMnaR2cC27mPiXJEH24i?mode=ac_t<\/p>\n<p><strong>Siga-nos no Facebook:<\/strong>\u00a0https:\/\/www.facebook.com\/profile.php?id=100070790366110<\/p>\n<p><strong>Siga-nos no X:<\/strong>\u00a0https:\/\/x.com\/Antropofagista1<\/p>\n<div><ins data-ad-format=\"auto\" data-ad-client=\"ca-pub-6181673169341280\" data-adsbygoogle-status=\"done\" data-ad-status=\"filled\"><\/p>\n<div><strong>Siga-nos no Instagram:<\/strong><span>\u00a0<\/span>https:\/\/www.instagram.com\/blogantropofagista?igsh=YzljYTk1ODg3Z<\/div>\n<\/p>\n<p><\/ins><\/div>\n<\/div>\n<\/div>\n<p>The post Moro e fraude do INSS no governo Bolsonaro s\u00e3o uma coisa s\u00f3 first appeared on Antropofagista.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/lula-condena-bloqueio-dos-eua-contra-cuba-na-reuniao-cupula-brasil-caribe\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/06\/Brasil-Caribe-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Lula condena bloqueio dos EUA contra Cuba na Reuni...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/partido-socialista-dos-eua-rejeita-fake-news-sobre-participacao-em-assassinato-de-funcionarios-da-embaixada-de-israel\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Partido socialista dos EUA rejeita fake news sobre...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/mulher-que-pichou-perdeu-mane-pede-perdao-em-depoimento-ao-stf\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Mulher que pichou \u2018Perdeu, man\u00e9\u2019 pede perd\u00e3o em de...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/sul21.com.br\/noticias\/geral\/2025\/08\/mpf-critica-governo-leite-por-excluir-povo-guarani-das-celebracoes-dos-400-anos-das-missoes\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">MPF critica governo Leite por excluir povo Guarani...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Um ex-assessor do senador Sergio Moro (Uni\u00e3o Brasil-PR) foi citado nas investiga\u00e7\u00f5es da Pol\u00edcia Federal (PF) sobre o esc\u00e2ndalo de fraudes no INSS, conhecido como \u201cFarra do INSS\u201d ou \u201cAposent\u00e3o\u201d. As apura\u00e7\u00f5es, conduzidas pela Opera\u00e7\u00e3o Sem Desconto, apontam para um esquema de descontos indevidos em benef\u00edcios de aposentados e pensionistas, que teria causado preju\u00edzos de [\u2026]<\/p>\n<p>The post <a href=\"https:\/\/antropofagista.com.br\/2025\/08\/24\/moro-e-fraude-do-inss-no-governo-bolsonaro-sao-uma-coisa-so\/\">Moro e fraude do INSS no governo Bolsonaro s\u00e3o uma coisa s\u00f3<\/a> first appeared on <a href=\"https:\/\/antropofagista.com.br\/\">Antropofagista<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[1820,3251,824,132,270],"tags":[],"class_list":["post-47068","post","type-post","status-publish","format-standard","hentry","category-fraude","category-inss","category-jair-bolsonaro","category-politica","category-sergio-moro"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/47068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=47068"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/47068\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=47068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=47068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=47068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}