{"id":48112,"date":"2025-08-28T19:35:21","date_gmt":"2025-08-28T22:35:21","guid":{"rendered":"https:\/\/redept.org\/blogosfera\/eleicoes-legislativas-argentinas-sao-teste-para-milei-que-amarga-alta-na-desaprovacao\/"},"modified":"2025-08-28T19:35:21","modified_gmt":"2025-08-28T22:35:21","slug":"eleicoes-legislativas-argentinas-sao-teste-para-milei-que-amarga-alta-na-desaprovacao","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/eleicoes-legislativas-argentinas-sao-teste-para-milei-que-amarga-alta-na-desaprovacao\/","title":{"rendered":"Elei\u00e7\u00f5es legislativas argentinas s\u00e3o teste para Milei, que amarga alta na desaprova\u00e7\u00e3o"},"content":{"rendered":"<p>O que parecia mera burocracia para a consolida\u00e7\u00e3o do poder de Javier Milei na Argentina ganha, agora, ares de obst\u00e1culo que pode <a href=\"https:\/\/www.brasildefato.com.br\/2025\/08\/22\/justica-argentina-investiga-denuncia-de-corrupcao-que-envolve-a-irma-de-milei\/\">enfraquecer seu governo extremista de direita<\/a>. Em 7 de setembro, eleitores da prov\u00edncia de Buenos Aires escolhem seus representantes no legislativo local e, em 26 de outubro, v\u00e3o ser eleitos os deputados e senadores nacionais.<\/p>\n<p>Milei enfrenta os maiores \u00edndices de desaprova\u00e7\u00e3o desde o in\u00edcio de seu mandato, em dezembro de 2023. Os n\u00fameros mostram tend\u00eancia de queda. Pesquisa AtlasIntel publicada nesta quinta-feira (28) indica que mais da metade dos argentinos (51%) desaprova seu governo. Em julho, a desaprova\u00e7\u00e3o era de 47,8%.<\/p>\n<p>Os n\u00fameros preocupam a Casa Rosada. Milei tem minoria no Congresso e vem sofrendo derrotas seguidas em suas tentativas de aprovar projetos de lei que aprofundem seu desmonte do Estado. Para n\u00e3o depender de coliga\u00e7\u00f5es com outros partidos para governar, sua administra\u00e7\u00e3o contava com um aumento significativo de legisladores aliados, confiando no <a href=\"https:\/\/www.brasildefato.com.br\/2025\/06\/13\/governo-milei-comemora-queda-da-inflacao-enquanto-povo-sofre-com-demissoes-e-renda-em-queda\/\">controle da infla\u00e7\u00e3o<\/a> para isso.<\/p>\n<p>Entretanto, al\u00e9m da impopularidade de suas medidas de austeridade, que deixaram a maioria da popula\u00e7\u00e3o abaixo da linha da pobreza, o governo do extremista foi atingido em cheio por um esc\u00e2ndalo de corrup\u00e7\u00e3o envolvendo sua irm\u00e3, Karina Milei, que ocupa o cargo de Secret\u00e1ria da Presid\u00eancia. Como term\u00f4metro da crise, os dois foram <a href=\"https:\/\/www.brasildefato.com.br\/2025\/08\/27\/argentina-escandalo-de-corrupcao-no-governo-milei-impacta-intencoes-de-voto-no-inicio-das-eleicoes-regionais\/\">alvo de pedradas e vaias<\/a> nesta quarta-feira (27) em um ato de campanha com seus candidatos ao legislativo na periferia de Buenos Aires. Milei saiu fisicamente ileso, mas as cicatrizes podem ser profundas.<\/p>\n<p>\u201cQualquer esc\u00e2ndalo de corrup\u00e7\u00e3o \u00e9 uma coisa muito complicada. Ainda mais em se tratando de um presidente que sempre se apresentou contra a casta corrupta, com discurso muito forte contra isso quando se elegeu, e criou uma imagem que, mesmo tendo alguns defeitos, jamais teria esse, que \u00e9 considerado t\u00e3o grave\u201d, disse a professora Miriam Gomes Saraiva, do departamento de Rela\u00e7\u00f5es Internacionais da Universidade Estadual do Rio de Janeiro (Uerj).<\/p>\n<p>\u201cAo desmontar essa imagem, ele deve perder eleitores, especialmente aqueles que n\u00e3o t\u00eam lealdade absoluta, n\u00e3o pertencem \u00e0 bolha dele\u201d, afirmou Saraiva ao <strong>Brasil de Fato<\/strong>.<\/p>\n<h4>Esc\u00e2ndalo<\/h4>\n<p>O epis\u00f3dio veio \u00e0 tona com a divulga\u00e7\u00e3o de \u00e1udios que implicam Karina em supostas cobran\u00e7as de suborno na compra de medicamentos para pessoas com defici\u00eancia. A irm\u00e3 \u00e9 considerada o bra\u00e7o direito do presidente.<\/p>\n<p>Calcula-se que ela embolsava cerca de US$ 15 mil (R$ 82 mil) por m\u00eas com o esquema. Karina ainda n\u00e3o se pronunciou publicamente sobre o esc\u00e2ndalo, que derrubou a bolsa de Buenos Aires, gerou press\u00e3o sobre o c\u00e2mbio da moeda local, o peso, e aumentou o risco-pa\u00eds.<\/p>\n<p>O caso ocorre ap\u00f3s o Congresso anular um <a href=\"https:\/\/www.brasildefato.com.br\/2025\/08\/05\/milei-veta-leis-sociais-e-amplia-tensao-com-oposicao-e-pessoas-com-deficiencia-na-argentina\/\">veto de Milei<\/a> a uma lei que declara a Emerg\u00eancia em Defici\u00eancia e destina mais fundos para o setor, o que representa um golpe pol\u00edtico para o presidente.<\/p>\n<p>Na Argentina, os legisladores \u2013 C\u00e2mara e Senado \u2013 s\u00e3o renovados a cada dois anos, o que significa que um presidente pode perder ou ganhar base de apoio. Para a professora Miriam Saraiva, as elei\u00e7\u00f5es de 7 de setembro na capital argentina ser\u00e3o uma \u201cantessala das elei\u00e7\u00f5es nacionais\u201d.<\/p>\n<p>\u201cSe Milei tiver muitos votos em setembro, deve ter tamb\u00e9m em outubro, mesmo porque Buenos Aires, por ter quantidade muito grande de eleitores, normalmente d\u00e1 a t\u00f4nica do que vai ocorrer nacionalmente.\u201d<\/p>\n<p>\u201cA administra\u00e7\u00e3o de Milei deve ficar com uma base maior no Congresso do que tem hoje. Mas para mim, hoje, parece dif\u00edcil que ele consiga eleger a quantidade necess\u00e1ria de parlamentares para aprovar todos os seus projetos\u201d, avalia a analista.<\/p>\n<p>O post <a href=\"https:\/\/www.brasildefato.com.br\/2025\/08\/28\/eleicoes-legislativas-argentinas-sao-teste-para-milei-que-amarga-alta-na-desaprovacao\/\">Elei\u00e7\u00f5es legislativas argentinas s\u00e3o teste para Milei, que amarga alta na desaprova\u00e7\u00e3o<\/a> apareceu primeiro em <a href=\"https:\/\/www.brasildefato.com.br\/\">Brasil de Fato<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/mostra-sobre-escravidao-contemporanea-entra-em-cartaz-no-palacio-tiradentes-no-rio-de-janeiro\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Mostra sobre escravid\u00e3o contempor\u00e2nea entra em car...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/china-e-russia-reagem-a-tarifa-de-trump-e-elevam-tom-contra-coercao\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/07\/d36864e5-f629-4d78-b615-c4848867252b-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">China e R\u00fassia reagem a tarifa de Trump e elevam t...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/ato-em-defesa-da-soberania-nacional-reune-universidades-e-institutos-federais-em-porto-alegre\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/08\/image-5-2-150x128.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ato em defesa da soberania nacional re\u00fane universi...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/maduro-diz-que-venezuela-tem-5-mil-misseis-russos-para-se-defender-dos-eua\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/8320f7ce-09d5-4f92-a1e9-2f29ab056f76-447302256-487706590446905-8700891616130820939-n-150x150.webp') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Maduro diz que Venezuela tem 5 mil m\u00edsseis russos ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>O que parecia mera burocracia para a consolida\u00e7\u00e3o do poder de Javier Milei na Argentina ganha, agora, ares de obst\u00e1culo que pode enfraquecer seu governo extremista de direita. Em 7 de setembro, eleitores da prov\u00edncia de Buenos Aires escolhem seus representantes no legislativo local e, em 26 de outubro, v\u00e3o ser eleitos os deputados e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[4703,50],"tags":[],"class_list":["post-48112","post","type-post","status-publish","format-standard","hentry","category-bdf","category-internacional"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/48112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=48112"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/48112\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=48112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=48112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=48112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}