{"id":53662,"date":"2025-09-20T20:13:24","date_gmt":"2025-09-20T23:13:24","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/brasil-exclui-eua-de-reuniao-sobre-democracia-durante-assembleia-da-onu\/"},"modified":"2025-09-20T20:13:24","modified_gmt":"2025-09-20T23:13:24","slug":"brasil-exclui-eua-de-reuniao-sobre-democracia-durante-assembleia-da-onu","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/brasil-exclui-eua-de-reuniao-sobre-democracia-durante-assembleia-da-onu\/","title":{"rendered":"Brasil exclui EUA de reuni\u00e3o sobre democracia durante Assembleia da ONU"},"content":{"rendered":"<p>Decis\u00e3o do governo Lula reflete cr\u00edticas ao governo Trump e leva a aus\u00eancia in\u00e9dita dos EUA em c\u00fapula internacional sobre democracia<\/p>\n<p>O Brasil decidiu n\u00e3o incluir os Estados Unidos na lista de participantes da reuni\u00e3o \u201cDemocracia Sempre\u201d, que ser\u00e1 realizada na pr\u00f3xima semana em Nova York, paralelamente \u00e0 Assembleia-Geral da ONU. A informa\u00e7\u00e3o foi publicada pela Folha de S.Paulo, que destacou a mudan\u00e7a em rela\u00e7\u00e3o ao ano passado, quando os norte-americanos estiveram entre os convidados.<\/p>\n<p>A c\u00fapula, idealizada inicialmente por Brasil e Espanha, reunir\u00e1 cerca de 30 pa\u00edses, entre eles Uruguai, Col\u00f4mbia, Chile, Alemanha, Canad\u00e1, Fran\u00e7a, M\u00e9xico, Noruega, Qu\u00eania, Senegal e Timor Leste. Tamb\u00e9m deve participar o secret\u00e1rio-geral da ONU, Ant\u00f3nio Guterres, al\u00e9m de representantes da Uni\u00e3o Europeia.<\/p>\n<p><strong>Crit\u00e9rios de exclus\u00e3o dos EUA<\/strong><br \/>\nSegundo um integrante do governo brasileiro, a lista de convidados foi restrita a na\u00e7\u00f5es consideradas plenamente democr\u00e1ticas. A exclus\u00e3o dos Estados Unidos, sob a presid\u00eancia de Donald Trump, foi justificada pelo \u201cretrocesso extremista\u201d vivido no pa\u00eds e pelo questionamento do governo americano \u00e0s elei\u00e7\u00f5es brasileiras, de acordo com Ot\u00e1vio Rosso, 247.<\/p>\n<p>Entre os principais temas do encontro est\u00e3o a defesa da democracia, o combate \u00e0 desigualdade social e a luta contra a desinforma\u00e7\u00e3o. O presidente Luiz In\u00e1cio Lula da Silva j\u00e1 havia participado de uma edi\u00e7\u00e3o do evento no Chile, em julho, quando os l\u00edderes reafirmaram seu compromisso com a preserva\u00e7\u00e3o das institui\u00e7\u00f5es democr\u00e1ticas e com a coopera\u00e7\u00e3o internacional frente \u00e0s amea\u00e7as globais.<\/p>\n<p><strong>Tens\u00f5es com o governo Trump<\/strong><br \/>\nDesde que reassumiu a Casa Branca, Donald Trump tem adotado medidas que geram atritos em f\u00f3runs multilaterais. Um dos primeiros atos de seu governo foi uma ordem executiva que pro\u00edbe pol\u00edticas de combate \u00e0 desinforma\u00e7\u00e3o, consideradas pelo republicano como censura. Al\u00e9m disso, Trump tem pressionado emissoras e empresas a punirem figuras p\u00fablicas que fizeram cr\u00edticas a apoiadores conservadores. O apresentador Jimmy Kimmel, da ABC, foi suspenso ap\u00f3s coment\u00e1rio sobre o assassinato de Charlie Kirk, militante de direita morto na semana passada.<\/p>\n<p>Outro ponto de fric\u00e7\u00e3o \u00e9 a regula\u00e7\u00e3o das grandes plataformas digitais. Enquanto Uni\u00e3o Europeia e pa\u00edses latino-americanos pressionam por leis que obriguem as Big Tech a moderar conte\u00fados nocivos, Trump se coloca contra qualquer restri\u00e7\u00e3o e amea\u00e7a impor tarifas a blocos econ\u00f4micos que adotem legisla\u00e7\u00f5es mais r\u00edgidas.<\/p>\n<p><strong>Refer\u00eancias a ataques antidemocr\u00e1ticos<\/strong><br \/>\nNo convite enviado aos pa\u00edses em 2024, Lula e S\u00e1nchez citaram tanto os ataques de 8 de janeiro em Bras\u00edlia quanto a invas\u00e3o ao Capit\u00f3lio, em Washington, como exemplos de movimentos violentos que rejeitam a altern\u00e2ncia de poder e a diversidade. J\u00e1 em seu novo mandato, Trump concedeu perd\u00e3o a 1.500 pessoas condenadas pela invas\u00e3o ao Congresso americano, medida que aprofundou a percep\u00e7\u00e3o de enfraquecimento democr\u00e1tico nos EUA.<\/p>\n<hr>\n<h5>Apoie o Antropofagista com qualquer valor<br \/>\nPIX: 45013993768<br \/>\nAgradecemos aos nossos leitores<\/h5>\n<hr>\n<p><strong>Siga-nos no Facebook:<\/strong> https:\/\/www.facebook.com\/profile.php?id=100070790366110<\/p>\n<p><strong>Siga-nos no Whatsapp:<\/strong> https:\/\/chat.whatsapp.com\/K8Zc6XOHkN258pOahSE1L1mode=ems_copy_c<\/p>\n<p><strong>Siga-nos no X:<\/strong> https:\/\/x.com\/Antropofagista1<\/p>\n<p><strong>Siga-nos no Instagram<\/strong> https:\/\/www.instagram.com\/blogantropofagista?igsh=YzljYTk1ODg3Z<\/p>\n<p>The post Brasil exclui EUA de reuni\u00e3o sobre democracia durante Assembleia da ONU first appeared on Antropofagista.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/emprego-formal-avanca-abril-tem-melhor-saldo-desde-2020\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Emprego formal avan\u00e7a: abril tem melhor saldo desd...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/ceasefire-must-include-recognition-of-the-palestinian-state\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Ceasefire must include recognition of the Palestin...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/show-bad-bunny-em-sao-paulo-guia-para-curtir-benito-no-allianz-parque\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/02\/AFP__20260209__2260606473__v1__MidRes__AppleMusicSuperBowlLxHalftimeShow-e1770636779779-1-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Show Bad Bunny em S\u00e3o Paulo: guia para curtir Beni...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/sul21.com.br\/noticias\/educacao\/2025\/11\/projeto-inclui-disciplina-de-educacao-moral-e-civica-na-rede-municipal-de-porto-alegre\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Projeto inclui disciplina de Educa\u00e7\u00e3o Moral e C\u00edvi...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Decis\u00e3o do governo Lula reflete cr\u00edticas ao governo Trump e leva a aus\u00eancia in\u00e9dita dos EUA em c\u00fapula internacional sobre democracia O Brasil decidiu n\u00e3o incluir os Estados Unidos na lista de participantes da reuni\u00e3o \u201cDemocracia Sempre\u201d, que ser\u00e1 realizada na pr\u00f3xima semana em Nova York, paralelamente \u00e0 Assembleia-Geral da ONU. A informa\u00e7\u00e3o foi publicada [\u2026]<\/p>\n<p>The post <a href=\"https:\/\/antropofagista.com.br\/2025\/09\/20\/brasil-exclui-eua-de-reuniao-sobre-democracia-durante-assembleia-da-onu\/\">Brasil exclui EUA de reuni\u00e3o sobre democracia durante Assembleia da ONU<\/a> first appeared on <a href=\"https:\/\/antropofagista.com.br\/\">Antropofagista<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[17539,45,9,26],"tags":[],"class_list":["post-53662","post","type-post","status-publish","format-standard","hentry","category-assembleia-da-onu","category-brasil","category-eua","category-mundo"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/53662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=53662"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/53662\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=53662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=53662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=53662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}