{"id":54539,"date":"2025-09-24T17:34:20","date_gmt":"2025-09-24T20:34:20","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/lula-cobra-de-nacoes-desenvolvidas-a-apresentacao-de-ndcs-para-cop30\/"},"modified":"2025-09-24T17:34:20","modified_gmt":"2025-09-24T20:34:20","slug":"lula-cobra-de-nacoes-desenvolvidas-a-apresentacao-de-ndcs-para-cop30","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/lula-cobra-de-nacoes-desenvolvidas-a-apresentacao-de-ndcs-para-cop30\/","title":{"rendered":"Lula cobra de na\u00e7\u00f5es desenvolvidas a apresenta\u00e7\u00e3o de NDCs para COP30"},"content":{"rendered":"<p>O presidente Luiz In\u00e1cio Lula da Silva fez nesta quarta-feira\u00a0(24) um chamado para que os pa\u00edses desenvolvidos se engajem no compromisso de apresentar novas Contribui\u00e7\u00f5es Nacionalmente Determinadas (NDCs,\u00a0na sigla em ingl\u00eas), com metas atualizadas de redu\u00e7\u00e3o de emiss\u00f5es de gases de efeito estufa, conforme estabelece o Acordo de Paris. Leia em <strong><a href=\"https:\/\/tvtnews.com.br\/\">TVT News<\/a><\/strong>.<\/p>\n<p>Durante o Evento Especial sobre Clima para Chefes de Estado e de Governo, na Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas,\u00a0Lula lembrou que as novas NDCs ser\u00e3o determinantes para os debates que ser\u00e3o travados durante a COP30.<\/p>\n<p>\u201cA transi\u00e7\u00e3o energ\u00e9tica abre as portas para uma transforma\u00e7\u00e3o produtiva e tecnol\u00f3gica equipar\u00e1vel \u00e0 revolu\u00e7\u00e3o industrial. As NDCs s\u00e3o o mapa do caminho que guiar\u00e1 cada pa\u00eds nessa mudan\u00e7a. Elas n\u00e3o s\u00e3o meros n\u00fameros ou percentuais,\u00a0s\u00e3o uma oportunidade para repensar e reorientar a pol\u00edtica e investimentos rumo a um novo paradigma econ\u00f4mico. Para que isso ocorra em escala global, as na\u00e7\u00f5es ricas precisam antecipar as suas metas de neutralidade clim\u00e1tica e ampliar o acesso a recursos e tecnologias a pa\u00edses em desenvolvimento\u201d, defendeu.<\/p>\n<blockquote>\n<p>\u201cQueremos promover uma c\u00fapula de lideres que propicie um di\u00e1logo franco e direto \u00e0\u00a0altura da miss\u00e3o que as nossas sociedades nos confiaram. Temos a chance de reparar injusti\u00e7as e construir um futuro pr\u00f3spero e sustent\u00e1vel para todos. Por isso, fa\u00e7o um apelo para os pa\u00edses que ainda n\u00e3o apresentaram as suas NDCs: o sucesso da COP 30 depende de voc\u00eas\u201d, concluiu Lula.<\/p>\n<figure>\n<div>\n<\/div>\n<\/figure>\n<\/blockquote>\n<h2>Negacionismo<\/h2>\n<p>Lula co-presidiu, ao lado do secret\u00e1rio-geral da ONU, Ant\u00f3nio Guterres, o evento, com autoridades de diferentes pa\u00edses.\u00a0Segundo o presidente, a COP30, que ocorrer\u00e1 em novembro, em Bel\u00e9m, ser\u00e1 a COP \u201cda verdade\u201d, pois mostrar\u00e1 o grau de compromisso dos pa\u00edses no enfrentamento \u00e0s mudan\u00e7as clim\u00e1ticas.<\/p>\n<blockquote>\n<p>\u201cVamos juntos fazer da Amaz\u00f4nia\u00a0o palco de um momento decisivo da hist\u00f3ria do multirateralismo. Tenho dito ao secret\u00e1rio-geral que a COP 30 \u00e9 a COP da verdade. Ela vai ter que dizer se acreditamos ou n\u00e3o no que a ci\u00eancia est\u00e1 nos mostrando. Se n\u00f3s, lideres e chefes de estado, confiamos ou n\u00e3o na ci\u00eancia\u201d, discursou.<\/p>\n<\/blockquote>\n<p>\u201cAo sediar a COP, na Amaz\u00f4nia, o Brasil quer mostrar que n\u00e3o h\u00e1 como preservar a natureza sem cuidar das pessoas. N\u00e3o h\u00e1 como revolucionar a nossa rela\u00e7\u00e3o com o planeta sem engajar uma ampla gama de atores\u201d, complementou.<\/p>\n<p>O presidente brasileiro criticou o negacionismo clim\u00e1tico e acrescentou que h\u00e1 tamb\u00e9m um negacionismo\u00a0multirateral, que amea\u00e7a compromissos globais.<\/p>\n<p>\u201cO negacionismo que enfrentamos n\u00e3o \u00e9 apenas clim\u00e1tico, mas tamb\u00e9m multilateral. Ningu\u00e9m est\u00e1 a salvo dos efeitos da mudan\u00e7a do clima. Muros nas fronteiras n\u00e3o v\u00e3o conter secas e tempestades. A natureza n\u00e3o se curva a bombas nem a navios de guerra. Nenhum pa\u00eds est\u00e1 acima do outro. O risco do unilateralismo \u00e9 a rea\u00e7\u00e3o em cadeia que ele provoca. Cada compromisso rompido \u00e9 um convite para atitudes isoladas. O resultado \u00e9 um c\u00edrculo vicioso de desconfian\u00e7a e paralisia. Precisamos resgatar a convic\u00e7\u00e3o na mobiliza\u00e7\u00e3o coletiva\u201d, alertou.<\/p>\n<p>O presidente destacou a posi\u00e7\u00e3o do Brasil com o comprometimento de redu\u00e7\u00e3o das emiss\u00f5es de gases do efeito estufa.<\/p>\n<p>\u201cEstamos comprometidos em\u00a0reduzir as emiss\u00f5es de todos os gases do efeito estufa entre 59% e 67%, [at\u00e9 2035, em compara\u00e7\u00e3o com o que o pa\u00eds emitiu em 2005] abrangendo todos os setores da economia. Nossa meta de zerar o desmatamento at\u00e9 2030 contribuir\u00e1 para concretizar esse objetivo\u201d, afirmou.<\/p>\n<p><em>Luciano Nascimento \u2013 rep\u00f3rter da <a href=\"https:\/\/agenciabrasil.ebc.com.br\/meio-ambiente\/noticia\/2025-09\/lula-cobra-nacoes-desenvolvidas-apresentarem-ndcs-para-cop30\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">Ag\u00eancia Brasil<\/a><\/em><\/p>\n<p>The post <a rel=\"nofollow\" href=\"https:\/\/tvtnews.com.br\/lula-cobra-de-nacoes-desenvolvidas-a-apresentacao-de-ndcs-para-cop30\/\">Lula cobra de na\u00e7\u00f5es desenvolvidas a apresenta\u00e7\u00e3o de NDCs para COP30<\/a> appeared first on <a rel=\"nofollow\" href=\"https:\/\/tvtnews.com.br\/\">TVT News<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/venezuela-repatria-menores-de-idade-que-estavam-presos-nos-eua\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/07\/diosdado-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Venezuela repatria menores de idade que estavam pr...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/na-mira-das-eolicas-indigenas-kapinawa-conseguem-suspender-leilao-de-parte-das-suas-terras\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-09-at-191225-150x150.jpeg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Na mira das e\u00f3licas, ind\u00edgenas Kapinaw\u00e1 conseguem ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/trump-recua-de-novo-apos-ameacas-e-ira-celebra-derrota-inegavel-e-historica-do-inimigo\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/04\/55166758984_49f9663295_k-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Trump recua de novo ap\u00f3s amea\u00e7as, e Ir\u00e3 celebra \u2018d...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/inscricoes-para-o-sisu-comecam-nesta-segunda-feira-19\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Inscri\u00e7\u00f5es para o Sisu come\u00e7am nesta segunda-feira...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>O presidente Luiz In\u00e1cio Lula da Silva fez nesta quarta-feira\u00a0(24) um chamado para que os pa\u00edses desenvolvidos se engajem no compromisso de apresentar novas Contribui\u00e7\u00f5es Nacionalmente Determinadas (NDCs,\u00a0na sigla em ingl\u00eas), com metas atualizadas de redu\u00e7\u00e3o de emiss\u00f5es de gases de efeito estufa, conforme estabelece o Acordo de Paris. Leia em TVT News. Durante o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[2519,489,112,26],"tags":[],"class_list":["post-54539","post","type-post","status-publish","format-standard","hentry","category-cop30","category-destaque-pequeno","category-lula","category-mundo"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/54539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=54539"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/54539\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=54539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=54539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=54539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}