{"id":57876,"date":"2025-10-11T11:06:16","date_gmt":"2025-10-11T14:06:16","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/desabamento-no-restaurante-jamile-quem-sao-e-onde-estao-os-verdadeiros-donos-do-negocio\/"},"modified":"2025-10-11T11:06:16","modified_gmt":"2025-10-11T14:06:16","slug":"desabamento-no-restaurante-jamile-quem-sao-e-onde-estao-os-verdadeiros-donos-do-negocio","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/desabamento-no-restaurante-jamile-quem-sao-e-onde-estao-os-verdadeiros-donos-do-negocio\/","title":{"rendered":"Desabamento no restaurante Jamile: quem s\u00e3o e onde est\u00e3o os verdadeiros donos do neg\u00f3cio?"},"content":{"rendered":"<p>Desde a \u00faltima quarta-feira, 8 de outubro, os paulistanos se perguntam quem s\u00e3o e onde est\u00e3o os donos do restaurante Jamile, localizado na regi\u00e3o do \u2018Bixiga\u2019, na capital de S\u00e3o Paulo. Foi nesse estabelecimento que o mezanino desabou, causando a morte da cozinheira Su\u00eania Maria Tom\u00e9 Bezerra e ferindo mais oito pessoas.<\/p>\n<p>A pergunta se justifica pela aus\u00eancia de respons\u00e1veis pelo local. At\u00e9 o momento, os empres\u00e1rios que antes eram relacionados ao restaurante na imprensa ou negaram participa\u00e7\u00e3o no neg\u00f3cio, caso do chef Henrique Foga\u00e7a, ou n\u00e3o se manifestaram, como os empres\u00e1rios Anuar Tacach, da ag\u00eancia promocional Out of Office e Alberto Hiar, conhecido como Turco Loco, fundador da marca de roupas Cavalera e ex-deputado estadual de S\u00e3o Paulo pelo PSDB (1999 a 2007).<\/p>\n<p>Quando ocorre um desastre com v\u00edtimas fatais, como o que aconteceu no restaurante Jamile, os donos do local s\u00e3o os primeiros a ser procurados porque s\u00e3o os respons\u00e1veis pelo espa\u00e7o, como explica a advogada Fernanda Marotti.<\/p>\n<p>\u201cO acidente de trabalho com resultado morte \u00e9 um dos eventos mais graves no \u00e2mbito das rela\u00e7\u00f5es laborais. Al\u00e9m de representar uma trag\u00e9dia humana, ele gera importantes consequ\u00eancias jur\u00eddicas nas esferas trabalhista, civil e penal, impondo \u00e0 empresa e seus administradores deveres imediatos e responsabilidades de longo prazo\u201d, afirma.<\/p>\n<p>Para tentar elucidar a d\u00favida e descobrir quem deve responder pelo desabamento, a <strong>Ag\u00eancia P\u00fablica<\/strong> realizou uma pesquisa na Junta Comercial de S\u00e3o Paulo (Jucesp) e na prefeitura de S\u00e3o Paulo. A surpresa foi que os nomes do chef e dos empres\u00e1rios n\u00e3o constam nos cadastros de constitui\u00e7\u00e3o das empresas que funcionam no endere\u00e7o do restaurante Jamile desde 2015, quando o neg\u00f3cio foi inaugurado. De acordo com esses documentos, nos \u00faltimos dez anos, o restaurante Jamile teve apenas duas \u201cdonas\u201d, Viviane Esteque e Mislaine Monteiro Silva.<\/p>\n<div>\n<div>\n<h2>Por que isso importa?<\/h2>\n<\/p><\/div>\n<div>\n<ul>\n<li>O eventual uso de terceiros, tamb\u00e9m conhecidos como \u2018laranjas\u2019, na constitui\u00e7\u00e3o da empresa, \u00e9 uma forma de escapar de responsabilidades que a legisla\u00e7\u00e3o imp\u00f5e e pode permitir que quem realmente lucra com o neg\u00f3cio saia ileso de acusa\u00e7\u00f5es criminais<\/li>\n<\/ul><\/div>\n<\/p><\/div>\n<h2><strong>Por que Foga\u00e7a, Anuar e Hiar s\u00e3o identificados como donos do Jamile?<\/strong><\/h2>\n<p>As primeiras notas na imprensa, publicadas logo ap\u00f3s o incidente, identificavam o local como \u201crestaurante de Henrique Foga\u00e7a\u201d, o famoso jurado do reality show MasterChef. Erro justific\u00e1vel porque Henrique Foga\u00e7a assina o menu do restaurante e tem se colocado como o rosto institucional do Jamile. Em uma entrevista de 2024 \u00e0 revista Pequenas Empresas, Grandes Neg\u00f3cios, Foga\u00e7a afirma que pretende expandir o restaurante como franquia. Ap\u00f3s o desabamento, entretanto, a assessoria do chef esclareceu, via uma nota oficial, que ele nunca foi s\u00f3cio do local ou exerceu qualquer fun\u00e7\u00e3o de administra\u00e7\u00e3o.<\/p>\n<p>Desfeito o mal-entendido, surgiram reportagens com os nomes de dois empres\u00e1rios que desde 2015 se apresentam na imprensa como os respons\u00e1veis pelo Jamile: Anuar Tacach e Alberto Hiar, o Turco Loco. Eles foram procurados pela reportagem, mas n\u00e3o retornaram os contatos. O espa\u00e7o segue aberto para manifesta\u00e7\u00e3o.<\/p>\n<p>Tacach e Hiar, de fato, nunca foram juridicamente s\u00f3cios do restaurante Jamile, que \u00e9 um nome fantasia. O primeiro registro do neg\u00f3cio na Jucesp aconteceu em 1\u00ba de agosto de 2012, tr\u00eas anos antes da sua inaugura\u00e7\u00e3o, como Tredici Bar e Restaurante. Eram tr\u00eas s\u00f3cios, um casal de investidores que hoje vive no Reino Unido e Viviane Esteque, irm\u00e3 de Val\u00e9ria Steck Hiar, esposa de Alberto Hiar. Viviane tamb\u00e9m \u00e9 s\u00f3cia da Cavalera, que entrou em recupera\u00e7\u00e3o judicial em 2021.<\/p>\n<p>Em 2013, os outros dois nomes foram retirados da sociedade e Viviane Esteque se tornou a \u00fanica s\u00f3cia-administradora da Tredici, situa\u00e7\u00e3o que mant\u00e9m at\u00e9 hoje. Em 1\u00ba de outubro de 2018 a empresa enfrentou uma execu\u00e7\u00e3o fiscal \u2013 que \u00e9 basicamente um processo aberto pelo munic\u00edpio contra o estabelecimento para cobrar impostos devidos.<\/p>\n<p>Em setembro de 2020, de acordo com um processo da Fazenda P\u00fablica do Estado de S\u00e3o Paulo, houve o pedido de bloqueio de valores. Isso se alongou at\u00e9 julho de 2025, quando houve o pedido de penhora de bens da s\u00f3cia Viviane Esteque, que, de acordo com o mesmo processo, n\u00e3o tem bens penhor\u00e1veis.<\/p>\n<p>No dia 28 de agosto de 2025 houve a \u00faltima decis\u00e3o judicial, que bloqueou todos os bens passados e futuros da Tredici Bar e Restaurante, e o juiz concedeu ao estabelecimento mais um ano para pagar a d\u00edvida de cerca de R$ 213 mil.<\/p>\n<p>A essa altura, por\u00e9m, a Tredici j\u00e1 n\u00e3o se encaixava mais no segmento de bares e restaurantes. Com o argumento que precisava se reestruturar por causa da pandemia de Covid-19, a empresa modificou o seu ramo de neg\u00f3cios. No dia 30 de novembro de 2021 passou a ser uma empresa de processamento de dados. O endere\u00e7o foi alterado para um edif\u00edcio residencial no bairro Ipiranga, e o telefone continuou sendo o mesmo do restaurante Jamile.<\/p>\n<p>Com essa mudan\u00e7a, desde 25 de junho de 2019, o Restaurante Jamile opera sob uma segunda raz\u00e3o social: Studio Bar e Restaurante, que funciona exatamente no mesmo endere\u00e7o da Treze de Maio, e com o mesmo telefone divulgado pelo restaurante em sua conta no Instagram. A \u00fanica s\u00f3cia-administradora da empresa \u00e9 Mislaine Monteiro Silva, um nome n\u00e3o-relacionado com qualquer um dos supostos s\u00f3cios. Juridicamente, ela \u00e9 a principal respons\u00e1vel pelo desabamento do dia 8 de outubro, segundo Fernanda Marotti.<\/p>\n<p>\u201cFora as implica\u00e7\u00f5es na esfera trabalhista e civil, a empresa e seus prepostos (s\u00f3cios ou administradores), podem responder criminalmente se o acidente decorrer de viola\u00e7\u00e3o das normas de seguran\u00e7a, seja por neglig\u00eancia, imprud\u00eancia ou imper\u00edcia, pelo crime de homic\u00eddio culposo previsto no art. 121, \u00a73\u00ba, do C\u00f3digo Penal. As penas podem ser agravadas se comprovada omiss\u00e3o dolosa de medidas preventivas para seguran\u00e7a do ambiente de trabalho\u201d, descreve a advogada.<\/p>\n<h2><strong>Quem \u00e9 Mislaine Monteiro Silva<\/strong><\/h2>\n<p>Um m\u00eas antes do desabamento que destruiu a cozinha do Jamile, o empres\u00e1rio Anuar Tacach, que atesta em seu perfil na rede social Facebook trabalhar no restaurante, estava esquiando em Aspen. O chef Henrique Foga\u00e7a, prestador de servi\u00e7o do estabelecimento, estava em viagem ao exterior na semana do desastre, segundo sua assessoria de imprensa.<\/p>\n<p>J\u00e1 Mislaine Monteiro, a s\u00f3cia-propriet\u00e1ria jur\u00eddica desse mesmo restaurante, que teve um faturamento declarado de R$ 6,4 milh\u00f5es no ano de 2023, seguia sua vida com a fam\u00edlia, na periferia de Itapevi, em um conjunto residencial de moradores de baixa renda. A reportagem esteve no local.<\/p>\n<figure><figcaption>Apartamento onde m\u00e3e de Mislaine, Joelma Monteiro, recebeu a reportagem<\/figcaption><\/figure>\n<p>Joelma Monteiro, m\u00e3e de Mislaine, atendeu a <strong>Ag\u00eancia P\u00fablica<\/strong> neste apartamento. Declarou que a filha mora com a fam\u00edlia, mas \u201cprecisou viajar e ficaria pelo menos uma semana fora\u201d. Quando foi informada sobre a reportagem e que, de acordo com os contratos da Jucesp, Mislaine Monteiro era a s\u00f3cia-propriet\u00e1ria do Restaurante Jamile, ela reagiu com indigna\u00e7\u00e3o. Disse que a filha \u201cn\u00e3o tem nada a ver com isso, n\u00e3o \u00e9 dona de nada, e nem trabalhou no restaurante\u201d.<\/p>\n<p>Em meio \u00e0s exclama\u00e7\u00f5es e ao espanto, Joelma explicou que sua outra filha, Jaciara, trabalha no Restaurante Jamile. Mais calma, pediu que a reportagem aguardasse na pequena sala, enquanto foi ao quarto fazer liga\u00e7\u00f5es. Depois de alguns minutos, retornou e disse que quem falaria seria o marido, que estava a caminho.<\/p>\n<p>Antes disso, chegou uma filha, que n\u00e3o quis se identificar, junto com a irm\u00e3 de Joelma. Elas pediram que a reportagem se retirasse. A mulher, que se dizia irm\u00e3 de Mislaine Monteiro tamb\u00e9m reiterou que a posi\u00e7\u00e3o da fam\u00edlia seria a de manter o sil\u00eancio porque n\u00e3o tinha qualquer envolvimento com o assunto.<\/p>\n<h2><strong>Jamile SP: Per\u00edcia<\/strong><\/h2>\n<p>Uma per\u00edcia foi realizada na sexta-feira, 10 de outubro, no restaurante Jamile. Uma testemunha que pediu para n\u00e3o se identificar disse \u00e0 reportagem que a principal hip\u00f3tese para o desabamento \u00e9 o colapso da viga principal do mezanino, devido a uma solda feita fora das especifica\u00e7\u00f5es. N\u00e3o h\u00e1 previs\u00e3o do prazo necess\u00e1rio para entrega do laudo.<\/p>\n<p>A subprefeitura da S\u00e9 informou que o restaurante tinha um laudo de funcionamento emitido em 2022 e que todas as licen\u00e7as estavam em dia. O ex-vereador pelo PT e professor titular de planejamento urbano da Universidade de S\u00e3o Paulo (USP), Nabil Bonduki, afirmou na sexta-feira, 10 de outubro, em uma publica\u00e7\u00e3o em suas redes sociais, que o pedido de reforma do restaurante Jamile nunca foi autorizado pela prefeitura.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/produtores-de-arroz-podem-antecipar-venda-a-conab-para-garantir-preco-minimo\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/04\/238bbb7f5224bf3f2c5cee6f4a148fff-10-150x92.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Produtores de arroz podem antecipar venda \u00e0 Conab ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/anvisa-atualiza-limites-de-curcuma-em-suplementos-alimentares\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Anvisa atualiza limites de c\u00farcuma em suplementos ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/ha-medo-um-estado-de-alerta-permanente-afirma-psicologa-sobre-as-sobreviventes-de-feminicidio\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/04\/image-14-150x128.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">\u2018H\u00e1 medo, um estado de alerta permanente\u2019, afirma ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/china-reage-a-guerra-tarifaria-de-trump-um-beco-sem-saida\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/04\/exportacoes-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">China reage \u00e0 guerra tarif\u00e1ria de Trump: \u2018um beco ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Empres\u00e1rios que se apresentavam como s\u00f3cios do estabelecimento n\u00e3o constam nos documentos de constitui\u00e7\u00e3o da empresa<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[1753,5557,16404,29],"tags":[],"class_list":["post-57876","post","type-post","status-publish","format-standard","hentry","category-empresas","category-portugues","category-restaurantes","category-sao-paulo"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/57876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=57876"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/57876\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=57876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=57876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=57876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}