{"id":61041,"date":"2025-10-28T13:30:23","date_gmt":"2025-10-28T16:30:23","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/jafar-panahi-chega-a-sao-paulo-e-apresenta-seu-novo-filme-vencedor-em-cannes\/"},"modified":"2025-10-28T13:30:23","modified_gmt":"2025-10-28T16:30:23","slug":"jafar-panahi-chega-a-sao-paulo-e-apresenta-seu-novo-filme-vencedor-em-cannes","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/jafar-panahi-chega-a-sao-paulo-e-apresenta-seu-novo-filme-vencedor-em-cannes\/","title":{"rendered":"Jafar Panahi chega a S\u00e3o Paulo e apresenta seu novo filme vencedor em Cannes"},"content":{"rendered":"<p><span>Cineasta iraniano mais proeminente da atualidade, Jafar Panahi participou nesta segunda-feira (29\/10) de um debate na Cinemateca Brasileira ap\u00f3s a estreia de seu novo filme na Mostra Internacional de Cinema de S\u00e3o Paulo. Na ocasi\u00e3o, o diretor recebeu tamb\u00e9m o Pr\u00eamio Humanidade, por \u201cter demonstrado como a cultura e a arte s\u00e3o, hoje e sempre, poderes fundamentais de defesa das liberdades e por expandir os horizontes do audiovisual como linguagem est\u00e9tica, \u00e9tica e pol\u00edtica\u201d, afirma a organiza\u00e7\u00e3o da Mostra. Seu \u00faltimo filme, premiado com a Palma de Ouro de Cannes, <\/span><i><span>Foi apenas um acidente<\/span><\/i><span> (2025), ter\u00e1 ainda mais duas sess\u00f5es no evento.<\/span><\/p>\n<p><span>No longa-metragem, um grupo de ex-presos pol\u00edticos se forma ao encontrarem um homem que acreditam ser seu torturador. A busca pela confirma\u00e7\u00e3o da identidade do agente de Estado leva o grupo a se questionar sobre as possibilidades de vingan\u00e7a ou perd\u00e3o.<\/span><\/p>\n<figure aria-describedby=\"caption-attachment-235904\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\"src=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/jafar-pahani.webp\" alt=\"Jafar Panahi na Cinemateca Brasileira, ao lado da tradutora e da diretora da Mostra internacional de Cinema de S\u00e3o Paulo, Renata de Almeida. &lt;br&gt; (Foto: Caio Brito)\" width=\"1024\" height=\"683\" srcset=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/jafar-pahani.webp 1024w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/10\/jafar-pahani-300x200.webp 300w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/10\/jafar-pahani-768x512.webp 768w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/10\/jafar-pahani-150x100.webp 150w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/10\/jafar-pahani-750x500.webp 750w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><figcaption>Jafar Panahi na Cinemateca Brasileira, ao lado da tradutora e da diretora da Mostra internacional de Cinema de S\u00e3o Paulo, Renata de Almeida. <br \/>(Foto: Caio Brito)<\/figcaption><\/figure>\n<p><span>A condi\u00e7\u00e3o dos personagens em <\/span><i><span>Foi apenas um acidente<\/span><\/i><span> se espelha \u00e0quela do diretor, liberto de mais um dos muitos per\u00edodos na pris\u00e3o. Diante de seu cinema eminentemente pol\u00edtico, Panahi acumula graves penalidades desde 2010, quando foi condenado a seis anos de pris\u00e3o e proibido de fazer filmes, escrever roteiros, viajar para o exterior e falar com a m\u00eddia por 20 anos. Em 2022, foi preso novamente e s\u00f3 foi liberado em 2023, ap\u00f3s uma greve de fome.<\/span><\/p>\n<p><span>Segundo o diretor, a ideia do filme surgiu de hist\u00f3rias que ele mesmo ouviu de seus colegas de cela enquanto estava preso. Apesar de ressaltar a import\u00e2ncia do perd\u00e3o em diversas cenas, o que lhe interessa \u00e9 olhar para o futuro e mostrar para as pessoas que, para que ele seja poss\u00edvel, a viol\u00eancia deve acabar. Para tanto, explora o trauma e as consequ\u00eancias f\u00edsicas e emocionais da viol\u00eancia estatal, que coloca os personagens em uma posi\u00e7\u00e3o pendular que oscila entre o papel de v\u00edtimas e de poss\u00edveis vil\u00f5es. \u201cNo cinema social, n\u00e3o existe ser humano completamente bom ou completamente ruim. Nesse cinema, o importante \u00e9 o ser humano, a humanidade de cada um\u201d, afirmou no debate na Cinemateca Brasileira.<\/span><\/p>\n<p><span>Interessado em olhar para a sociedade, com uma lente que focaliza nos indiv\u00edduos para refletir sobre o coletivo, Panahi nunca deixou de filmar, mesmo diante dos riscos enfrentados. Para abordar as quest\u00f5es de g\u00eanero no Ir\u00e3 em seus primeiros filmes, diante da repress\u00e3o e limita\u00e7\u00f5es impostas \u00e0 inclus\u00e3o de mulheres no cinema, recorreu a meninas crian\u00e7as para fazer sua defesa dos direitos das mulheres. Quando proibido de fazer filmes, em pris\u00e3o domiciliar, utilizou uma pequena c\u00e2mera dom\u00e9stica para fazer o longa-metragem <\/span><i><span>Isto n\u00e3o \u00e9 um filme<\/span><\/i><span> (2011) e retratar os obst\u00e1culos enfrentados pelo cinema iraniano contempor\u00e2neo. Sem poder trabalhar com cinema, decidiu dirigir um t\u00e1xi acompanhado de uma c\u00e2mera, que registrava os passageiros. A partir do material, montou <\/span><i><span>T\u00e1xi Teer\u00e3<\/span><\/i><span> (2015), um de seus filmes mais conhecidos e celebrados. Com uma produ\u00e7\u00e3o prol\u00edfica, criativa e transgressora, tornou-se o \u00fanico cineasta do mundo premiado com o Urso de Ouro, em Berlim, a Palma de Ouro, em Cannes, o Leopardo de Ouro, em Locarno, e o Le\u00e3o de Ouro, em Veneza.<\/span><\/p>\n<figure aria-describedby=\"caption-attachment-235906\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\"src=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/rsz_1jafar_pahani.jpeg\" alt='Cena de \"Foi apenas um acidente\" (2025). &lt;br&gt; (Foto: Divulga\u00e7\u00e3o)' width=\"1024\" height=\"540\" srcset=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/rsz_1jafar_pahani.jpeg 1024w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/10\/rsz_1jafar_pahani-300x158.jpeg 300w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/10\/rsz_1jafar_pahani-768x405.jpeg 768w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/10\/rsz_1jafar_pahani-150x79.jpeg 150w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2025\/10\/rsz_1jafar_pahani-750x396.jpeg 750w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><figcaption>Cena de \u201cFoi apenas um acidente\u201d (2025). <br \/>(Foto: Divulga\u00e7\u00e3o)<\/figcaption><\/figure>\n<p><b>Servi\u00e7o<\/b><\/p>\n<p><i><span>Foi apenas um acidente<\/span><\/i><span> ser\u00e1 exibido na Mostra Internacional de Cinema de S\u00e3o Paulo nos dias:<\/span><\/p>\n<p><span>27\/10, segunda-feira, \u00e0s 18h30 \/ Sala Petrobras na Mostra \u2013 Cinemateca Brasileira.<\/span><\/p>\n<p><span>28\/10, ter\u00e7a-feira, \u00e0s 17h15 \/ Cultura Art\u00edstica.<\/span><\/p>\n<p><span>29\/10, quarta-feira, \u00e0s 20h40 \/ Reserva Cultural \u2013 Sala 1<\/span><\/p>\n<p><span>Ingressos dispon\u00edveis para compra 4 dias antes de cada sessa\u0303o pelo app do evento e pelo site da Velox, sempre a partir das 9h. No dia da sessa\u0303o, uma pequena cota estara\u0301 disponi\u0301vel para compra diretamente na bilheteria do cinema.<\/span><\/p>\n<p><span>Segundas, terc\u0327as, quartas e quintas: R$ 26,00 (inteira) | R$ 13,00 (meia).<\/span><\/p>\n<p><span>Sextas, sa\u0301bados e domingos: R$ 32,00 (inteira) | R$ 16,00 (meia).<\/span><\/p>\n<p><span>Mais informa\u00e7\u00f5es em: https:\/\/mostra.org\/<\/span><\/p>\n<div data-id=\"3a925c7\" data-element_type=\"widget\" data-widget_type=\"jnews_archive_title_elementor.default\">\n<div>\n<div>\n<div>\n<div><em><strong>(*)<\/strong> Graduada em Audiovisual pela ECA-USP, <strong>Nayla Guerra<\/strong> \u00e9 produtora cultural na Cinemateca Brasileira e organizadora do coletivo Cine Sapat\u00e3o. \u00c9 autora do livro \u201cEntre apagamentos e resist\u00eancias\u201d (Editora Alameda, 2023) e diretora do filme \u201cFerro\u2019s Bar\u201d (2023).<\/em><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>O post Jafar Panahi chega a S\u00e3o Paulo e apresenta seu novo filme vencedor em Cannes apareceu primeiro em Opera Mundi.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/trump-faz-bravata-contra-drogas-mas-foco-e-petroleo-venezuelano-avalia-especialista-em-direito-internacional\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Trump faz \u2018bravata contra drogas\u2019, mas foco \u00e9 petr...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/sem-citar-trump-barroso-diz-que-nao-ha-perseguicao-no-brasil\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/07\/barroso_Foto-Gustavo-MorenoSCOSTF-150x150.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Sem citar Trump, Barroso diz que n\u00e3o h\u00e1 persegui\u00e7\u00e3...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/vivemos-o-maior-ciclo-de-investimentos-privados-em-infraestrutura-do-pais-afirma-ministro\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">\u2018Vivemos o maior ciclo de investimentos privados e...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/abin-de-bolsonaro-monitorou-movimentos-populares-e-criticas-apos-tragedia-de-brumadinho\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Abin de Bolsonaro monitorou movimentos populares e...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Cineasta iraniano mais proeminente da atualidade, Jafar Panahi participou nesta segunda-feira (29\/10) de um debate na Cinemateca Brasileira ap\u00f3s a estreia de seu novo filme na Mostra Internacional de Cinema de S\u00e3o Paulo. Na ocasi\u00e3o, o diretor recebeu tamb\u00e9m o Pr\u00eamio Humanidade, por \u201cter demonstrado como a cultura e a arte s\u00e3o, hoje e sempre, [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/operamundi.uol.com.br\/cultura\/jafar-panahi-chega-a-sao-paulo-e-apresenta-seu-novo-filme-vencedor-em-cannes\/\">Jafar Panahi chega a S\u00e3o Paulo e apresenta seu novo filme vencedor em Cannes<\/a> apareceu primeiro em <a href=\"https:\/\/operamundi.uol.com.br\/\">Opera Mundi<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":61042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[18018,488,309,41,5854,27247,27248],"tags":[],"class_list":["post-61041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cineasta","category-cinema","category-cultura","category-ira","category-iraniano","category-jafar-pahani","category-mostra-sp"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/61041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=61041"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/61041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media\/61042"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=61041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=61041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=61041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}