{"id":61287,"date":"2025-10-29T18:57:35","date_gmt":"2025-10-29T21:57:35","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/trabalho-um-respiro-nos-tempos-de-barbarie\/"},"modified":"2025-10-29T18:57:35","modified_gmt":"2025-10-29T21:57:35","slug":"trabalho-um-respiro-nos-tempos-de-barbarie","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/trabalho-um-respiro-nos-tempos-de-barbarie\/","title":{"rendered":"Trabalho: um respiro nos tempos de barb\u00e1rie"},"content":{"rendered":"<figure><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"850\" height=\"560\"src=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/IMG_6191-850x560-1.jpg\" alt=\"\" srcset=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/IMG_6191-850x560-1.jpg 850w, https:\/\/outraspalavras.net\/wp-content\/uploads\/2025\/10\/IMG_6191-850x560-1-300x198.jpg 300w, https:\/\/outraspalavras.net\/wp-content\/uploads\/2025\/10\/IMG_6191-850x560-1-768x506.jpg 768w\" sizes=\"(max-width: 850px) 100vw, 850px\"><\/figure>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<h4>Boletim Outras Palavras<\/h4>\n<p>Receba por email, diariamente, todas as publica\u00e7\u00f5es do site<\/p>\n<\/p><\/div>\n<div>\n<div>\n<div>\n<div>\n<div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n                <button type=\"submit\">Assinar<\/button><br \/>\n                <button disabled type=\"button\"> <\/p>\n<div><\/div>\n<p> <span>Loading&#8230;<\/span> <\/button>\n              <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n            <button type=\"submit\">Assinar<\/button><br \/>\n            <button disabled type=\"button\"> <\/p>\n<div><\/div>\n<p> <span>Loading&#8230;<\/span> <\/button>\n          <\/div>\n<\/p><\/div>\n<div>\n<div>\n<h4>Agradecemos!<\/h4>\n<p>Voc\u00ea j\u00e1 est\u00e1 inscrito e come\u00e7ar\u00e1 a receber os boletins em breve. Boa leitura!<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Por <strong>Clemente Ganz L\u00facio<\/strong><\/p>\n<p>A negocia\u00e7\u00e3o coletiva \u00e9 um dos pilares fundamentais da regula\u00e7\u00e3o democr\u00e1tica das rela\u00e7\u00f5es de trabalho por meio do di\u00e1logo social. Por meio dela, trabalhadores e empregadores constroem acordos nos quais se distribuem ganhos salariais diretos e indiretos, se ampliam direitos trabalhistas e sociais e organiza o mundo do trabalho na atividade produtiva em torno de par\u00e2metros justos e sustent\u00e1veis. \u00c9 no espa\u00e7o da negocia\u00e7\u00e3o que se materializa o\u00a0di\u00e1logo social\u00a0como instrumento de coes\u00e3o, de avan\u00e7o civilizat\u00f3rio no mundo do trabalho.<\/p>\n<p>No Brasil, a negocia\u00e7\u00e3o coletiva foi consagrada pela Constitui\u00e7\u00e3o de 1988 como um direito essencial, expressando o princ\u00edpio da\u00a0autonomia coletiva, a for\u00e7a normativa das conven\u00e7\u00f5es e acordos coletivos de trabalho e o papel essencial e estrat\u00e9gico dos sindicatos. Esse processo \u00e9 ainda mais relevante em um pa\u00eds com forte heterogeneidade produtiva, altos n\u00edveis de desigualdade, m\u00faltiplas formas de inser\u00e7\u00e3o ocupacional e alta informalidade, rotatividade, precariza\u00e7\u00e3o e vulnerabilidade.<\/p>\n<div>\n<div><img decoding=\"async\"src=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/Prancheta--24.png\" alt=\"\" srcset=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/Prancheta--24.png 680w, https:\/\/outraspalavras.net\/wp-content\/uploads\/2022\/12\/Prancheta-4-300x110.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" width=\"680\" height=\"250\"><\/div>\n<\/div>\n<p>A negocia\u00e7\u00e3o coletiva \u00e9, portanto,\u00a0instrumento de promo\u00e7\u00e3o da cidadania e governan\u00e7a econ\u00f4mica, pois permite que temas espec\u00edficos \u2014 muitas vezes invis\u00edveis \u00e0s normas gerais \u2014 sejam tratados com precis\u00e3o setorial e legitimidade.<\/p>\n<p>Nos \u00faltimos anos, esse papel ganhou renovada import\u00e2ncia diante dos desafios contempor\u00e2neos: a digitaliza\u00e7\u00e3o, o teletrabalho, as diversidades de g\u00eanero, ra\u00e7a, orienta\u00e7\u00e3o sexual e pessoas com defici\u00eancia nas empresas, a transi\u00e7\u00e3o ecol\u00f3gica e ambiental e as novas demandas de cuidado e concilia\u00e7\u00e3o entre vida pessoal e profissional. O fortalecimento da negocia\u00e7\u00e3o coletiva \u00e9, portanto, condi\u00e7\u00e3o estrat\u00e9gica para a\u00a0transi\u00e7\u00e3o justa\u00a0e para a reconstru\u00e7\u00e3o de um mercado de trabalho mais inclusivo e menos desigual.<\/p>\n<p><strong>A diversidade de temas tratados nas negocia\u00e7\u00f5es coletivas<\/strong><\/p>\n<p>As negocia\u00e7\u00f5es coletivas no Brasil sempre foram marcadas por grande diversidade tem\u00e1tica, portanto, n\u00e3o se restringem a cl\u00e1usulas econ\u00f4micas, como reajustes salariais, pisos ou PLR. Elas abrangem temas como a \u00a0qualidade de vida no trabalho, a\u00a0igualdade de oportunidades, a\u00a0sa\u00fade e seguran\u00e7a, a\u00a0educa\u00e7\u00e3o, o\u00a0meio ambiente, a\u00a0forma\u00e7\u00e3o profissional, o\u00a0direito \u00e0 creche, o\u00a0combate \u00e0s discrimina\u00e7\u00f5es\u00a0e a\u00a0inclus\u00e3o de grupos vulner\u00e1veis.<\/p>\n<p>Esse mosaico de temas reflete a diversidade e abrang\u00eancia das pautas apresentadas pelo sindicalismo brasileiro e a complexidade do mercado de trabalho. Por meio da negocia\u00e7\u00e3o coletiva, novas pautas emergem e ganham for\u00e7a normativa \u2014 como equidade racial, diversidade de g\u00eanero, inclus\u00e3o de jovens, enfrentamento ao ass\u00e9dio moral e sexual, e pol\u00edticas de cuidado.<\/p>\n<p>Esses temas se articulam a uma vis\u00e3o moderna da negocia\u00e7\u00e3o coletiva:\u00a0um instrumento n\u00e3o apenas distributivo, mas tamb\u00e9m civilizat\u00f3rio, que redefine valores sociais e impulsiona transforma\u00e7\u00f5es culturais no ambiente de trabalho.<\/p>\n<p><strong>O Boletim \u201cBoas Pr\u00e1ticas em Negocia\u00e7\u00e3o Coletiva\u201d<\/strong><\/p>\n<div>\n<div><\/div>\n<\/div>\n<p>Com not\u00e1vel sensibilidade, o\u00a0DIEESE<sup>1<\/sup>\u00a0e o\u00a0Minist\u00e9rio do Trabalho e Emprego<sup>2<\/sup> (MTE)\u00a0lan\u00e7aram a s\u00e9rie\u00a0<em>Boas Pr\u00e1ticas em Negocia\u00e7\u00e3o Coletiva<\/em>, um conjunto de boletins que sistematiza, analisa e divulga\u00a0exemplos concretos de cl\u00e1usulas inovadoras\u00a0pactuadas em conven\u00e7\u00f5es e acordos coletivos em todo o pa\u00eds.<\/p>\n<p>A iniciativa nasce da convic\u00e7\u00e3o de que a negocia\u00e7\u00e3o coletiva \u00e9 fonte viva de regula\u00e7\u00e3o e de inova\u00e7\u00e3o social, e que seus resultados merecem ser conhecidos, valorizados e disseminados como\u00a0refer\u00eancias inspiradoras\u00a0para sindicatos, empresas e governos.<\/p>\n<p>Cada boletim aborda um\u00a0tema espec\u00edfico\u00a0\u2014 equidade racial, direito \u00e0 creche, juventude, diversidade sexual e de g\u00eanero, entre outros \u2014 e apresenta\u00a0boas pr\u00e1ticas\u00a0identificadas no\u00a0Sistema Mediador do MTE, a base oficial que registra acordos e conven\u00e7\u00f5es coletivas realizadas no Brasil.<\/p>\n<p>Ao reunir essas experi\u00eancias, o projeto cumpre tr\u00eas pap\u00e9is fundamentais:<\/p>\n<ul>\n<li>Valoriza a negocia\u00e7\u00e3o coletiva\u00a0como mecanismo leg\u00edtimo e eficaz de regula\u00e7\u00e3o trabalhista.<\/li>\n<li>Promove a difus\u00e3o de cl\u00e1usulas exemplares, estimulando a replica\u00e7\u00e3o de boas pr\u00e1ticas em outros setores.<\/li>\n<li>Fortalece o di\u00e1logo social\u00a0e o protagonismo das entidades sindicais como construtoras de pol\u00edticas inclusivas.<\/li>\n<\/ul>\n<p>Essa parceria entre o DIEESE e o MTE reafirma o papel do Estado de fortalecimento da negocia\u00e7\u00e3o, de promo\u00e7\u00e3o da transpar\u00eancia e mostra a vitalidade de um sindicalismo que busca inovar e responder aos desafios do s\u00e9culo XXI.<\/p>\n<p><strong>Destaques de boas pr\u00e1ticas dos primeiros boletins<\/strong><\/p>\n<p><strong>Boletim n\u00ba 1 \u2013 Equidade Racial<sup>3<\/sup><\/strong><\/p>\n<p>O primeiro boletim da s\u00e9rie inaugura o projeto com o tema\u00a0equidade racial, destacando 20 cl\u00e1usulas pactuadas em diferentes categorias. As negocia\u00e7\u00f5es apresentadas envolvem, por exemplo,\u00a0compromissos com a diversidade na contrata\u00e7\u00e3o,\u00a0a\u00e7\u00f5es de combate \u00e0 discrimina\u00e7\u00e3o racial,\u00a0promo\u00e7\u00e3o da igualdade salarial\u00a0e\u00a0cria\u00e7\u00e3o de comiss\u00f5es internas de equidade.<\/p>\n<p>As pr\u00e1ticas citadas demonstram que o movimento sindical tem sido ator ativo na luta contra o racismo estrutural. Ao incluir a equidade racial nas conven\u00e7\u00f5es, a negocia\u00e7\u00e3o coletiva traduz em compromissos concretos aquilo que \u00e9 um valor constitucional: a dignidade da pessoa humana e a igualdade de oportunidades.<\/p>\n<p><strong>Boletim n\u00ba 2 \u2013 Direito \u00e0 Creche<sup>4<\/sup><\/strong><\/p>\n<p>O segundo boletim aborda o\u00a0direito \u00e0 creche, com exemplos de cl\u00e1usulas que ampliam direitos de trabalhadoras e trabalhadores respons\u00e1veis pelo cuidado infantil. Entre as boas pr\u00e1ticas destacam-se:<\/p>\n<ul>\n<li>o\u00a0reembolso-creche\u00a0como benef\u00edcio garantido por muitas conven\u00e7\u00f5es, independentemente do g\u00eanero;<\/li>\n<li>o\u00a0atendimento a crian\u00e7as at\u00e9 seis anos, superando o limite legal de quatro anos; a\u00a0extens\u00e3o do benef\u00edcio a pais solo e casais homoafetivos;<\/li>\n<li>a cria\u00e7\u00e3o de\u00a0creches pr\u00f3prias\u00a0ou conv\u00eanios com institui\u00e7\u00f5es de ensino infantil.<\/li>\n<\/ul>\n<p>Essas experi\u00eancias evidenciam que o tema do cuidado \u2014 historicamente invisibilizado \u2014 vem sendo incorporado \u00e0s mesas de negocia\u00e7\u00e3o, sinalizando avan\u00e7os civilizat\u00f3rios e de igualdade de g\u00eanero.<\/p>\n<p><strong>Boletim n\u00ba 3 \u2013 Juventude e Trabalho<sup>5<\/sup><\/strong><\/p>\n<p>O terceiro boletim trata da\u00a0inclus\u00e3o e prote\u00e7\u00e3o de jovens\u00a0no mundo do trabalho. A publica\u00e7\u00e3o mostra 16 exemplos de cl\u00e1usulas que garantem, entre outros:<\/p>\n<ul>\n<li>flexibilidade de hor\u00e1rios para estudantes;<\/li>\n<li>licen\u00e7a para provas e vestibulares;<\/li>\n<li>incentivo a programas de aprendizagem e est\u00e1gios remunerados;<\/li>\n<li>prioridade de contrata\u00e7\u00e3o para jovens em vulnerabilidade social.<\/li>\n<\/ul>\n<p>Essas boas pr\u00e1ticas refor\u00e7am o papel da negocia\u00e7\u00e3o coletiva na\u00a0integra\u00e7\u00e3o entre educa\u00e7\u00e3o e trabalho, na\u00a0forma\u00e7\u00e3o profissional\u00a0e na\u00a0gera\u00e7\u00e3o de oportunidades\u00a0para a juventude, especialmente em um pa\u00eds onde o desemprego juvenil ainda \u00e9 expressivo.<\/p>\n<p><strong>Boletim n\u00ba 4 \u2013 Diversidade e Popula\u00e7\u00e3o LGBTQIAPN+<sup>6<\/sup><\/strong><\/p>\n<p>O quarto boletim aborda cl\u00e1usulas que promovem\u00a0respeito \u00e0 diversidade sexual e de g\u00eanero. Os exemplos incluem:<\/p>\n<ul>\n<li>inclus\u00e3o de casais homoafetivos\u00a0em benef\u00edcios de sa\u00fade e previd\u00eancia;<\/li>\n<li>uso do nome social\u00a0em todos os registros corporativos;<\/li>\n<li>preven\u00e7\u00e3o e combate ao ass\u00e9dio moral e sexual e \u00e0 discrimina\u00e7\u00e3o;<\/li>\n<li>e a cria\u00e7\u00e3o de\u00a0comiss\u00f5es internas de diversidade.<\/li>\n<\/ul>\n<p>Essas pr\u00e1ticas mostram que a negocia\u00e7\u00e3o coletiva \u00e9 tamb\u00e9m\u00a0instrumento de cidadania e inclus\u00e3o, capaz de transformar o ambiente de trabalho em espa\u00e7o de respeito, dignidade e igualdade.<\/p>\n<p><strong>A negocia\u00e7\u00e3o coletiva como laborat\u00f3rio da democracia<\/strong><\/p>\n<p>Os quatro primeiros boletins\u00a0<em>Boas Pr\u00e1ticas em Negocia\u00e7\u00e3o Coletiva<\/em>\u00a0demonstram a vitalidade da negocia\u00e7\u00e3o como\u00a0laborat\u00f3rio da democracia. Neles, sindicatos e empresas constroem solu\u00e7\u00f5es para temas sens\u00edveis e contempor\u00e2neos, traduzindo demandas de igualdade, cuidado e diversidade em normas efetivas.<\/p>\n<p>A s\u00e9rie reafirma que\u00a0a negocia\u00e7\u00e3o coletiva n\u00e3o \u00e9 apenas um instrumento econ\u00f4mico, mas um\u00a0processo civilizat\u00f3rio, capaz de incorporar novas dimens\u00f5es da vida social ao mundo do trabalho.<\/p>\n<p>O reconhecimento p\u00fablico dessas experi\u00eancias \u2014 promovido pelo DIEESE e pelo MTE \u2014 fortalece o di\u00e1logo social e estimula a dissemina\u00e7\u00e3o de uma cultura de\u00a0compromissos de solidariedade e justi\u00e7a\u00a0nas rela\u00e7\u00f5es de trabalho.<\/p>\n<p>Ao difundir boas pr\u00e1ticas, o projeto cumpre tamb\u00e9m uma fun\u00e7\u00e3o pedag\u00f3gica: inspira novas gera\u00e7\u00f5es de dirigentes sindicais, negociadores e gestores a enxergarem a negocia\u00e7\u00e3o coletiva como\u00a0um campo de inova\u00e7\u00e3o social permanente, essencial para um pa\u00eds que busca conciliar desenvolvimento, igualdade e democracia.<\/p>\n<p>1 DIEESE: https:\/\/www.dieese.org.br<\/p>\n<p>2 MTE: https:\/\/www.gov.br\/trabalho-e-emprego\/pt-br\/noticias-e-conteudo\/2025\/junho\/mte-lanca-serie-de-boletins-com-boas-praticas-em-negociacao-coletiva<\/p>\n<p>3 https:\/\/www.dieese.org.br\/boletimboaspraticas\/2025\/boletimBoasPraticas1_equidadeRacial.html<\/p>\n<p>4 https:\/\/www.dieese.org.br\/boletimboaspraticas\/2025\/boletimBoasPraticas2_creche.html<\/p>\n<p>5 https:\/\/www.dieese.org.br\/boletimboaspraticas\/2025\/boletimBoasPraticas3_jovens.html<\/p>\n<p>6 https:\/\/www.dieese.org.br\/boletimboaspraticas\/2025\/boletimBoasPraticas4_lgbtqiapn.html<\/p>\n<div>\n<div>\n<p><span><em>Outras Palavras \u00e9 feito por muitas m\u00e3os. Se voc\u00ea valoriza nossa produ\u00e7\u00e3o, seja nosso apoiador e fortale\u00e7a o jornalismo cr\u00edtico: <strong>apoia.se\/outraspalavras<\/strong><\/em><\/span><\/p>\n<\/div>\n<\/div>\n<p>The post Trabalho: um respiro nos tempos de barb\u00e1rie appeared first on Outras Palavras.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/lula-entrega-obras-da-cop30-com-investimentos-de-r-15-bilhoes-no-para\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/Belem-COP30-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Lula entrega obras da COP30 com investimentos de R...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/brasil-sinaliza-cooperacao-militar-com-china-apos-desfile-de-misseis-avancados\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Brasil sinaliza coopera\u00e7\u00e3o militar com China ap\u00f3s ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/isso-e-uma-comunidade-so-queremos-paz-policia-militar-de-tarcisio-assassina-trabalhadora-na-zona-leste-de-sp\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-173157-150x150.jpeg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">\u201cIsso \u00e9 uma comunidade. S\u00f3 queremos paz\u201d. Pol\u00edcia ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/lula-reage-a-sancoes-dos-eua-e-defende-moraes-justica-nao-se-negocia\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/07\/5f48b119-9798-4bb0-8438-5685094a709f-150x150.jpeg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Lula reage a san\u00e7\u00f5es dos EUA e defende Moraes: \u2018Ju...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Em meio \u00e0s contrarreformas que devastaram dos direitos laborais, sindicatos refugiam-se nas negocia\u00e7\u00f5es coletivas. Parte delas resulta em amplia\u00e7\u00e3o de direitos reais \u2013 um ref\u00fagio civilizat\u00f3rio, em meio a um pa\u00eds em regress\u00e3o produtiva<\/p>\n<p>The post <a href=\"https:\/\/outraspalavras.net\/crise-brasileira\/trabalho-um-respiro-nos-tempos-de-barbarie\/\">Trabalho: um respiro nos tempos de barb\u00e1rie<\/a> appeared first on <a href=\"https:\/\/outraspalavras.net\/\">Outras Palavras<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":61288,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[978,27409,6007,1679,27410,27411,27412,474,377],"tags":[],"class_list":["post-61287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capitalismo","category-contrarreforma-trabalhista","category-crise-brasileira","category-direitos-trabalhistas","category-negociacoes-trabalhistas","category-papel-do-trabalho","category-processo-civilizatorio","category-sindicatos","category-trabalho"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/61287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=61287"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/61287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media\/61288"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=61287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=61287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=61287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}