{"id":67117,"date":"2025-11-28T17:53:28","date_gmt":"2025-11-28T20:53:28","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/sao-goncalo-400-funcionarios-de-os-denunciam-demissao-sem-direitos\/"},"modified":"2025-11-28T17:53:28","modified_gmt":"2025-11-28T20:53:28","slug":"sao-goncalo-400-funcionarios-de-os-denunciam-demissao-sem-direitos","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/sao-goncalo-400-funcionarios-de-os-denunciam-demissao-sem-direitos\/","title":{"rendered":"S\u00e3o Gon\u00e7alo: 400 funcion\u00e1rios de OS denunciam demiss\u00e3o sem direitos"},"content":{"rendered":"<p><img fetchpriority=\"high\" width=\"1024\" height=\"576\"src=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-28-at-164959.jpeg\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-28-at-16.49.59-1024x576.jpeg 1024w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-28-at-16.49.59-300x169.jpeg 300w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-28-at-16.49.59-768x432.jpeg 768w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-28-at-16.49.59-1536x864.jpeg 1536w, https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-28-at-164959.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/p>\n<p>Cerca de 400 funcion\u00e1rios da organiza\u00e7\u00e3o social In Sa\u00fade foram demitidos, em S\u00e3o Gon\u00e7alo, na Regi\u00e3o Metropolitana do Rio de Janeiro, sem seus direitos rescis\u00f3rios assegurados. \u00c9 o que denuncia a deputada federal Enfermeira Rejane e o vereador de S\u00e3o Gon\u00e7alo, Isaac Ricalde, ambos do PCdoB.<\/p>\n<p>Rejane e Isaac foram procurados, na \u00faltima quinta-feira (27), pelo grupo de trabalhadores. Entre as den\u00fancias est\u00e3o casos de funcion\u00e1rias gr\u00e1vidas demitidas e de c\u00e1lculos rescis\u00f3rios incorretos.<\/p>\n<p><strong>Leia mais: <\/strong><a href=\"https:\/\/vermelho.org.br\/2025\/11\/14\/patroes-do-rj-recorrem-ao-stf-contra-o-feriado-de-corpus-christi\/\">Patr\u00f5es do RJ recorrem contra o feriado de Corpus Christi<\/a><\/p>\n<p>\u201cRecebemos as den\u00fancias e daremos encaminhamento \u00e0 quest\u00e3o. Esse problema tem sido recorrente quando se trata de organiza\u00e7\u00f5es sociais. Ent\u00e3o, por isso, continuo defendendo os concursos p\u00fablicos. As trabalhadoras e os trabalhadores precisam ser respeitados\u201d, disse a deputada federal Enfermeira Rejane.<\/p>\n<p>Agora, a deputada e o vereador aguardam reuni\u00e3o para tratar do assunto diretamente com o prefeito da cidade, Capit\u00e3o Nelson. Isso porque a empresa j\u00e1 atuou no Pronto Socorro Central de S\u00e3o Gon\u00e7alo.<\/p>\n<p>O post <a href=\"https:\/\/vermelho.org.br\/2025\/11\/28\/sao-goncalo-400-funcionarios-de-os-denunciam-demissao-sem-direitos\/\">S\u00e3o Gon\u00e7alo: 400 funcion\u00e1rios de OS denunciam demiss\u00e3o sem direitos<\/a> apareceu primeiro em <a href=\"https:\/\/vermelho.org.br\/\">Vermelho<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/filho-de-musk-manda-trump-se-calar-voce-nao-e-o-presidente-voce-precisa-ir-embora\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Filho de Musk manda Trump se calar: \u2018Voc\u00ea n\u00e3o \u00e9 o ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/xingu-em-disputa\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Xingu em Disputa<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/sul21.com.br\/noticias\/politica\/2025\/08\/stf-forma-maioria-para-condenar-zambelli-pela-segunda-vez-por-porte-ilegal-de-armas\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1655510&amp;o=node') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">STF forma maioria para condenar Zambelli pela segu...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/5-de-fevereiro-e-dia-da-mamografia-exame-pode-ser-feito-no-sus\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">5 de fevereiro \u00e9 Dia da Mamografia: exame pode ser...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Cerca de 400 funcion\u00e1rios da organiza\u00e7\u00e3o social In Sa\u00fade foram demitidos, em S\u00e3o Gon\u00e7alo, na Regi\u00e3o Metropolitana do Rio de Janeiro, sem seus direitos rescis\u00f3rios assegurados. \u00c9 o que denuncia a deputada federal Enfermeira Rejane e o vereador de S\u00e3o Gon\u00e7alo, Isaac Ricalde, ambos do PCdoB. Rejane e Isaac foram procurados, na \u00faltima quinta-feira (27), [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[976,31889,692,49,31890],"tags":[],"class_list":["post-67117","post","type-post","status-publish","format-standard","hentry","category-enfermeira-rejane","category-isaac-ricalde","category-pcdob","category-rio-de-janeiro","category-sao-goncalo"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/67117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=67117"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/67117\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=67117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=67117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=67117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}