{"id":78507,"date":"2026-03-16T16:42:12","date_gmt":"2026-03-16T19:42:12","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/pesquisadores-e-movimentos-denunciam-impactos-da-contrarreforma-do-ensino-medio-nos-ifs\/"},"modified":"2026-03-16T16:42:12","modified_gmt":"2026-03-16T19:42:12","slug":"pesquisadores-e-movimentos-denunciam-impactos-da-contrarreforma-do-ensino-medio-nos-ifs","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/pesquisadores-e-movimentos-denunciam-impactos-da-contrarreforma-do-ensino-medio-nos-ifs\/","title":{"rendered":"Pesquisadores e movimentos denunciam impactos da contrarreforma do ensino m\u00e9dio nos IFs"},"content":{"rendered":"<p>Mais de 200 pesquisadores, educadores e lideran\u00e7as de movimentos sindicais e sociais de todo o pa\u00eds divulgaram a <a href=\"https:\/\/tvtnews.com.br\/wp-content\/uploads\/2026\/03\/Carta-de-Vitoria-em-Defesa-da-Rede-Federal-e-do-Ensino-Medio-Integrado.docx-1.pdf\">Carta de Vit\u00f3ria em Defesa da Rede Federal e do Ensino M\u00e9dio Integrado<\/a> nesta segunda-feira, 16. O documento denuncia os impactos da contrarreforma do ensino m\u00e9dio sobre os Institutos Federais e a educa\u00e7\u00e3o p\u00fablica. A \u00edntegra do documento pode ser acessada abaixo. Leia em\u00a0<strong><a href=\"https:\/\/tvtnews.com.br\/\">TVT News<\/a><\/strong>.<\/p>\n<p>A carta foi aprovada ao final do I Semin\u00e1rio Nacional de Pesquisa sobre a Contrarreforma do Ensino M\u00e9dio na Rede Federal de Educa\u00e7\u00e3o Profissional e Tecnol\u00f3gica, realizado entre os dias 10 e 12 de fevereiro, em Vit\u00f3ria (ES), que reuniu pesquisadores e representantes de movimentos sociais de diferentes regi\u00f5es do pa\u00eds.<\/p>\n<p><a href=\"https:\/\/chat.whatsapp.com\/HC8TJaWXK8t4wNAG0oRwZI?mode=gi_t\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">&gt;&gt; Siga o grupo da\u00a0<strong>TVT News\u00a0<\/strong>no WhatsApp<\/a><\/p>\n<p>O documento re\u00fane resultados de pesquisas que analisam criticamente os efeitos da reforma do Ensino M\u00e9dio iniciada em 2016 e aponta retrocessos no direito \u00e0 forma\u00e7\u00e3o humana integral da juventude e da classe trabalhadora. Mesmo ap\u00f3s altera\u00e7\u00f5es legislativas recentes, os pesquisadores avaliam que os fundamentos da reforma permanecem, mantendo a redu\u00e7\u00e3o da forma\u00e7\u00e3o geral em cursos t\u00e9cnicos e refor\u00e7ando a flexibiliza\u00e7\u00e3o curricular.<\/p>\n<p>A carta tamb\u00e9m alerta para o subfinanciamento da Rede Federal de Educa\u00e7\u00e3o Profissional, Cient\u00edfica e Tecnol\u00f3gica. Dados apresentados no semin\u00e1rio indicam que o n\u00famero de matr\u00edculas quase dobrou nos \u00faltimos anos, enquanto o or\u00e7amento permaneceu praticamente estagnado, o que pressiona a capacidade das institui\u00e7\u00f5es de manter a qualidade das atividades de ensino, pesquisa e extens\u00e3o.<\/p>\n<p>Al\u00e9m da den\u00fancia, o documento apresenta 18 propostas para fortalecer o Ensino M\u00e9dio Integrado e a Rede Federal, entre elas a amplia\u00e7\u00e3o do or\u00e7amento da rede, a garantia de autonomia pedag\u00f3gica das institui\u00e7\u00f5es e a cria\u00e7\u00e3o de pol\u00edticas p\u00fablicas de incentivo \u00e0 forma\u00e7\u00e3o integrada.<\/p>\n<p>Os signat\u00e1rios afirmam que a defesa do Ensino M\u00e9dio Integrado e da Rede Federal est\u00e1 diretamente ligada \u00e0 garantia do direito \u00e0 educa\u00e7\u00e3o p\u00fablica e de qualidade. \u201cEnsino M\u00e9dio Integrado \u00e9 direito inalien\u00e1vel. A Rede Federal de EPT \u00e9 patrim\u00f4nio do povo brasileiro\u201d, conclui o documento.<\/p>\n<\/p>\n<p>The post <a rel=\"nofollow\" href=\"https:\/\/tvtnews.com.br\/pesquisadores-e-movimentos-denunciam-impactos-da-contrarreforma-do-ensino-medio-nos-ifs\/\">Pesquisadores e movimentos denunciam impactos da contrarreforma do ensino m\u00e9dio nos IFs<\/a> appeared first on <a rel=\"nofollow\" href=\"https:\/\/tvtnews.com.br\/\">TVT News<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/ivan-cepeda-indica-lider-indigena-como-candidata-a-vice-presidencial-na-colombia\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/03\/cepquil-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Iv\u00e1n Cepeda indica l\u00edder ind\u00edgena como candidata a...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/7a-semana-das-ligas-e-lutas-camponesas-acontece-de-13-a-18-de-julho-em-sape-pb\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">7\u00aa Semana das Ligas e Lutas Camponesas acontece de...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/globo-de-ouro-uma-batalha-apos-a-outra-e-adolescencia-dominam-premiacao-veja-onde-assistir\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/01\/RJP34218-e1768234474799-150x150.webp') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Globo de Ouro: Uma Batalha Ap\u00f3s a Outra e Adolesc\u00ea...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/bom-para-todos-debate-o-fim-da-escala-6x1-nesta-segunda\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Bom Para Todos debate o fim da escala 6\u00d71 nesta se...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Mais de 200 pesquisadores, educadores e lideran\u00e7as de movimentos sindicais e sociais de todo o pa\u00eds divulgaram a Carta de Vit\u00f3ria em Defesa da Rede Federal e do Ensino M\u00e9dio Integrado nesta segunda-feira, 16. O documento denuncia os impactos da contrarreforma do ensino m\u00e9dio sobre os Institutos Federais e a educa\u00e7\u00e3o p\u00fablica. A \u00edntegra do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[489,95,2298],"tags":[],"class_list":["post-78507","post","type-post","status-publish","format-standard","hentry","category-destaque-pequeno","category-educacao","category-escola"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/78507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=78507"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/78507\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=78507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=78507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=78507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}