{"id":83084,"date":"2026-04-15T10:34:41","date_gmt":"2026-04-15T13:34:41","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/defesa-de-ramagem-tenta-asilo-nos-eua-para-barrar-extradicao-ao-brasil\/"},"modified":"2026-04-15T10:34:41","modified_gmt":"2026-04-15T13:34:41","slug":"defesa-de-ramagem-tenta-asilo-nos-eua-para-barrar-extradicao-ao-brasil","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/defesa-de-ramagem-tenta-asilo-nos-eua-para-barrar-extradicao-ao-brasil\/","title":{"rendered":"Defesa de Ramagem tenta asilo nos EUA para barrar extradi\u00e7\u00e3o ao Brasil"},"content":{"rendered":"<p><img fetchpriority=\"high\" width=\"1024\" height=\"684\"src=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/04\/ficha-de-prisao-de-Alexandre-Ramagem-2048x1367-1.webp\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/vermelho.org.br\/wp-content\/uploads\/2026\/04\/ficha-de-prisao-de-Alexandre-Ramagem-1024x684.webp 1024w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2026\/04\/ficha-de-prisao-de-Alexandre-Ramagem-300x200.webp 300w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2026\/04\/ficha-de-prisao-de-Alexandre-Ramagem-768x513.webp 768w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2026\/04\/ficha-de-prisao-de-Alexandre-Ramagem-1536x1026.webp 1536w, https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/04\/ficha-de-prisao-de-Alexandre-Ramagem-2048x1367-1.webp 2048w, https:\/\/vermelho.org.br\/wp-content\/uploads\/2026\/04\/ficha-de-prisao-de-Alexandre-Ramagem-272x182.webp 272w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/p>\n<p>A defesa do ex-agente bolsonarista Alexandre Ramagem intensificou, nos \u00faltimos dias, a estrat\u00e9gia de solicitar asilo pol\u00edtico nos Estados Unidos. O objetivo \u00e9 travar o processo de envio do condenado ao Brasil, utilizando a tese de \u201cpersegui\u00e7\u00e3o pol\u00edtica\u201d. Aliados pr\u00f3ximos, como o senador Jorge Seif (PL-SC), j\u00e1 se manifestaram publicamente para dar sustenta\u00e7\u00e3o pol\u00edtica a essa narrativa, tentando transformar um caso de condena\u00e7\u00e3o criminal em uma quest\u00e3o de ref\u00fagio de direitos.<\/p>\n<p>Essa movimenta\u00e7\u00e3o \u00e9 vista pelas autoridades brasileiras como uma manobra clara para impedir a deporta\u00e7\u00e3o ou extradi\u00e7\u00e3o. O diretor-geral da Pol\u00edcia Federal rebateu as tentativas da defesa de desvirtuar o caso. <strong>\u201cN\u00e3o h\u00e1 persegui\u00e7\u00e3o pol\u00edtica. H\u00e1 condena\u00e7\u00e3o por crimes graves contra a democracia\u201d<\/strong>, refor\u00e7ou Andrei Rodrigues, em declara\u00e7\u00e3o reproduzida pela Ag\u00eancia Brasil.<\/p>\n<p>\u00a0O governo brasileiro, via Itamaraty e Minist\u00e9rio da Justi\u00e7a, mant\u00e9m a press\u00e3o pela extradi\u00e7\u00e3o baseado no tratado de 1965 para que Ramagem cumpra a pena imposta pelo STF. O ex-diretor da Abin, que estava foragido desde o ano passado, tentava se manter invis\u00edvel em territ\u00f3rio americano at\u00e9 ser abordado em uma fiscaliza\u00e7\u00e3o de tr\u00e2nsito rotineira, o que desencadeou o processo atual.<\/p>\n<p><strong>A foto oficial do fichamento<\/strong><\/p>\n<p>A imagem do fichamento de Ramagem foi liberada pelas autoridades do Condado de Orange e circula amplamente. Nela, o ex-dirigente aparece com moletom verde, barba por fazer e express\u00e3o s\u00e9ria. O registro oficial, datado de 13\/04\/2026, traz o n\u00famero de reserva <strong>26013314<\/strong> e indica que ele est\u00e1 na cela <strong>BRC3D<\/strong>. A legenda do sistema americano \u00e9 direta: \u201cDETEN\u00c7\u00c3O DE IMIGRA\u00c7\u00c3O\u201d.<\/p>\n<p>Alexandre Ramagem est\u00e1 sob cust\u00f3dia do <strong>ICE<\/strong> (<em>U.S. Immigration and Customs Enforcement<\/em>) no Orange County Corrections. Sua deten\u00e7\u00e3o ocorreu por irregularidade migrat\u00f3ria, o chamado <em>overstay<\/em> (visto expirado), uma vez que seus documentos diplom\u00e1ticos foram cancelados ap\u00f3s a condena\u00e7\u00e3o no Brasil. O sistema de imigra\u00e7\u00e3o dos EUA agora processa sua perman\u00eancia, enquanto o Brasil aguarda que os tr\u00e2mites resultem em sua entrega imediata \u00e0 justi\u00e7a brasileira.<\/p>\n<p><strong>Coopera\u00e7\u00e3o policial internacional\u00a0<\/strong><\/p>\n<p>Segundo nota oficial da PF, Ramagem foi capturado ap\u00f3s \u201ccoopera\u00e7\u00e3o policial internacional entre a Pol\u00edcia Federal e autoridades policiais dos EUA\u201d. Ele \u00e9 considerado foragido da Justi\u00e7a brasileira desde setembro de 2025, quando <strong>o Supremo Tribunal Federal (STF) o condenou a 16 anos de pris\u00e3o pelos crimes de organiza\u00e7\u00e3o criminosa armada, golpe de Estado e tentativa de aboli\u00e7\u00e3o violenta do Estado de Direito<\/strong>.\u00a0<\/p>\n<p>Ramagem \u00e9 considerado o articulador central da \u201cAbin paralela\u201d montada no governo Bolsonaro. Sua pris\u00e3o refor\u00e7a o compromisso do governo Lula com o combate aos ataques contra o Estado Democr\u00e1tico de Direito. Ele \u00e9 apontado como pe\u00e7a-chave nas investiga\u00e7\u00f5es sobre a estrutura de intelig\u00eancia que subsidiou as a\u00e7\u00f5es golpistas e os ataques \u00e0s sedes dos Tr\u00eas Poderes em 8 de janeiro de 2023.<\/p>\n<p>O post <a href=\"https:\/\/vermelho.org.br\/2026\/04\/15\/defesa-de-ramagem-tenta-asilo-nos-eua-para-barrar-extradicao-ao-brasil\/\">Defesa de Ramagem tenta asilo nos EUA para barrar extradi\u00e7\u00e3o ao Brasil<\/a> apareceu primeiro em <a href=\"https:\/\/vermelho.org.br\/\">Vermelho<\/a>.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/memoria-juventude-e-luta-antirracista-marcam-debate-sobre-o-futuro-do-pt\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Mem\u00f3ria, juventude e luta antirracista marcam deba...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/carro-perseguido-por-viatura-da-pm-voa-a-3-m-em-cruzamento-video\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Carro perseguido por viatura da PM voa a 3 m em cr...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/saiba-como-sera-o-expediente-dos-bancos-no-natal-e-no-ano-novo\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Saiba como ser\u00e1 o expediente dos bancos no Natal e...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/educacao-para-as-massas-o-sistema-de-ensino-na-uniao-sovietica\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/02\/english_classes_in_moscow_school_1964_36-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Educa\u00e7\u00e3o para as massas: o sistema de ensino na Un...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>A defesa do ex-agente bolsonarista Alexandre Ramagem intensificou, nos \u00faltimos dias, a estrat\u00e9gia de solicitar asilo pol\u00edtico nos Estados Unidos. O objetivo \u00e9 travar o processo de envio do condenado ao Brasil, utilizando a tese de \u201cpersegui\u00e7\u00e3o pol\u00edtica\u201d. Aliados pr\u00f3ximos, como o senador Jorge Seif (PL-SC), j\u00e1 se manifestaram publicamente para dar sustenta\u00e7\u00e3o pol\u00edtica a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[8528,891,15453,114,31590,2129,6530,1764,132,47489],"tags":[],"class_list":["post-83084","post","type-post","status-publish","format-standard","hentry","category-abin-paralela","category-alexandre-ramagem","category-asilo-politico","category-bolsonarismo","category-extradicao-ramagem","category-golpe-de-estado","category-ice","category-policia-federal","category-politica","category-prisao-ramagem-eua"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/83084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=83084"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/83084\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=83084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=83084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=83084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}