{"id":84704,"date":"2026-04-24T14:40:32","date_gmt":"2026-04-24T17:40:32","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/agente-dos-eua-deixa-o-brasil-apos-retirada-de-credenciais\/"},"modified":"2026-04-24T14:40:32","modified_gmt":"2026-04-24T17:40:32","slug":"agente-dos-eua-deixa-o-brasil-apos-retirada-de-credenciais","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/agente-dos-eua-deixa-o-brasil-apos-retirada-de-credenciais\/","title":{"rendered":"Agente dos EUA deixa o Brasil ap\u00f3s retirada de credenciais"},"content":{"rendered":"<p>O governo dos Estados Unidos informou nesta sexta-feira (24\/04) que o agente norte-americano Michael Myers, que trabalhava junto \u00e0 Pol\u00edcia Federal (PF), deixou o pa\u00eds ap\u00f3s a decis\u00e3o da pr\u00f3pria PF e do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores de retirar suas credenciais, adotando medidas de reciprocidade em rela\u00e7\u00e3o uma determina\u00e7\u00e3o recente de Washington envolvendo um delegado brasileiro.<\/p>\n<p>Segundo a Casa Branca, Myers trabalhava desde 2024 em colabora\u00e7\u00e3o com a PF, como parte de um acordo de coopera\u00e7\u00e3o entre os dois pa\u00edses em mat\u00e9ria de Seguran\u00e7a.<\/p>\n<p>O comunicado norte-americano informa que o agente deixou o pa\u00eds na mesma quarta-feira (22\/04) em que teve suas credenciais retiradas.<\/p>\n<p>A retirada das credenciais foi aplicada a um segundo agente norte-americano, que tamb\u00e9m trabalhava em colabora\u00e7\u00e3o com a PF.<\/p>\n<p>As autoridades brasileiras n\u00e3o informaram a identidade do agente, mas afirmam que ele n\u00e3o saiu do pa\u00eds. Sobre o caso de Myers, o Itamaraty esclareceu que, apesar da retirada das credenciais, o agente n\u00e3o foi expulso do Brasil, e deixou o pa\u00eds por decis\u00e3o pr\u00f3pria.<\/p>\n<h3>Caso Ramagem<\/h3>\n<p>A quest\u00e3o da reciprocidade ganhou repercuss\u00e3o na \u00faltima segunda-feira (20\/04), quando o Escrit\u00f3rio para Assuntos do Hemisf\u00e9rio Ocidental dos Estados Unidos informou que pediu a sa\u00edda de um \u201cfuncion\u00e1rio brasileiro\u201d do pa\u00eds \u2013 a postagem n\u00e3o citou o nome do funcion\u00e1rio envolvido, mas detalhou que ele estaria ligado \u00e0 pris\u00e3o do ex-deputado federal Alexandre Ramagem (PL-RJ).<\/p>\n<p>Ramagem foi condenado a 16 anos de pris\u00e3o por seu envolvimento na trama golpista liderada pelo ex-presidente Jair Bolsonaro (2019-2023) ap\u00f3s o segundo turno das elei\u00e7\u00f5es de 2022.<\/p>\n<p>O ex-parlamentar, que tamb\u00e9m foi diretor-geral da Ag\u00eancia Brasileira de Intelig\u00eancia (Abin) durante o governo de Bolsonaro, se encontrava foragido em Miami desde setembro de 2025, e foi preso no dia 13 de abril por agentes do Servi\u00e7o de Imigra\u00e7\u00e3o e Controle de Aduanas (ICE, por sua sigla em ingl\u00eas), mas libertado dois dias depois.<\/p>\n<figure aria-describedby=\"caption-attachment-252951\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\"src=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/04\/rafa.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/04\/rafa.jpg 800w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/04\/rafa-300x200.jpg 300w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/04\/rafa-768x512.jpg 768w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/04\/rafa-150x100.jpg 150w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/04\/rafa-750x500.jpg 750w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\"><figcaption>Edif\u00edcio sede da Pol\u00edcia Federal, em Bras\u00edlia <br \/>Rafa Neddermeyer \/ Ag\u00eancia Brasil<\/figcaption><\/figure>\n<p>A puni\u00e7\u00e3o ao delegado da PF que trabalhou em colabora\u00e7\u00e3o com o ICE na pris\u00e3o de Ramagem foi criticada pelo presidente do Brasil, Luiz In\u00e1cio Lula da Silva, durante um evento na Alemanha, onde realiza visita de Estado.<\/p>\n<p>\u201cSe houve um abuso dos norte-americanos em rela\u00e7\u00e3o ao nosso policial, n\u00f3s vamos aplicar reciprocidade com um deles no Brasil. N\u00e3o tem conversa\u201d, disse o mandat\u00e1rio brasileiro.<\/p>\n<p>Segundo Lula, \u201cn\u00e3o podemos aceitar inger\u00eancia e abuso de autoridade que algumas personalidades norte-americanas querem ter em rela\u00e7\u00e3o ao Brasil\u201d.<\/p>\n<p>O post Agente dos EUA deixa o Brasil ap\u00f3s retirada de credenciais apareceu primeiro em Opera Mundi.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/pl-da-devastacao-fragiliza-licenciamento-ambiental-e-amplia-efeitos-da-crise-climatica\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/07\/image-7-11-150x150.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">PL da Devasta\u00e7\u00e3o fragiliza licenciamento ambiental...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/medidas-fiscais-reforcam-compromisso-com-pais-mais-justo-e-governo-eficiente-avaliam-senadores\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Medidas fiscais refor\u00e7am compromisso com pa\u00eds mais...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/prefeito-de-manchester-ameaca-mandato-de-keir-starmer-no-reino-unido-saiba-quem-e\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/06\/andy-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Prefeito de Manchester amea\u00e7a mandato de Keir Star...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/trump-ameaca-saida-da-otan-e-projeta-mudancas-em-politica-externa-dos-eua\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2024\/12\/Captura-de-Tela-2024-12-09-as-16.50.30-150x150.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Trump amea\u00e7a sa\u00edda da OTAN e projeta mudan\u00e7as em p...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>O governo dos Estados Unidos informou nesta sexta-feira (24\/04) que o agente norte-americano Michael Myers, que trabalhava junto \u00e0 Pol\u00edcia Federal (PF), deixou o pa\u00eds ap\u00f3s a decis\u00e3o da pr\u00f3pria PF e do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores de retirar suas credenciais, adotando medidas de reciprocidade em rela\u00e7\u00e3o uma determina\u00e7\u00e3o recente de Washington envolvendo um delegado [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/operamundi.uol.com.br\/brasil\/agente-dos-eua-deixa-o-brasil-apos-retirada-de-credenciais\/\">Agente dos EUA deixa o Brasil ap\u00f3s retirada de credenciais<\/a> apareceu primeiro em <a href=\"https:\/\/operamundi.uol.com.br\/\">Opera Mundi<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":84705,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[4749,1390,45,9,2129,518,112,51033,1200,1798,260],"tags":[],"class_list":["post-84704","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-abin","category-bolsonaro","category-brasil","category-eua","category-golpe-de-estado","category-itamaraty","category-lula","category-michael-myers","category-pf","category-ramagem","category-stf"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/84704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=84704"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/84704\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media\/84705"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=84704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=84704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=84704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}