{"id":86020,"date":"2026-05-04T17:01:39","date_gmt":"2026-05-04T20:01:39","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/um-golpe-privado-mercenarios-da-silvercorp-invadem-a-venezuela\/"},"modified":"2026-05-04T17:01:39","modified_gmt":"2026-05-04T20:01:39","slug":"um-golpe-privado-mercenarios-da-silvercorp-invadem-a-venezuela","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/um-golpe-privado-mercenarios-da-silvercorp-invadem-a-venezuela\/","title":{"rendered":"Um golpe privado: mercen\u00e1rios da Silvercorp invadem a Venezuela"},"content":{"rendered":"<p>H\u00e1 seis anos, em 4 de maio de 2020, a Venezuela era alvo de uma tentativa frustrada de invas\u00e3o organizada por mercen\u00e1rios ligados \u00e0 Silvercorp, uma empresa de seguran\u00e7a privada dos Estados Unidos.<\/p>\n<p>Batizada de \u201cOpera\u00e7\u00e3o Gide\u00e3o\u201d, a ofensiva tinha como objetivo derrubar o presidente Nicol\u00e1s Maduro, provocando uma mudan\u00e7a de regime. A opera\u00e7\u00e3o envolveu cerca de 60 homens, incluindo ex-militares venezuelanos e norte-americanos.<\/p>\n<p>A opera\u00e7\u00e3o fracassou gra\u00e7as \u00e0 a\u00e7\u00e3o r\u00e1pida dos civis e militares venezuelanos, que colaboraram em um plano para interceptar os invasores logo ap\u00f3s o desembarque. Oito mercen\u00e1rios foram mortos e 17 foram capturados.<\/p>\n<h3>Maduro na mira<\/h3>\n<p>Desde a morte de Hugo Ch\u00e1vez em 2013, o governo venezuelano passou a enfrentar uma mobiliza\u00e7\u00e3o golpista cada vez mais violenta, conduzida pela extrema-direita venezuelana em conluio com agentes externos, sobretudo da Col\u00f4mbia e dos Estados Unidos.<\/p>\n<p>Vislumbrando a hip\u00f3tese de enfraquecimento do projeto pol\u00edtico bolivariano, os setores reacion\u00e1rios lan\u00e7aram uma campanha contestando a legitimidade do sucessor de Ch\u00e1vez, Nicol\u00e1s Maduro. O primeiro grande cap\u00edtulo dessa ofensiva foi o movimento \u201cLa Salida\u201d (2013-2014), liderado por Henrique Capriles, Mar\u00eda Corina Machado e Leopoldo L\u00f3pez \u2014 todos envolvidos em uma tentativa de golpe contra Hugo Ch\u00e1vez em 2002.<\/p>\n<p>Sob uma ret\u00f3rica inflamada acusando Maduro de cometer \u201cfraude eleitoral\u201d, a oposi\u00e7\u00e3o convocou protestos conhecidos como \u201cguarimbas\u201d, que se transformaram em motins violentos, com apedrejamentos, saques, inc\u00eandios e ataques contra instala\u00e7\u00f5es p\u00fablicas e privadas. Os protestos deixaram um saldo de 43 mortes e mais de 500 feridos.<\/p>\n<p>Em fevereiro de 2015, oficiais da Aeron\u00e1utica lan\u00e7aram uma nova opera\u00e7\u00e3o contra Maduro, batizada de \u201cGolpe Azul\u201d. O plano envolvia o sequestro de aeronaves e o bombardeio de alvos estrat\u00e9gicos como o Pal\u00e1cio de Miraflores, o Minist\u00e9rio da Defesa, o Minist\u00e9rio P\u00fablico, o Tribunal Supremo e a Telesur. O Servi\u00e7o Nacional de Intelig\u00eancia conseguiu desarticular o plano a tempo e apontou ind\u00edcios de envolvimento da CIA. Oito pessoas foram presas, incluindo o prefeito de Caracas, Antonio Ledezma.<\/p>\n<p>Em 2016, foi a vez da \u201cOpera\u00e7\u00e3o Espada de Deus\u201d, idealizada pelos generais \u00c1ngel Vivas e Ra\u00fal Baduel. Os golpistas pretendiam assassinar Maduro, mas a trama foi neutralizada gra\u00e7as \u00e0 dela\u00e7\u00e3o e infiltra\u00e7\u00e3o de agentes. No ano seguinte, ocorreram mais duas tentativas de golpe, envolvendo o roubo de armamentos e muni\u00e7\u00f5es: a \u201cOpera\u00e7\u00e3o Escudo Zamorano\u201d e a \u201cOpera\u00e7\u00e3o David\u201d. Mais de 500 fuzis, lan\u00e7adores de granadas e armas foram roubados de arsenais do governo venezuelano.<\/p>\n<p>Ainda em 2017, um grupo de militares insurgentes liderado por \u00d3scar P\u00e9rez sequestrou um helic\u00f3ptero de combate e atacou o Tribunal Supremo de Justi\u00e7a. P\u00e9rez ainda lideraria a \u201cOpera\u00e7\u00e3o G\u00eanesis\u201d, atacando um posto da Guarda Nacional em Miranda. Ele foi morto em janeiro de 2018 durante opera\u00e7\u00e3o de captura.<\/p>\n<p>Uma nova tentativa de assassinato contra Maduro foi levada a cabo em agosto de 2018. Durante uma cerim\u00f4nia da Guarda Nacional Bolivariana, drones carregados de explosivos foram direcionados contra Maduro, seus ministros e o alto comando militar. O ataque foi neutralizado pelas for\u00e7as de seguran\u00e7a. Ainda naquele ano, o governo venezuelano desmantelou mais dois planos golpistas \u2014 um interno, liderado pelo general Miguel Rodr\u00edguez Torres, e outro planejado na Col\u00f4mbia pelo general Oswaldo Garc\u00eda Palomo.<\/p>\n<h3>Juan Guaid\u00f3<\/h3>\n<p>Maduro foi reeleito presidente da Venezuela em maio de 2018, com mais de 6,2 milh\u00f5es de votos. A elei\u00e7\u00e3o foi boicotada pela maioria dos candidatos de oposi\u00e7\u00e3o, que protestaram contra a impugna\u00e7\u00e3o de candidaturas pela justi\u00e7a eleitoral.<\/p>\n<p>Os governos dos Estados Unidos, da Uni\u00e3o Europeia e de pa\u00edses latino-americanos governados pela direita se recusaram a reconhecer a legitimidade do pleito. A Casa Branca e o Parlamento Europeu impuseram novas san\u00e7\u00f5es contra o governo venezuelano, agravando a crise econ\u00f4mica do pa\u00eds.<\/p>\n<p>A contesta\u00e7\u00e3o da elei\u00e7\u00e3o abriu caminho para a escalada golpista. Em janeiro de 2019, Juan Guaid\u00f3, presidente da Assembleia Nacional, se autoproclamou \u201cpresidente interino\u201d da Venezuela. Ele foi imediatamente reconhecido pelo governo norte-americano, fomentando novas conspira\u00e7\u00f5es, divis\u00f5es nas For\u00e7as Armadas e protestos violentos.<\/p>\n<p>Em abril de 2019, Guaid\u00f3 e Leopoldo L\u00f3pez lideraram a \u201cOpera\u00e7\u00e3o Liberdade\u201d, que preconizava a tomada da Base A\u00e9rea de La Carlota e a subsequente derrubada do governo de Maduro. Mais duas tentativas golpistas foram neutralizadas em junho (\u201cOpera\u00e7\u00e3o Vuelvan Caras\u201d) e agosto (\u201cOpera\u00e7\u00e3o For\u00e7a e Liberdade\u201d).<\/p>\n<figure aria-describedby=\"caption-attachment-253755\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\"src=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/05\/960px-operacion_gedeon_2020_-_arrests.png\" alt=\"\" width=\"960\" height=\"537\" srcset=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/05\/960px-operacion_gedeon_2020_-_arrests.png 960w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/05\/960px-operacion_gedeon_2020_-_arrests-300x168.png 300w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/05\/960px-operacion_gedeon_2020_-_arrests-768x430.png 768w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/05\/960px-operacion_gedeon_2020_-_arrests-150x84.png 150w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/05\/960px-operacion_gedeon_2020_-_arrests-750x420.png 750w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\"><figcaption>Policiais venezuelanos prendem mercen\u00e1rios da Silvercorp <br \/>Via Wikimedia Commons<\/figcaption><\/figure>\n<h3>Opera\u00e7\u00e3o Gide\u00e3o<\/h3>\n<p>Em 2020, a Venezuela testemunharia a mais ousada tentativa de golpe contra o governo de Nicol\u00e1s Maduro at\u00e9 ent\u00e3o: a Opera\u00e7\u00e3o Gide\u00e3o. O ataque foi coordenado por Jordan Goudreau \u2014 um mercen\u00e1rio canadense-americano que atuou nas guerras do Iraque e do Afeganist\u00e3o, respons\u00e1vel por fundar a Silvercorp em 2018.<\/p>\n<p>Sediada em Miami, a Silvercorp \u00e9 um ex\u00e9rcito privado de aluguel ativa nos Estados Unidos, em Porto Rico e na Col\u00f4mbia. A empresa foi contratada pelo governo dos Estados Unidos para prestar servi\u00e7os de seguran\u00e7a para Donald Trump.<\/p>\n<p>A opera\u00e7\u00e3o ocorreu poucas semanas depois de Donald Trump oferecer uma recompensa de 15 milh\u00f5es de d\u00f3lares para quem prendesse Maduro e altos burocratas do governo venezuelano, acusados de suposto envolvimento com o \u201cCartel dos S\u00f3is\u201d.<\/p>\n<p>Ap\u00f3s o ataque, um documento descrevendo o objetivo da opera\u00e7\u00e3o, firmado pela Silvercorp e por um membro do Comit\u00ea de Estrat\u00e9gia de Juan Guaid\u00f3 chamado Juan Jos\u00e9 Rend\u00f3n, veio a p\u00fablico. O documento detalhava poss\u00edveis cen\u00e1rios e planos para remover Maduro do poder e instalar Guaid\u00f3 como presidente.<\/p>\n<p>No dia 4 de maio de 2020, 60 mercen\u00e1rios da Silvercorp, divididos em duas lanchas, zarparam da Col\u00f4mbia rumo \u00e0 costa venezuelana. Uma das lanchas desembarcaria no vilarejo de Chuao, estado de Ar\u00e1gua, e a outra em Macuto, em La Guaira.<\/p>\n<p>O plano dos mercen\u00e1rios consistia em duas opera\u00e7\u00f5es paralelas. Um grupo tomaria o controle de instala\u00e7\u00f5es estrat\u00e9gicas, incluindo o Aeroporto Internacional Sim\u00f3n Bol\u00edvar, em Maiquetia, enquanto um segundo grupo seguiria para o Pal\u00e1cio de Miraflores, sede do poder executivo venezuelano, para sequestrar ou matar Nicol\u00e1s Maduro e a c\u00fapula do governo.<\/p>\n<p>Os mercen\u00e1rios eram boinas-verdes (i.e., ex-combatentes das For\u00e7as Especiais do Ex\u00e9rcito dos Estados Unidos) e desertores das For\u00e7as Armadas Nacionais Bolivarianas.<\/p>\n<p>Antes mesmo que desembarcassem, os mercen\u00e1rios foram descobertos. Pescadores venezuelanos avistaram as embarca\u00e7\u00f5es e alertaram as autoridades. Com o apoio de cinco policiais do vilarejo e a ajuda de um helic\u00f3ptero militar, os pescadores arquitetaram um plano de defesa na praia.<\/p>\n<p>Oito mercen\u00e1rios foram mortos na opera\u00e7\u00e3o e outros 17 invasores foram capturados \u2014 incluindo dois \u201cboinas verdes\u201d norte-americanos, Airan Berry e Luke Denman. Os mercen\u00e1rios foram amarrados com linhas e cordas dos pescadores e rendidos deitados de frente para o ch\u00e3o at\u00e9 a chegada das For\u00e7as Armadas Nacionais Bolivarianas junto \u00e0 \u201cCasa do Pescador Socialista\u201d, uma associa\u00e7\u00e3o sindical cuja sede \u00e9 decorada com os rostos de personagens hist\u00f3ricos venezuelanos: Sim\u00f3n Bol\u00edvar, Francisco de Miranda, Ezequiel Zamora e Hugo Ch\u00e1vez.<\/p>\n<p>Outros mercen\u00e1rios que escaparam da a\u00e7\u00e3o em Chuao foram presos nos dias seguintes, na cidade de Cepe e em outras localidades vizinhas, elevando o total de suspeitos detidos para mais de 40.<\/p>\n<p>Assim como no caso dos pescadores de Chuao, em todas essas pris\u00f5es houve participa\u00e7\u00e3o de civis que haviam passado por treinamentos militares administrados pela Mil\u00edcia Nacional Bolivariana \u2014 um corpo de seguran\u00e7a que conforma um ex\u00e9rcito popular de civis com conhecimentos de t\u00e9cnicas militares, abrangendo cerca de quatro milh\u00f5es de cidad\u00e3os.<\/p>\n<p>Donald Trump negou veementemente qualquer envolvimento com a opera\u00e7\u00e3o e afirmou que n\u00e3o possu\u00eda sequer conhecimento pr\u00e9vio sobre o ataque. Seis anos depois, no entanto, uma nova invas\u00e3o, dessa vez executada por for\u00e7as militares dos Estados Unidos sob ordens diretas de Trump, logrou atingir o objetivo que a Silvercorp n\u00e3o conseguiu concretizar, capturando Nicol\u00e1s Maduro e o conduzindo at\u00e9 os Estados Unidos para responder a acusa\u00e7\u00f5es forjadas de envolvimento com o narcoterrorismo.<\/p>\n<p>O post Um golpe privado: mercen\u00e1rios da Silvercorp invadem a Venezuela apareceu primeiro em Opera Mundi.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/trump-cancela-financiamento-a-universidade-de-columbia-em-represalia-aos-protestos-pro-palestina\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/03\/gzukfpzxqaahuv9-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Trump cancela financiamento \u00e0 Universidade de Colu...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/sul21.com.br\/noticias\/geral\/2025\/08\/justica-determina-que-brf-garanta-privacidade-de-trabalhadores-durante-troca-de-uniformes-em-marau\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Justi\u00e7a determina que BRF garanta privacidade de t...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/lula-envia-video-a-trump-semear-comida-e-nao-o-odio\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/08\/lula-brasil-soberano-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Lula envia v\u00eddeo a Trump: \u201csemear comida e n\u00e3o o \u00f3...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/depoimento-de-general-confirma-atuacao-de-bolsonaro-para-viabilizar-golpe\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/05\/bolsonaro-e-militares_Isac-Nobrega_Presidencia-da-Republica-notice--150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Depoimento de general confirma atua\u00e7\u00e3o de Bolsonar...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>H\u00e1 seis anos, em 4 de maio de 2020, a Venezuela era alvo de uma tentativa frustrada de invas\u00e3o organizada por mercen\u00e1rios ligados \u00e0 Silvercorp, uma empresa de seguran\u00e7a privada dos Estados Unidos. Batizada de \u201cOpera\u00e7\u00e3o Gide\u00e3o\u201d, a ofensiva tinha como objetivo derrubar o presidente Nicol\u00e1s Maduro, provocando uma mudan\u00e7a de regime. A opera\u00e7\u00e3o envolveu [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/operamundi.uol.com.br\/pensar-a-historia\/um-golpe-privado-mercenarios-da-silvercorp-invadem-a-venezuela\/\">Um golpe privado: mercen\u00e1rios da Silvercorp invadem a Venezuela<\/a> apareceu primeiro em <a href=\"https:\/\/operamundi.uol.com.br\/\">Opera Mundi<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":86021,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[9,1797,2129,2328,54450,5622],"tags":[],"class_list":["post-86020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eua","category-golpe","category-golpe-de-estado","category-nicolas-maduro","category-operacao-armada","category-pensar-a-historia"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/86020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=86020"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/86020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media\/86021"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=86020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=86020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=86020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}