{"id":86145,"date":"2026-05-05T20:28:02","date_gmt":"2026-05-05T23:28:02","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/pt-fala-em-acordao-e-leva-ao-stf-lei-que-reduz-pena-de-bolsonaro-em-ate-70\/"},"modified":"2026-05-05T20:28:02","modified_gmt":"2026-05-05T23:28:02","slug":"pt-fala-em-acordao-e-leva-ao-stf-lei-que-reduz-pena-de-bolsonaro-em-ate-70","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/pt-fala-em-acordao-e-leva-ao-stf-lei-que-reduz-pena-de-bolsonaro-em-ate-70\/","title":{"rendered":"PT fala em \u201cacord\u00e3o\u201d e leva ao STF lei que reduz pena de Bolsonaro em at\u00e9 70%"},"content":{"rendered":"<p>L\u00edder da legenda na C\u00e2mara, Pedro Uczai afirma que a\u00e7\u00e3o contra nova dosimetria exp\u00f5e manobra de Davi Alcolumbre e barganha envolvendo a CPI do Banco Master<\/p>\n<p>O post PT fala em \u201cacord\u00e3o\u201d e leva ao STF lei que reduz pena de Bolsonaro em at\u00e9 70% apareceu primeiro em Urbs Magna.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/atingidos-pela-crise-climatica-no-rj-exigem-politica-estadual-do-governador-claudio-castro-pl\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Atingidos pela crise clim\u00e1tica no RJ exigem pol\u00edti...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/quatro-obras-de-luis-fernando-verissimo-que-enfrentaram-a-ditadura-civil-militar\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/08\/reporucao-rede-sociais-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Quatro obras de Luis Fernando Ver\u00edssimo que enfren...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/trabalhadores-dos-eua-protestam-contra-autoritarismo-de-donald-trump\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/AFP__20251018__79A76HU__v1__HighRes__UsPoliticsProtest-scaled-960x540-1-150x150.webp') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Trabalhadores dos EUA protestam contra autoritaris...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/mais-de-500-mil-cubanos-marcham-em-havana-pelo-fim-do-bloqueio-dos-eua\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2024\/12\/GfSbeLuW4AA-4LW-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Mais de 500 mil cubanos marcham em Havana pelo fim...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>L\u00edder da legenda na C\u00e2mara, Pedro Uczai afirma que a\u00e7\u00e3o contra nova dosimetria exp\u00f5e manobra de Davi Alcolumbre e barganha envolvendo a CPI do Banco Master<\/p>\n<p>O post <a rel=\"nofollow\" href=\"https:\/\/urbsmagna.com\/pt-stf-reducao-pena-bolsonaro-acordao-dosimetria\/\">PT fala em \u201cacord\u00e3o\u201d e leva ao STF lei que reduz pena de Bolsonaro em at\u00e9 70%<\/a> apareceu primeiro em <a rel=\"nofollow\" href=\"https:\/\/urbsmagna.com\/\">Urbs Magna<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[1269,54830,45,388,38499,3324,54831,53174,1760,17,288,53361,28337,191,42460,132,5471,54832,54833,7236],"tags":[],"class_list":["post-86145","post","type-post","status-publish","format-standard","hentry","category-8-de-janeiro","category-acordao-congresso","category-brasil","category-congresso-nacional","category-cpi-do-banco-master","category-davi-alcolumbre","category-derrubada-de-veto-lula","category-dosimetria-da-pena","category-eleicoes-2026","category-governo-lula","category-justica","category-justica-democracia","category-lei-antifaccao","category-noticias","category-pedro-uczai","category-politica","category-politica-nacional","category-pt-no-stf","category-reducao-de-pena-bolsonaro","category-supremo-tribunal-federal"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/86145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=86145"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/86145\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=86145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=86145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=86145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}