{"id":87081,"date":"2026-05-13T15:31:58","date_gmt":"2026-05-13T18:31:58","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/cuba-venezuela-e-ira-sao-temas-do-janela-internacional\/"},"modified":"2026-05-13T15:31:58","modified_gmt":"2026-05-13T18:31:58","slug":"cuba-venezuela-e-ira-sao-temas-do-janela-internacional","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/cuba-venezuela-e-ira-sao-temas-do-janela-internacional\/","title":{"rendered":"Cuba, Venezuela e Ir\u00e3 s\u00e3o temas do Janela Internacional"},"content":{"rendered":"<p>A edi\u00e7\u00e3o do Janela Internacional que estreou em 13 de maio analisa o agravamento da press\u00e3o dos Estados Unidos contra Cuba ap\u00f3s novas san\u00e7\u00f5es anunciadas pelo governo Donald Trump. O programa discute os impactos do bloqueio econ\u00f4mico e energ\u00e9tico sobre a popula\u00e7\u00e3o cubana, denunciados por especialistas da ONU como uma forma de \u201cfome de energia\u201d, al\u00e9m da crise humanit\u00e1ria provocada pela escassez de combust\u00edvel, medicamentos e servi\u00e7os essenciais na ilha. <\/p>\n<p>Na sequ\u00eancia, o epis\u00f3dio aborda a disputa territorial entre Venezuela e Guiana pela regi\u00e3o do Essequibo, marcada pela presen\u00e7a de reservas estrat\u00e9gicas de petr\u00f3leo e pela atua\u00e7\u00e3o da ExxonMobil. O programa acompanha a ida de Delcy Rodr\u00edguez \u00e0 Corte Internacional de Justi\u00e7a, em Haia, e discute o peso geopol\u00edtico da disputa na Am\u00e9rica do Sul.<\/p>\n<p>Nos Estados Unidos, a edi\u00e7\u00e3o analisa a nova estrat\u00e9gia antiterrorismo anunciada pela Casa Branca, que amplia o foco sobre movimentos sociais e organiza\u00e7\u00f5es classificadas como \u201camea\u00e7as internas\u201d, al\u00e9m da tentativa de enquadrar o PCC e o Comando Vermelho como organiza\u00e7\u00f5es terroristas estrangeiras. <\/p>\n<p>O epis\u00f3dio tamb\u00e9m discute a rea\u00e7\u00e3o de parlamentares democratas, que alertam para os riscos de militariza\u00e7\u00e3o e inger\u00eancia na Am\u00e9rica Latina. O programa examina ainda as tens\u00f5es entre Donald Trump e o Papa Le\u00e3o XIV, ap\u00f3s cr\u00edticas do pont\u00edfice \u00e0 guerra no Oriente M\u00e9dio e \u00e0s amea\u00e7as contra o Ir\u00e3. <\/p>\n<p>Assista, inscreva-se no\u00a0<a href=\"https:\/\/www.youtube.com\/@FundacaoPerseuAbramo\/featured\" target=\"_blank\" rel=\"noreferrer noopener\">canal,<\/a>\u00a0deixe seu like e compartilhe para fortalecer o debate cr\u00edtico sobre soberania, imperialismo, democracia e geopol\u00edtica.<\/p>\n<figure>\n<div>\n<\/div>\n<\/figure>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/entorno-digital-nao-e-democratico-alertam-janja-e-ministra-da-juventude-e-da-infancia-da-espanha\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">\u201cEntorno digital n\u00e3o \u00e9 democr\u00e1tico\u201d, alertam Janja...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/jesse-souza-vira-alvo-do-mpf-apos-fala-considera-antissemita\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Jess\u00e9 Souza vira alvo do MPF ap\u00f3s fala considera a...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/pf-ameaca-suspender-emissao-de-passaportes-em-novembro-por-falta-de-verba\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/10\/passaporte-brasileiro_mcamgo_abr_140220221818-3-150x150.webp') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">PF amea\u00e7a suspender emiss\u00e3o de passaportes em nove...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/a-nova-idade-das-trevas-comeca-em-israel\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/05\/Sem-titulo-12-1024x565-1-150x150.jpeg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">A nova Idade das Trevas come\u00e7a em Israel<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>A edi\u00e7\u00e3o do Janela Internacional que estreou em 13 de maio analisa o agravamento da press\u00e3o dos Estados Unidos contra Cuba ap\u00f3s novas san\u00e7\u00f5es anunciadas pelo governo Donald Trump. O programa discute os impactos do bloqueio econ\u00f4mico e energ\u00e9tico sobre a popula\u00e7\u00e3o cubana, denunciados por especialistas da ONU como uma forma de \u201cfome de energia\u201d, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[8620],"tags":[],"class_list":["post-87081","post","type-post","status-publish","format-standard","hentry","category-noticia"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/87081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=87081"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/87081\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=87081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=87081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=87081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}