{"id":88160,"date":"2026-05-21T18:27:42","date_gmt":"2026-05-21T21:27:42","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/festa-de-aniversario-do-marx-reune-debates-e-feira-de-livros-em-sao-paulo\/"},"modified":"2026-05-21T18:27:42","modified_gmt":"2026-05-21T21:27:42","slug":"festa-de-aniversario-do-marx-reune-debates-e-feira-de-livros-em-sao-paulo","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/festa-de-aniversario-do-marx-reune-debates-e-feira-de-livros-em-sao-paulo\/","title":{"rendered":"Festa de Anivers\u00e1rio do Marx re\u00fane debates e feira de livros em S\u00e3o Paulo"},"content":{"rendered":"<p>A tradicional Festa de Anivers\u00e1rio do Marx chega a S\u00e3o Paulo neste s\u00e1bado (23) para celebrar os 208 anos de nascimento do pensador alem\u00e3o. Organizado pela editora Boitempo em parceria com o Movimento dos Trabalhadores Rurais Sem Terra (MST), o evento gratuito ocorrer\u00e1 a partir das 10h no Espa\u00e7o Cultural Elza Soares, localizado no bairro [\u2026]<\/p>\n<p><a href=\"https:\/\/www.brasildefato.com.br\/2026\/05\/21\/festa-de-aniversario-do-marx-reune-debates-e-feira-de-livros-em-sao-paulo\/\" rel=\"nofollow\">Fonte<\/a><\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/sebastiao-salgado-e-a-heranca-do-humanismo-militante\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/05\/whatsapp-image-2025-05-25-at-115509-150x150.jpeg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Sebasti\u00e3o Salgado e a heran\u00e7a do humanismo militan...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/trump-nao-e-imperador-do-mundo-e-soberania-brasileira-e-do-povo-diz-lula\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/07\/Captura-de-Tela-2025-07-24-as-153308-150x150.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Trump n\u00e3o \u00e9 imperador do mundo e soberania brasile...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/jandira-feghali-ve-dificuldades-para-projeto-da-anistia-avancar-na-camara\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/04\/Jandira-Feghali-audiovisual-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Jandira Feghali v\u00ea dificuldades para projeto da an...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/cuba-termina-um-novo-ano-sem-conseguir-sair-de-sua-longa-crise\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Cuba termina um novo ano sem conseguir sair de sua...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>A tradicional Festa de Anivers\u00e1rio do Marx chega a S\u00e3o Paulo neste s\u00e1bado (23) para celebrar os 208 anos de nascimento do pensador alem\u00e3o. Organizado pela editora Boitempo em parceria com o Movimento dos Trabalhadores Rurais Sem Terra (MST), o evento gratuito ocorrer\u00e1 a partir das 10h no Espa\u00e7o Cultural Elza Soares, localizado no bairro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[306,1960,41367,41016,59913,309,25187,59914,59915,2416,6874,423,1819,54293,9533,59916,1312,59917,2026,59918,59919,35762,1689,302,59920,29,59921,4141,59922],"tags":[],"class_list":["post-88160","post","type-post","status-publish","format-standard","hentry","category-agroecologia","category-armazem-do-campo","category-boitempo","category-capitalismo-racial","category-classicos-do-marxismo","category-cultura","category-debates","category-disputa-eleitoral-2026","category-editoras-independentes","category-espaco-cultural-elza-soares","category-esquerda-brasileira","category-extrema-direita","category-fascismo","category-feira-de-livros","category-feminismo-marxista","category-festa-de-aniversario-do-marx","category-geopolitica","category-intelectuais-brasileiros","category-karl-marx","category-leopoldina-fortunati","category-lutas-anti-imperialistas","category-marilena-chaui","category-movimentos-sociais","category-mst","category-programacao-infantil","category-sao-paulo","category-solidariedade-sul-global","category-trabalho-domestico","category-trabalho-e-questao-racial"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/88160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=88160"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/88160\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=88160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=88160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=88160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}