{"id":88216,"date":"2026-05-21T18:01:07","date_gmt":"2026-05-21T21:01:07","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/o-paradoxo-de-ormuz\/"},"modified":"2026-05-21T18:01:07","modified_gmt":"2026-05-21T21:01:07","slug":"o-paradoxo-de-ormuz","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/o-paradoxo-de-ormuz\/","title":{"rendered":"O paradoxo de Ormuz"},"content":{"rendered":"<figure><figcaption>Cr\u00e9dito: REUTERS<\/figcaption><\/figure>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<h4>Boletim Outras Palavras<\/h4>\n<p>Receba por email, diariamente, todas as publica\u00e7\u00f5es do site<\/p>\n<\/p><\/div>\n<div>\n<div>\n<div>\n<div>\n<div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n                <button type=\"submit\">Assinar<\/button><br \/>\n                <button disabled type=\"button\"> <\/p>\n<div><\/div>\n<p> <span>Loading&#8230;<\/span> <\/button>\n              <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n            <button type=\"submit\">Assinar<\/button><br \/>\n            <button disabled type=\"button\"> <\/p>\n<div><\/div>\n<p> <span>Loading&#8230;<\/span> <\/button>\n          <\/div>\n<\/p><\/div>\n<div>\n<div>\n<h4>Agradecemos!<\/h4>\n<p>Voc\u00ea j\u00e1 est\u00e1 inscrito e come\u00e7ar\u00e1 a receber os boletins em breve. Boa leitura!<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<p><imgsrc=\"\" width=\"1\" height=\"1\" alt=\".\" border=\"0\">\n<\/div>\n<\/div>\n<p><strong>MAIS<\/strong>:<br \/>O texto a seguir integra o n\u00famero 17 (maio de 2026) do boletim do <strong>Observat\u00f3rio do S\u00e9culo XXI, <\/strong>parceiro editorial de <em>Outras Palavras.<\/em><\/p>\n<p>Fazem tr\u00eas d\u00e9cadas, pelo menos, que Benjamin Netanyahu conspira continuamente para convencer o governo norte-americano a participar de um ataque conjunto, massivo, rel\u00e2mpago, e devastador, contra o Ir\u00e3. E acabou conseguindo persuadir o presidente Donald Trump de que obteria uma vit\u00f3ria r\u00e1pida e uma mudan\u00e7a quase instant\u00e2nea do regime iraniano depois que a avia\u00e7\u00e3o israelense assassinasse \u2013 nos primeiros minutos do combate \u2013 as principais lideran\u00e7as religiosas, civis e militares do povo persa. Promovendo a instala\u00e7\u00e3o de um governo t\u00edtere que destru\u00edsse o programa nuclear e o sistema de defesa bal\u00edstico iraniano, e que suspendesse seu apoio ao \u201ceixo da resist\u00eancia\u201d \u00e0 Israel, no L\u00edbano, no Iraque e no Yemen.<\/p>\n<p>Mas nada disto aconteceu depois do ataque surpresa do dia 28 de fevereiro de 2026.. Pelo contr\u00e1rio, passados quase tr\u00eas meses do in\u00edcio do conflito, pode-se dizer \u2013 do ponto de vista dos objetivos declarados pelas pot\u00eancias agressoras \u2013 que Israel e Estados Unidos sofreram uma grande derrota estrat\u00e9gica. As autoridades assassinadas foram substitu\u00eddas rapidamente, o programa nuclear iraniano n\u00e3o foi desativado, seu sistema de produ\u00e7\u00e3o e defesa bal\u00edstico n\u00e3o foi destru\u00eddo, as suas reservas de uranio enriquecido n\u00e3o foram localizadas, e o Ir\u00e3 segue apoiando seus aliados do \u201ceixo da resist\u00eancia\u201d. Al\u00e9m disto, os m\u00edsseis e drones iranianos atingiram, destru\u00edram ou danificaram pesadamente todas as bases americanas ao redor do Golfo P\u00e9rsico, al\u00e9m de terem \u201cvazado\u201d o sistema de defesa a\u00e9rea de Israel \u2013 o Iron Dome, que era considerado indevass\u00e1vel.<\/p>\n<div>\n<div><imgsrc=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/05\/14--37.png\" alt=\"\" srcset=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/05\/14--37.png 680w, https:\/\/estaticos.opara.me\/outraspalavras\/uploads\/2025\/12\/04164350\/14-1-300x110.png 300w\" sizes=\"(max-width: 680px) 100vw, 680px\" width=\"680\" height=\"250\"><\/div>\n<\/div>\n<p>Por outro lado. apesar do bombardeio, massivo e cont\u00ednuo do territ\u00f3rio iraniano, durante mais de um m\u00eas de combate o Ir\u00e3 ainda mant\u00e9m \u2013 segundo a intelig\u00eancia americana \u2013 70% de seus lan\u00e7adores m\u00f3veis em todo o pa\u00eds, e conserva cerca de 70% do seu arsenal do pr\u00e9-guerra. E al\u00e9m disto, conseguiu restabelecer o acesso operacional de 30 de seus 33 locais de m\u00edsseis ao longo do Estreito de Ormuz, tendo recuperado o acesso a 90% de suas instala\u00e7\u00f5es militares subterr\u00e2neas. E apesar da destrui\u00e7\u00e3o causada pelos bombardeios, o Ir\u00e3 conquistou uma vit\u00f3ria extraordin\u00e1ria ao assumir o controle militar e a soberania econ\u00f4mica sobre o Estreito de Ormuz. Por tudo isto, os norte-americanos, mais do que os israelenses, encontram-se neste momento num \u201cbeco sem sa\u00edda\u201d, sem o apoio de sua pr\u00f3pria popula\u00e7\u00e3o e divididos entre a alternativa de prosseguir indefinidamente uma guerra impopular, ou aceitar uma retirada e um acordo de paz que eles consideram humilhante. Uma posi\u00e7\u00e3o estrat\u00e9gica extremamente desconfort\u00e1vel, agravada pelo fato que neste momento \u00e9 o Ir\u00e3 que est\u00e1 \u201cdando as cartas\u201d nas negocia\u00e7\u00f5es de paz intermediadas pelo Paquist\u00e3o, e sustentadas pela China.<\/p>\n<p>Neste momento paira no ar uma enorme incerteza com rela\u00e7\u00e3o ao desfecho desse conflito, mas o mais prov\u00e1vel \u00e9 que a guerra prossiga por tempo indeterminado. Assim mesmo, o terremoto mundial provocado pela vit\u00f3ria estrat\u00e9gica do Ira, e sobretudo pelo seu controle do Estreito de Ormuz, produziu tr\u00eas sequelas, pelo menos, que j\u00e1 s\u00e3o irrevers\u00edveis. A primeira, \u00e9 que ficaram expl\u00edcitos os limites do poder militar norte-americano, mesmo no caso de uma guerra assim\u00e9trica, o que atinge em cheio o projeto de supremacia militar global de Donald Trump. A segunda, \u00e9 que Israel perdeu a aura de sua invencibilidade, depois que sua estrat\u00e9gia dos assassinatos seletivos fracassou, e depois que seu sistema de defesa foi vazado, e depois que suas bases militares foram atingidas, dentro do pr\u00f3prio territ\u00f3rio israelense. E a terceira \u00e9 que o Ir\u00e3 j\u00e1 conquistou uma nova posi\u00e7\u00e3o hier\u00e1rquica dentro do mapa geopol\u00edtico do Oriente M\u00e9dio que nascer\u00e1 desta guerra, com rela\u00e7\u00e3o aos pa\u00edses \u00e1rabes, e com rela\u00e7\u00e3o a Israel.<\/p>\n<p>Mais al\u00e9m destas consequ\u00eancias imediatas, os efeitos em cadeia desse grande erro estrat\u00e9gico norte-americano foram bem al\u00e9m do Oriente M\u00e9dio. Parece n\u00e3o haver d\u00favida, por exemplo, que cresceu em todo mundo a desconfian\u00e7a dos pa\u00edses que dependem da \u201cprote\u00e7\u00e3o militar\u2019 dos EUA, como \u00e9 o caso exemplar de Taiwan. Haja vista que durante a guerra, a l\u00edder do principal partido de oposi\u00e7\u00e3o de Taiwan, (o partido nacionalista Kuomitang (KMT) fundado por Sun Yat-sen, em 1912) a senhora Cheng Li-Un fez uma visita oficial de cinco dias \u2013 absolutamente inusitada \u2013 \u00e0 Pequin onde discutiu pessoalmente com o presidente Xi Jinping a possibilidade de uma reaproxima\u00e7\u00e3o pac\u00edfica entre o continente chin\u00eas e sua \u201cilha rebelde\u201d. Um acontecimento dif\u00edcil de ser imaginado sem ter em conta a fragiliza\u00e7\u00e3o americana frente aos seus \u201cprotetorados militares\u201d.<\/p>\n<p>E o mesmo pode ser dito com rela\u00e7\u00e3o \u00e0 posi\u00e7\u00e3o do presidente Donald Trump, durante sua visita oficial de dois dias \u00e0 Pequim, quando foi obrigado a tratar a China de igual para igual e teve que ouvir em silencio a amea\u00e7a do presidente Xi Jinping de que haver\u00e1 guerra se os EUA intervierem a favor da independ\u00eancia de Taiwan. Neste sentido, n\u00e3o h\u00e1 d\u00favida que a impot\u00eancia dos EUA frente ao fechamento iraniano do Estreito de Ormuz acelerou o processo em curso de deslocamento do centro do poder pol\u00edtico e econ\u00f4mico do Sistema Mundial, na dire\u00e7\u00e3o da \u00c1sia, em particular na dire\u00e7\u00e3o da China.<\/p>\n<p>Mas isto n\u00e3o significa, de forma alguma, o fim do \u201cpoder americano\u201d, nem muito menos que os EUA deixar\u00e3o de ser uma grande pot\u00eancia durante o S\u00e9culo XXI. Mesmo derrotados no Vietn\u00e3, no Afeganist\u00e3o e agora no Ir\u00e3, os EUA mant\u00eam sua capacidade global de atacar, punir e destruir seus \u201cdesafetos\u201d, e isto lhe assegura lugar central dentro da ordem multipolar que estar\u00e1 sendo constru\u00edda ao longo deste novo s\u00e9culo. Al\u00e9m disto, apesar do panorama geral ser extremamente sombrio, n\u00e3o \u00e9 imposs\u00edvel que as negocia\u00e7\u00f5es em torno \u00e0 \u201cPaz de Ormuz\u201d possam se transformar na primeira grande negocia\u00e7\u00e3o da nova era multipolar do sistema mundial.<\/p>\n<p>Neste ponto n\u00e3o cabe d\u00favida sobre a posi\u00e7\u00e3o belicista dos europeus que se preparam atualmente para uma grande guerra contra a R\u00fassia. E n\u00e3o se deve esperar que Israel abdique de sua estrat\u00e9gia de \u201cguerra permanente\u2019 contra os povos isl\u00e2micos e contra o Ir\u00e3 em particular. E portanto, todas a quest\u00e3o \u00e9 saber se os EUA acabar\u00e3o aceitando sua nova posi\u00e7\u00e3o como uma entre outras potencias equivalentes. E neste ponto, apesar de todos os sinais contr\u00e1rios, Donald Trump talvez ainda seja o l\u00edder norte-americano com maior possibilidade de dar este passo rumo a um novo equil\u00edbrio mundo de poder. Neste momento, o Partido Democrata est\u00e1 sem nenhum projeto alternativo, e se voltarem, ao poder o mais prov\u00e1vel \u00e9 que se alinhem com os europeus numa guerra geral com os russos. E dentro do Partido Republicano, se Donald Trump for sucedido por David Vance ou por Marco Rubio, o que se deve esperar \u00e9 um a estrat\u00e9gia internacional igualmente agressiva e baseada na for\u00e7a, mas complementada por uma vis\u00e3o ideol\u00f3gico-religiosa fundamentalista de defesa da civiliza\u00e7\u00e3o ocidental, branca e crist\u00e3, e de promo\u00e7\u00e3o de uma \u201cguerra entre civiliza\u00e7\u00f5es\u201d, como foi antecipado por Samuel Huntington, na d\u00e9cada de 90 do s\u00e9culo passado, e que agora aparece defendida de forma expl\u00edcita, no manifesto de 22 pontos publicado no jornal New York Times, no dia 18 de abril de 2026, por Alex Karp, CEO da Empresa Palantir, estreitamente associada ao Pent\u00e1gono e muito pr\u00f3xima do vice-presidente norte- americano, e David Vence.<\/p>\n<p>Neste contexto, paradoxalmente o realismo pragm\u00e1tico, quase c\u00ednico e sem pretens\u00f5es catequ\u00e9ticas, pr\u00f3prias de um jogador e negocista, admirador da for\u00e7a e do dinheiro representa uma rara \u201cjanela de oportunidade\u201d (por curto espa\u00e7o de tempo), para uma negocia\u00e7\u00e3o com a China e com a R\u00fassia, inicialmente, das bases estrat\u00e9gicas deste novo mundo multipolar, come\u00e7ando pela defini\u00e7\u00e3o de algumas de suas linhas vermelhas intranspon\u00edveis comumente aceitas, no Oriente M\u00e9dio, no Pac\u00edfico, no Atl\u00e2ntico, e na pr\u00f3pria Europa. Mas nesse momento, esta possibilidade depende quase inteiramente da capacidade do presidente norte-americano se impor frente \u00e0 figura conspirat\u00f3ria, fan\u00e1tica e belicista do seu s\u00f3cio Benjamin Netanyahu. Isto ser\u00e1 poss\u00edvel? Sim, \u00e9 poss\u00edvel, ainda que seja pouco prov\u00e1vel.<\/p>\n<div>\n<div><imgsrc=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/05\/circuito3anos-banner_outraspalavras-2.jpg\" alt=\"\" srcset=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/05\/circuito3anos-banner_outraspalavras-2.jpg 729w, https:\/\/estaticos.opara.me\/outraspalavras\/uploads\/2022\/06\/01180420\/circuito3anos-banner_outraspalavras-300x37.jpg 300w\" sizes=\"(max-width: 729px) 100vw, 729px\" width=\"729\" height=\"90\"><\/div>\n<\/div>\n<div>\n<div>\n<p><span><em>Outras Palavras \u00e9 feito por muitas m\u00e3os. Se voc\u00ea valoriza nossa produ\u00e7\u00e3o, seja nosso apoiador e fortale\u00e7a o jornalismo cr\u00edtico: <strong>apoia.se\/outraspalavras<\/strong><\/em><\/span><\/p>\n<\/div>\n<\/div>\n<p>The post O paradoxo de Ormuz appeared first on Outras Palavras.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/sorocaba-recebe-encontro-para-fortalecer-agricultura-familiar-e-seguranca-alimentar-em-sp\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Sorocaba recebe encontro para fortalecer agricultu...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/moraes-pede-sessao-extra-para-julgar-bolsonaro-e-nucleo-crucial-em-semana-decisiva\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Moraes pede sess\u00e3o extra para julgar Bolsonaro e \u201c...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/lula-alerta-para-fragilidade-da-al-e-defende-integracao-no-panama-em-discurso-recheado-de-recados-a-trump-video-texto\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Lula alerta para fragilidade da AL e defende integ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/ctb-anuncia-candidaturas-de-marcio-ayer-para-senado-e-igo-menezes-para-a-alerj\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">CTB anuncia candidaturas de M\u00e1rcio Ayer para Senad...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Desfecho da guerra \u00e9 incerto. Mas fracasso inicial dos EUA e Israel j\u00e1 produz terremoto geopol\u00edtico \u2013 que vai muito al\u00e9m do Oriente M\u00e9dio. Come\u00e7a a surgir uma ordem multipolar. E Trump, o c\u00ednico, pode ser (quem diria?) o primeiro a aceit\u00e1-la<\/p>\n<p>The post <a href=\"https:\/\/outraspalavras.net\/geopoliticaeguerra\/paradoxo-de-ormuz\/\">O paradoxo de Ormuz<\/a> appeared first on <a href=\"https:\/\/outraspalavras.net\/\">Outras Palavras<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":88217,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[37321,5511,292,7326,1023,8650,9,5700,60048,41,25,46346,3508,53,37217,60049,2827,1453],"tags":[],"class_list":["post-88216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ataques-ao-ira","category-capa","category-china","category-crise-do-ocidente","category-donald-trump","category-estreito-de-ormuz","category-eua","category-geopolitica-guerra","category-hegemonia-global","category-ira","category-israel","category-j-d-vance","category-marco-rubio","category-netanyahu","category-ormuz","category-paz-de-ormuz","category-petroleo","category-trump"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/88216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=88216"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/88216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media\/88217"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=88216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=88216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=88216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}