{"id":92668,"date":"2026-06-20T17:20:38","date_gmt":"2026-06-20T20:20:38","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/israel-viola-tregua-lanca-ataque-em-gaza-e-mata-familia-inteira-incluindo-duas-criancas\/"},"modified":"2026-06-20T17:20:38","modified_gmt":"2026-06-20T20:20:38","slug":"israel-viola-tregua-lanca-ataque-em-gaza-e-mata-familia-inteira-incluindo-duas-criancas","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/israel-viola-tregua-lanca-ataque-em-gaza-e-mata-familia-inteira-incluindo-duas-criancas\/","title":{"rendered":"Israel viola tr\u00e9gua, lan\u00e7a ataque em Gaza e mata fam\u00edlia inteira, incluindo duas crian\u00e7as"},"content":{"rendered":"<p>Fontes m\u00e9dicas na Faixa de Gaza informaram neste s\u00e1bado (20\/06) a morte de cinco pessoas, entre elas quatro membros de uma mesma fam\u00edlia, em ataques israelenses, apesar do fr\u00e1gil cessar-fogo em vigor no territ\u00f3rio palestino.<\/p>\n<p>Um dos ataques, ocorrido durante a noite contra um edif\u00edcio no bairro de Sabra, na Cidade de Gaza, matou quatro integrantes da fam\u00edlia al-Safadi, os pais e suas duas filhas, segundo a Defesa Civil, \u00f3rg\u00e3o que atua sob autoridade do Hamas. Doze pessoas tamb\u00e9m ficaram feridas. O hospital Al-Chifa, em Gaza, confirmou ter recebido os corpos de quatro membros da fam\u00edlia al-Safadi, incluindo duas crian\u00e7as.<\/p>\n<p>\u201cPor volta das 2h da manh\u00e3, meus primos estavam dormindo quando um m\u00edssil os atingiu. Eles n\u00e3o t\u00eam liga\u00e7\u00e3o com o Hamas e n\u00e3o est\u00e3o envolvidos em nada. S\u00e3o apenas crian\u00e7as inocentes\u201d, afirmou Nael al-Safadi, parente das v\u00edtimas.<\/p>\n<p>\u201cEu nunca imaginei que isso pudesse acontecer conosco\u201d, disse \u00e0 <em>AFP<\/em> o parente Mohammad al-Safadi, que sobreviveu ao ataque.<\/p>\n<p>Imagens da <em>AFP<\/em> mostram a parede externa do apartamento destru\u00edda pela explos\u00e3o, com escombros, roupas, colch\u00f5es e pertences pessoais espalhados entre os destro\u00e7os.<\/p>\n<figure aria-describedby=\"caption-attachment-258158\"><img fetchpriority=\"high\" decoding=\"async\"src=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/06\/wafaimage-6.jpg\" alt=\"\" width=\"1200\" height=\"807\" srcset=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/06\/wafaimage-6.jpg 1200w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/06\/wafaimage-6-300x202.jpg 300w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/06\/wafaimage-6-1024x689.jpg 1024w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/06\/wafaimage-6-768x516.jpg 768w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/06\/wafaimage-6-150x101.jpg 150w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/06\/wafaimage-6-750x504.jpg 750w, https:\/\/operamundi.uol.com.br\/wp-content\/uploads\/2026\/06\/wafaimage-6-1140x767.jpg 1140w\" sizes=\"(max-width: 1200px) 100vw, 1200px\"><figcaption>Cidad\u00e3os transportam um m\u00e1rtir e feridos ap\u00f3s bombardeio israelense<br \/>Foto: WAFA<\/figcaption><\/figure>\n<p>O hospital tamb\u00e9m informou ter recebido o corpo de uma quinta v\u00edtima, ap\u00f3s um ataque separado de drone israelense perto de um cruzamento no norte da Cidade de Gaza.<\/p>\n<p>Procuradas pela <em>AFP<\/em>, as for\u00e7as armadas israelenses n\u00e3o comentaram as informa\u00e7\u00f5es.<\/p>\n<p>Israel e o Hamas trocam acusa\u00e7\u00f5es quase di\u00e1rias de viola\u00e7\u00f5es da tr\u00e9gua em vigor desde outubro do ano passado, enquanto a Faixa de Gaza segue marcada por epis\u00f3dios de viol\u00eancia, sem avan\u00e7os concretos rumo ao fim duradouro da guerra.<\/p>\n<p>Segundo o Minist\u00e9rio da Sa\u00fade do territ\u00f3rio, controlado pelo Hamas, pelo menos 1.012 palestinos foram mortos desde o in\u00edcio do cessar-fogo, n\u00fameros considerados confi\u00e1veis pela ONU. As for\u00e7as israelenses, por sua vez, afirmam ter registrado cinco mortos em suas fileiras no mesmo per\u00edodo.<\/p>\n<p>Restri\u00e7\u00f5es \u00e0 imprensa e o acesso limitado \u00e0 Faixa de Gaza impedem a verifica\u00e7\u00e3o independente dos n\u00fameros e a cobertura livre dos acontecimentos no local.<\/p>\n<p>O post Israel viola tr\u00e9gua, lan\u00e7a ataque em Gaza e mata fam\u00edlia inteira, incluindo duas crian\u00e7as apareceu primeiro em Opera Mundi.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/mercado-dos-eua-tenta-reacao-apos-quedas-e-acende-alerta-para-investidores-brasileiros\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Mercado dos EUA tenta rea\u00e7\u00e3o ap\u00f3s quedas e acende ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/mega-sena-nao-tem-ganhador-premio-sobe-para-r-62-milhoes\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Mega-Sena n\u00e3o tem ganhador; pr\u00eamio sobe para R$ 62...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/documentario-alianca-multietnica-estreia-na-ufpb-e-da-voz-a-luta-indigena-em-contexto-urbano\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-22-at-111044-150x150.jpeg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Document\u00e1rio \u2018Alian\u00e7a Multi\u00e9tnica\u2019 estreia na UFPB...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/teatros-e-espacos-culturais-estao-na-mira-das-demolicoes-pelo-poder-publico-em-sao-paulo\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Teatros e espa\u00e7os culturais est\u00e3o na mira das demo...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Fontes m\u00e9dicas na Faixa de Gaza informaram neste s\u00e1bado (20\/06) a morte de cinco pessoas, entre elas quatro membros de uma mesma fam\u00edlia, em ataques israelenses, apesar do fr\u00e1gil cessar-fogo em vigor no territ\u00f3rio palestino. Um dos ataques, ocorrido durante a noite contra um edif\u00edcio no bairro de Sabra, na Cidade de Gaza, matou quatro [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/operamundi.uol.com.br\/guerra-israel-x-palestina\/israel-viola-tregua-lanca-ataque-em-gaza-e-mata-familia-inteira-incluindo-duas-criancas\/\">Israel viola tr\u00e9gua, lan\u00e7a ataque em Gaza e mata fam\u00edlia inteira, incluindo duas crian\u00e7as<\/a> apareceu primeiro em <a href=\"https:\/\/operamundi.uol.com.br\/\">Opera Mundi<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":92669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[2000,23,3938,997,25,59,54],"tags":[],"class_list":["post-92668","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cessar-fogo","category-guerra","category-guerra-israel-x-palestina","category-hamas","category-israel","category-morte","category-palestina"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/92668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=92668"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/92668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media\/92669"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=92668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=92668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=92668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}