{"id":95278,"date":"2026-07-10T18:48:53","date_gmt":"2026-07-10T21:48:53","guid":{"rendered":"https:\/\/redept.com.br\/blogosfera\/mark-fisher-contra-a-dormencia-perceptiva\/"},"modified":"2026-07-10T18:48:53","modified_gmt":"2026-07-10T21:48:53","slug":"mark-fisher-contra-a-dormencia-perceptiva","status":"publish","type":"post","link":"https:\/\/redept.com.br\/blogosfera\/mark-fisher-contra-a-dormencia-perceptiva\/","title":{"rendered":"Mark Fisher contra a dorm\u00eancia perceptiva"},"content":{"rendered":"<div>\n<figure><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1086\" height=\"652\"src=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/07\/2019_47_mark_fisher.jpg\" alt=\"\" srcset=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/07\/2019_47_mark_fisher.jpg 1086w, https:\/\/outraspalavras.net\/wp-content\/uploads\/2026\/07\/2019_47_mark_fisher-300x180.jpg 300w, https:\/\/outraspalavras.net\/wp-content\/uploads\/2026\/07\/2019_47_mark_fisher-768x461.jpg 768w\" sizes=\"auto, (max-width: 1086px) 100vw, 1086px\"><figcaption>Imagem reproduzida no site da Revista Jacobina<\/figcaption><\/figure>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>\n<h4>Boletim Outras Palavras<\/h4>\n<p>Receba por email, diariamente, todas as publica\u00e7\u00f5es do site<\/p>\n<\/p><\/div>\n<div>\n<div>\n<div>\n<div>\n<div><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n                <button type=\"submit\">Assinar<\/button><br \/>\n                <button disabled type=\"button\"> <\/p>\n<div><\/div>\n<p> <span>Loading&#8230;<\/span> <\/button>\n              <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div>\n            <button type=\"submit\">Assinar<\/button><br \/>\n            <button disabled type=\"button\"> <\/p>\n<div><\/div>\n<p> <span>Loading&#8230;<\/span> <\/button>\n          <\/div>\n<\/p><\/div>\n<div>\n<div>\n<h4>Agradecemos!<\/h4>\n<p>Voc\u00ea j\u00e1 est\u00e1 inscrito e come\u00e7ar\u00e1 a receber os boletins em breve. Boa leitura!<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Trecho extra\u00eddo do livro <strong><em>O estranho e o sinistro<\/em><\/strong>, de <strong>Mark Fisher <\/strong>(Autonomia Liter\u00e1ria, 2026).<\/p>\n<p><strong>Inquieta\u00e7\u00f5es como m\u00e9todo<br \/>Por horizontes est\u00e9tico-pol\u00edticos ainda<br \/>mais estranhos<\/strong><\/p>\n<p><strong><br \/><\/strong>por Rodrigo Gonsalves,<br \/>Victor Marques e Jorge Adeodato<\/p>\n<div>\n<div><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\"src=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/07\/Prancheta--14.png\" alt=\"\" srcset=\"https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2026\/07\/Prancheta--14.png 680w, https:\/\/outraspalavras.net\/wp-content\/uploads\/2022\/12\/Prancheta-4-300x110.png 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" width=\"680\" height=\"250\"><\/div>\n<\/div>\n<p><strong>Sob o signo do assombro<\/strong><\/p>\n<p>H\u00e1 algo de sinistro em <em>The Weird and the Eerie<\/em>, \u00faltimo livro de Mark Fisher, que agora ganha uma edi\u00e7\u00e3o brasileira. Em algum sentido, \u00e9 como se a obra estivesse retrospectivamente assombrada pela presen\u00e7a da aus\u00eancia do autor \u2013 Fisher faleceu no dia 13 de janeiro de 2017, poucos dias depois do lan\u00e7amento do livro. Chama aten\u00e7\u00e3o como, aqui, o pr\u00f3prio tom da escrita de Fisher adquire uma esp\u00e9cie de \u201ccalma sinistra\u201d, de quem caminha lentamente entre ru\u00ednas, atento aos ecos, lacunas e vest\u00edgios de algo que n\u00e3o est\u00e1 mais ali. Quem conhece Fisher apenas por <em>Realismo Capitalista <\/em>pode estranhar: est\u00e3o ausentes n\u00e3o apenas a intensidade fren\u00e9tica de uma escrita acelerada, mas tamb\u00e9m o sentimento de urg\u00eancia diante das quest\u00f5es pol\u00edticas imediatas. Vemos um Fisher meditativo e desapegado, tateando no escuro, sem dire\u00e7\u00e3o aparente, como se houvesse suspendido provisoriamente a necessidade de orientar ou mobilizar. N\u00e3o h\u00e1 li\u00e7\u00f5es ou apelo direto \u00e0 a\u00e7\u00e3o \u2013 nem sequer cr\u00edtica, no significado estrito da palavra. Um livro soturno, deliberadamente inconcluso, redigido sob o signo do assombro, no qual o que domina \u00e9 uma postura de fascina\u00e7\u00e3o e explora\u00e7\u00e3o em rela\u00e7\u00e3o ao \u201cFora\u201d [<em>the outside<\/em>].<\/p>\n<p>Em boa medida, o livro \u00e9 um retorno aos temas de sua tese de doutoramento <em>Flatline Constructs: Gothic Materialism and Cybernetic Theory-Fiction <\/em>(2018) [1995]. Fisher retoma, embora em registro notavelmente distinto, o materialismo g\u00f3tico, o animismo anti-humanista, o interesse por ag\u00eancias impessoais e pela zona de indistin\u00e7\u00e3o entre realidade e fic\u00e7\u00e3o. Em ambas as obras, Fisher est\u00e1 obcecado com o que reside al\u00e9m da percep\u00e7\u00e3o e cogni\u00e7\u00e3o humana ordin\u00e1ria. Mas trata-se de um retorno sem euforia. Se em <em>Flatline <\/em>esses motivos explodiam em chave proliferante, quase man\u00edaca, como se o colapso do sujeito e a autonomiza\u00e7\u00e3o dos circuitos t\u00e9cnicos e narrativos pudessem ser explorados como vetores de ruptura, aqui reaparecem desencantados, frios, privados de qualquer promessa imanente. A experimenta\u00e7\u00e3o agressiva d\u00e1 espa\u00e7o \u00e0 contempla\u00e7\u00e3o cautelosa.<\/p>\n<p>A tese de doutorado aglutinou interesses que orbitavam o grupo de pesquisa CCRU (Unidade de Pesquisa em Cultura Cibern\u00e9tica), do qual Fisher participara ao longo de seus anos de p\u00f3s-gradua\u00e7\u00e3o em Warwick, investigando o cyberpunk e filosofias anti-humanistas sob forte influ\u00eancia de Donna Haraway,<br \/>Deleuze, Baudrillard, Lyotard e Espinosa. Foi ali que Fisher aprendeu a teorizar sobre a cultura, n\u00e3o ao estilo da \u201ccr\u00edtica cultural\u201d cl\u00e1ssica, mas a pensar <em>por meio <\/em>da fic\u00e7\u00e3o, em meio a e com a cultura pop \u2013 engajando-se teoricamente com contos e romances da literatura de l\u00edngua inglesa e cinema hollywoodiano, dedicando-se especialmente aos g\u00eaneros do horror e da fic\u00e7\u00e3o cient\u00edfica. As no\u00e7\u00f5es centrais na tese s\u00e3o o \u201cmaterialismo g\u00f3tico\u201d, desenvolvido de uma perspectiva deleuze-guattariana, e a \u201cteoria-fic\u00e7\u00e3o\u201d, inspirada na hiperfic\u00e7\u00e3o de Baudrillard. O curioso \u00e9 que j\u00e1 ali se pode perceber a preocupa\u00e7\u00e3o com o <em>Unheimliche<sup data-fn=\"bd173d07-aa40-42d7-8020-34a97bc31ff6\">1<\/sup> <\/em>freudiano, em um di\u00e1logo tenso com o fundador da psican\u00e1lise.<\/p>\n<p>De cara, Fisher anuncia que este livro que o leitor agora tem em m\u00e3os \u00e9 uma esp\u00e9cie de acerto de contas com um compromisso por anos adiado. Poder-se-ia dizer que, de maneira t\u00e1cita, o <em>Unheimliche <\/em>\u2013 aquilo que \u201cdeveria ter permanecido em segredo, mas veio \u00e0 superf\u00edcie\u201d, na defini\u00e7\u00e3o que Freud recolhe de Schelling \u2013 sempre rondou o pensamento de Fisher: um certo assombro persistente, que atravessa suas reflex\u00f5es sobre cultura, tecnologia e capitalismo, mas que s\u00f3 aqui ganha um tratamento sistem\u00e1tico. Esse peculiar afeto, como diz Dunker, tem por dimens\u00e3o a experi\u00eancia subjetiva de uma esp\u00e9cie de \u201caltera\u00e7\u00e3o\u201d, expressa no sentimento de uma mudan\u00e7a perturbadora entre o c\u00f4modo e o inc\u00f4modo, familiar e infamiliar, deixando fronteiras desconfortavelmente borradas; trata-se, portanto, de uma manifesta\u00e7\u00e3o peculiar da experi\u00eancia de ang\u00fastia. O retorno, contudo, est\u00e1 longe de ser mera repeti\u00e7\u00e3o. Em<br \/><em>Flatline Constructs<\/em>, o <em>Unheimliche <\/em>aparece sobretudo como um campo de batalha: Fisher l\u00ea Freud como algu\u00e9m que se aproxima da ag\u00eancia do inanimado, da falha na distin\u00e7\u00e3o entre sujeito<br \/>e objeto \u2013 apenas para, no \u00faltimo instante, recuar e reinscrever o estranho no interior da economia ps\u00edquica, neutralizando sua amea\u00e7a ontol\u00f3gica por meio da psicologiza\u00e7\u00e3o. O <em>Unheimliche<\/em> surgia ali como sintoma de uma repress\u00e3o filos\u00f3fica mais ampla: a tentativa de conter, no registro do <em>dentro<\/em>, aquilo que apontava para um fora material, impessoal e inassimil\u00e1vel. Da\u00ed a necessidade de ir \u201cal\u00e9m\u201d do <em>Unheimliche<\/em>. Em O estranho e o sinistro, Fisher est\u00e1 interessado, como Freud, em um tratamento do \u201cestranho\u201d, mas recusa a ideia de reduzi-lo \u00e0 forma do \u201cfamiliar perturbado\u201d \u2013 e resiste a qualquer tentativa de reconduzir o fora ao drama dom\u00e9stico, \u00e0 casa, \u00e0 fam\u00edlia. Trata-se, ao contr\u00e1rio, de explorar modos de estranhamento que n\u00e3o se deixem absorver pelo lar humano.<\/p>\n<p><strong>Dois momentos do <em>Unheimlich <\/em>em Fisher<\/strong><\/p>\n<p>Em <em>Flatline Constructs<\/em>, Fisher j\u00e1 declarava que <em>Das Unheimliche <\/em>havia sido uma esp\u00e9cie de \u201coportunidade desperdi\u00e7ada\u201d em rela\u00e7\u00e3o \u00e0 pot\u00eancia do conceito, e chega a nomear como \u201cdecepcionante\u201d a postura de Freud diante da dimens\u00e3o de seu achado. A frustra\u00e7\u00e3o de Fisher reside no fato de que Freud parece meramente \u201cflertar\u201d com o tema fundamentalmente g\u00f3tico pelo qual ele mesmo se aproximou, central \u00e0 formula\u00e7\u00e3o do materialismo g\u00f3tico, a part\u00edcula negativa que est\u00e1 \u00e0 frente do <em>in-c\u00f4modo<\/em>, do <em>in-familiar<\/em>, do <em>un-heimliche<\/em>. \u00c9 essa negatividade que introduz uma fissura na experi\u00eancia, estrangeirizando a rela\u00e7\u00e3o do sujeito com sua pr\u00f3pria realidade e produzindo o estranhamento n\u00e3o como simples conte\u00fado, mas como forma negativa da experi\u00eancia.<\/p>\n<p>Fisher nota no recuo de Freud um ponto fascinante: h\u00e1 algo na dimens\u00e3o do perturbador, do infamiliar, que acena ao horror. Freud encontra, na part\u00edcula negativa, um caminho para outra forma de oposi\u00e7\u00e3o: que encara os opostos vivo\/morto, convidando-nos a uma outra dimens\u00e3o de negatividade, um <em>continuum <\/em>presente em figuras como a dos mortos-vivos (des-mortos). No entanto, denuncia Fisher, ao se deparar com a radicalidade g\u00f3tica desta dimens\u00e3o inumana, Freud hesita.<\/p>\n<p>Fisher problematiza a compreens\u00e3o das cren\u00e7as animistas freudianas, presentes em <em>Totem <\/em>e <em>Tabu <\/em>[1913], que \u201cse referem \u00e0s camadas mais primitivas da mente, um equivalente ontogen\u00e9tico ao est\u00e1gio filogen\u00e9tico dos \u2018primitivos\u2019\u201d, referindo-se \u00e0 dimens\u00e3o das almas, esp\u00edritos, daquilo que anima o inanimado e subjaz como ac\u00famulo reminiscente da nossa compreens\u00e3o humana acerca de n\u00f3s mesmos. Fisher interroga como Freud n\u00e3o manteve \u201co problema do animismo em cheque\u201d valendo-se da contraposi\u00e7\u00e3o cr\u00edtica de Baudrillard, que indica que a divis\u00e3o freudiana entre o que pertence ao \u201cprimitivo\u201d e aquilo que estaria ao lado da \u201cciviliza\u00e7\u00e3o\u201d s\u00e3o aproxima\u00e7\u00f5es problem\u00e1ticas; soam como sintoma do excesso psicologizante que impera a partir de marcas p\u00f3s-vitorianas de Freud.<\/p>\n<p>Fisher, por seu lado, simplesmente abandona a ideia de \u201canimismo\u201d como um tra\u00e7o arcaico ou infantil, algo que deveria ter sido subsumido no desenvolvimento normal, mas n\u00e3o foi. Mais especificamente, Fisher aponta para o \u201cretorno do animismo em uma era cibern\u00e9tica\u201d, ilustrando com uma an\u00e1lise do filme <em>Toy Story <\/em>a realidade an\u00edmica da organiza\u00e7\u00e3o social capitalista em seus produtos culturais, em que objetos (brinquedos-mercadorias) ganham \u201cvida\u201d: \u201ca ficcionalidade possui aqui um novo sentido, j\u00e1 n\u00e3o tem nada a ver com qualquer intangibilidade fant\u00e1stica; muito pelo contr\u00e1rio, os brinquedos na tela est\u00e3o imediatamente dispon\u00edveis enquanto objetos de consumo, assim que se sai do cinema.\u201d Fisher, assim, desloca o problema para uma zona mais profunda, em que a distin\u00e7\u00e3o interno-externo se embaralha, revelando como os modos de subjetiviza\u00e7\u00e3o contempor\u00e2neos se reorganizam precisamente neste curto-circuito entre exterioridade e interioridade, sob formas renovadas de aliena\u00e7\u00e3o e de interpassividade.<\/p>\n<p>Em \u201cO estranho e o sinistro\u201d, testemunhamos, enfim, a segunda investida de Fisher sobre o territ\u00f3rio do<em> Unheimliche<\/em>. Fisher n\u00e3o retorna a Freud para reiterar o problema, mas para desambigu\u00e1-lo. O mesmo campo de experi\u00eancias inquietantes deixa de ser tratado como dominado por um afeto unit\u00e1rio e passa a ser decomposto em duas modalidades distintas: o <em>weird<\/em> (o estranho fisheriano) e o <em>eerie <\/em>(aqui traduzido por sinistro). Ambas dizem respeito ao <em>strange <\/em>[estranho], e nisso se aproximam do <em>Unheimliche <\/em>freudiano. Fisher sugere, no entanto, que Freud, apesar de tocar algo radicalmente estrangeiro, alien\u00edgena, no <em>Unheimliche<\/em>, acaba por recuar, reinscrevendo essa estranheza no interior da economia ps\u00edquica humana e no drama familiar. \u00c9 o estranho no interior do familiar, da din\u00e2mica do dom\u00e9stica: \u201co estranhamente familiar, o familiar como estranho\u201d. O que seria verdadeiramente estranho \u2013 no sentido de exterior ao humano \u2013 tende, assim, a ser neutralizado. \u201cJ\u00e1 o estranho e o sinistro\u201d, nos conta Fisher, \u201cfazem o movimento oposto: permitem-nos ver o interior da perspectiva do exterior\u201d. O estranho fisheriano \u00e9 justamente aquilo que n\u00e3o pertence, que est\u00e1 al\u00e9m do familiar e que, portanto, n\u00e3o tem como ser abarcado ou conciliado com o \u201ccaseiro\u201d\/\u201cdom\u00e9stico\u201d [<em>homely<\/em>], nem mesmo por meio da sua nega\u00e7\u00e3o. O estranho \u00e9 o fora, o incomensur\u00e1vel em rela\u00e7\u00e3o \u00e0s categorias humanas, \u00edndice do encontro n\u00e3o mediado com o desconhecido, que s\u00f3 \u00e9 experimentado como anomalia: a sensa\u00e7\u00e3o talvez aterrorizante ou mesmo enlouquecedora de que \u201calgo est\u00e1 terrivelmente errado\u201d, de que o mundo n\u00e3o \u00e9 como esper\u00e1vamos que fosse. H\u00e1 aqui uma recusa clara e deliberada a qualquer humanismo reconfortante.<\/p>\n<p>\u00c9 precisamente esse resto n\u00e3o assimilado que Fisher decide perseguir. O \u201cestranho\u201d e o \u201csinistro\u201d operam o movimento inverso ao do <em>Unheimliche<\/em>: em vez de reconduzir o estranho ao familiar, \u00e0 experi\u00eancia subjetiva, trata-se de estar aberto para que o exterior desestabilize o interior, sem reabsor\u00e7\u00e3o dom\u00e9stica poss\u00edvel. O <em>weird <\/em>[estranho] designa a intrus\u00e3o do que deveria permanecer fora e n\u00e3o pode ser encaixado no j\u00e1 familiar. O <em>eerie <\/em>[sinistro], por sua vez, emerge quando a aus\u00eancia ou a presen\u00e7a de ag\u00eancia se torna perturbadora \u2013 quando algo age sem que possamos identificar um agente, ou quando um vazio se imp\u00f5e onde esper\u00e1vamos a\u00e7\u00e3o humana. Em ambos os casos, n\u00e3o se trata de um mero desconforto psicol\u00f3gico, mas de uma falha ontol\u00f3gica: o mundo deixa de confirmar nossas pressuposi\u00e7\u00f5es e expectativas mais b\u00e1sicas.<\/p>\n<p>Com isso, Fisher n\u00e3o apenas reinsere o infamiliar na conversa entre psican\u00e1lise e filosofia, mas pretende avan\u00e7ar para al\u00e9m de Freud, radicalizando a intui\u00e7\u00e3o que o pr\u00f3prio Freud, ao menos segundo Fisher, manteve sob controle. Ancorado nos marcos pr\u00e9vios do materialismo g\u00f3tico, Fisher parece arriscar algo como um <em>Das Unheimliche <\/em>com esta chave g\u00f3tica, privilegiando a particularidade da nega\u00e7\u00e3o radical que ele pr\u00f3prio identifica em Freud, buscando n\u00e3o suprimi-la diante do horror, do absurdismo c\u00f3smico, da dimens\u00e3o do exterior sobre o interior que enfrenta a \u201conipot\u00eancia do pensamento\u201d diante da dimens\u00e3o de um Real, de um ponto de escapat\u00f3ria do pass\u00edvel de ser imaginado ou simbolizado, que invade a experi\u00eancia subjetiva exigindo uma nova reconfigura\u00e7\u00e3o.<\/p>\n<p>Fiel \u00e0 estrat\u00e9gia ensa\u00edstica de Freud, Fisher atravessa uma vasta constela\u00e7\u00e3o de exemplos culturais \u2013 filmes, romances, s\u00e9ries, m\u00fasicas \u2013 mas o faz agora com outro objetivo: n\u00e3o ilustrar um afeto j\u00e1 dado, e sim cartografar modos distintos de estranhamento. O estranho e o sinistro tornam-se, assim, categorias cr\u00edticas capazes de organizar experi\u00eancias contempor\u00e2neas em que o familiar se torna obsoleto, em que o humano perde centralidade e em que for\u00e7as impessoais passam a estruturar o mundo social. Ao formalizar essa desambigua\u00e7\u00e3o, Fisher sela uma de suas contribui\u00e7\u00f5es mais dur\u00e1veis: oferecer instrumentos conceituais para pensar como o Real irrompe \u2013 e assombra \u2013 em um contexto marcado pelos avan\u00e7os brutais e despersonalizantes do realismo capitalista.<\/p>\n<p><strong>por uma est\u00e9tica nada reconfortante<\/strong><\/p>\n<p>O que Fisher avan\u00e7a em rela\u00e7\u00e3o a Freud no que diz respeito ao tratamento te\u00f3rico da est\u00e9tica do horror e do grotesco? <em>Weird<\/em> [estranho], <em>eerie <\/em>[sinistro] e <em>Unheimlich <\/em>[infamiliar] s\u00e3o todos modos do estranho, do inquietante, do que \u00e9 ao mesmo tempo desconfort\u00e1vel e fascinante, do que simultaneamente angustia e seduz. O movimento de Fisher \u00e9 decididamente xenof\u00edlico: onde antes se podia ver um ponto de paralisia perante o assombro, ressalta-se agora precisamente como o local onde a emerg\u00eancia criativa deve se dar. Xenof\u00edlico, portanto, n\u00e3o no sentido de celebrar o estranho como fantasia ou fetichizar a alteridade, mas no sentido mais austero de manter aberta a possibilidade do fora \u2013 do Real que n\u00e3o se deixa traduzir em experi\u00eancia, identidade ou narrativa de reconcilia\u00e7\u00e3o. O <em>fora <\/em>aqui n\u00e3o \u00e9 transcend\u00eancia m\u00edstica, nem promessa redentora; \u00e9 aquilo que resiste ao nosso enquadramento simb\u00f3lico e que, justamente por isso, permanece como condi\u00e7\u00e3o da novidade. Em vez de um ponto de silenciamento, Fisher encontra o local onde o pensamento \u00e9 desafiado \u2013 por assim dizer, retirado de sua \u201czona de conforto\u201d.<\/p>\n<p>N\u00e3o \u00e9 novidade que a composi\u00e7\u00e3o do pensamento de Mark Fisher, desde seu envolvimento com a CCRU, se organiza como um esfor\u00e7o sistem\u00e1tico de diagramar uma \u201cal\u00e7a estranha\u201d entre filosofia e cr\u00edtica cultural, imanentizadas em um mesmo circuito. Em \u201cO estranho e o sinistro\u201d, esse gesto se intensifica: a aten\u00e7\u00e3o de Fisher se volta de modo deliberado para a fic\u00e7\u00e3o cient\u00edfica, o horror, as s\u00e9ries e o cinema, tratados n\u00e3o como simples sintomas culturais ou objetos a serem interpretados, mas como artefatos j\u00e1 carregados de teoria. Ao investigar aquilo que nos assusta, nos perturba ou nos desestabiliza, Fisher mostra como essas produ\u00e7\u00f5es culturais conseguem expressar algo decisivo sobre a nossa pr\u00f3pria configura\u00e7\u00e3o social diante do diferente. O grotesco, o monstruoso, o temer\u00e1rio n\u00e3o s\u00e3o apenas objetos de medo: eles funcionam como espelhos invertidos de nossas disposi\u00e7\u00f5es conservadoras frente \u00e0 alteridade e dos limites estruturais impostos \u00e0 imagina\u00e7\u00e3o radical.<\/p>\n<p>Nesse cen\u00e1rio, a no\u00e7\u00e3o de hipersti\u00e7\u00e3o \u2013 ainda que aqui apenas impl\u00edcita \u2013 ganha novo relevo. O fluxo acelerado e excessivo do desenvolvimento t\u00e9cnico-capitalista, ao impor o consumo como regra de pertencimento e sociabilidade, n\u00e3o \u201cdesencanta\u201d o mundo; ao contr\u00e1rio, lan\u00e7a novos feiti\u00e7os e engendra ag\u00eancias n\u00e3o-humanas. A delega\u00e7\u00e3o sistem\u00e1tica de desejos, satisfa\u00e7\u00f5es e decis\u00f5es a circuitos maqu\u00ednicos e digitais altera profundamente o tecido das intera\u00e7\u00f5es humanas \u2013 ou melhor, das intera\u00e7\u00f5es j\u00e1 parcialmente inumanizadas, convertidas em \u201cpoder alien\u00edgena\u201d sobre os humanos. O estranho e o sinistro funcionam aqui como operadores cr\u00edticos que nos obrigam a conceber outros espa\u00e7os para o estrangeiro e o diferente, abrindo pontos de inflex\u00e3o a partir dos quais se tornam poss\u00edveis est\u00e9ticas-pol\u00edticas da alteridade menos domestic\u00e1veis.<\/p>\n<p>O derradeiro livro de Fisher nos implica em uma travessia por literaturas e imagens que interrompem a dorm\u00eancia perceptiva, for\u00e7ando-nos a perguntar por que certas est\u00e9ticas da estranheza nos incomodam tanto. O percurso de Fisher pelo alien\u00edgena, pelo m\u00e1gico, pelo ins\u00f3lito e pelo esquisito convida a repensar aquilo que fomos ideologicamente treinados a receber com receio, com inc\u00f4modo e com repulsa. Trata-se de uma tentativa de abrir espa\u00e7o para outros modos de estar no mundo. Para Fisher, um dos ant\u00eddotos mais potentes contra a nostalgia repetitiva que estrutura a experi\u00eancia capitalista tardia est\u00e1 na desobstru\u00e7\u00e3o de potenciais de liberdade que j\u00e1 circularam no passado, mas foram bloqueados, esquecidos ou neutralizados. \u00c9 nesse sentido que o refinamento est\u00e9tico entre o estranho e o sinistro n\u00e3o se reduz a uma tipologia afetiva, mas tem consequ\u00eancias metaf\u00edsicas. De alguma maneira, \u00e9 como se esse livro fosse a contribui\u00e7\u00e3o tardia de Fisher ao chamado \u201crealismo especulativo\u201d.<\/p>\n<p>Se a criatividade arquitet\u00f4nica de conceitos \u00e9 uma das caracter\u00edstica mais evidentes de Fisher enquanto pensador, este livro ent\u00e3o evid\u00eancia de maneira cabal esse tra\u00e7o. Um dos casos mais evidentes \u00e9 sua discuss\u00e3o em torno das <em>passagens <\/em>[<em>egress<\/em>] que refere-se \u00e0 sensibilidade ficcional apontada para abertura de portais e caminhos para outros mundos. Fisher defende que uma das consequ\u00eancias da discuss\u00e3o do <em>estranho <\/em>e do <em>sinistro <\/em>est\u00e1 intimamente vinculada \u00e0s suas condi\u00e7\u00f5es de conduzir o pensamento \u00e0s sa\u00eddas para outros mundos. E, muito embora a sua aten\u00e7\u00e3o aos bols\u00f5es temporais, as interdimens\u00f5es, ao liminal integrem seu pensamento desde a CCRU (em meio aos l\u00eamures e aos fantasmas), nesta obra encontramos sua apresenta\u00e7\u00e3o das passagens<sup data-fn=\"201fa1dc-c6ba-4520-a57c-cab90557bc06\">2<\/sup>. Como se esbarr\u00e1ssemos em algo do Real por meio dessas passagens implicando numa transforma\u00e7\u00e3o subjetiva inevit\u00e1vel de inven\u00e7\u00e3o de novas simboliza\u00e7\u00f5es e novos imagin\u00e1rios, pois nada mais pode ser o mesmo.<\/p>\n<p>E a pol\u00edtica nisso tudo? Trata-se de um livro apenas indiretamente pol\u00edtico. O pr\u00f3prio Fisher esteve, at\u00e9 o \u00faltimo momento de sua vida, como demonstram as aulas reunidas em Desejo P\u00f3s-Capitalista e os rascunhos de sua grande obra n\u00e3o-escrita, <em>Acid Communism<\/em>, interessado na \u201cpol\u00edtica a quente\u201d. N\u00e3o \u00e9 segredo que Fisher estava ativamente envolvido com coletivos militantes, empenhado em fazer \u201can\u00e1lise de conjuntura\u201d no calor do momento, engajado em processos de massa \u201cpopulistas\u201d e disputa do senso comum. Mas nada disso transparece, sequer minimamente, em <em>O estranho e o sinistro<\/em>, onde reina o \u201cdesprendimento das urg\u00eancias do cotidiano\u201d e uma serenidade sinistra, como um calafrio ao p\u00e9 da nuca.<\/p>\n<p>Lento e reflexivo, <em>O Estranho e o sinistro <\/em>\u2013 voltamos a enfatizar \u2013 \u00e9 um texto sinistro no sentido rigoroso do termo, seja no estilo, seja no conte\u00fado. E n\u00e3o porque trate do macabro ou do aterrorizante, mas por parecer estar embebido em uma letargia crepuscular, fantasm\u00e1tica, espectral. Fixado em ag\u00eancias et\u00e9reas, n\u00e3o por acaso o capital desponta como entidade eminentemente \u201csinistra\u201d: conjurado do nada, gozando de uma exist\u00eancia n\u00e3o substancial, e ainda assim dotado de mais efic\u00e1cia causal do que qualquer objeto material alegadamente s\u00f3lido. Um verdadeiro \u201cesc\u00e2ndalo metaf\u00edsico\u201d. Como pensar a ag\u00eancia do capital, essa Coisa que n\u00e3o existe de nenhum modo palp\u00e1vel, mas causa tantas consequ\u00eancias? \u00c0 maneira de Fredric Jameson, Fisher mobiliza a est\u00e9tica do sinistro para esbo\u00e7ar um mapeamento cognitivo do capitalismo contempor\u00e2neo, apontando para sua arquitetura invis\u00edvel e os fantasmas que operam em seu sistema operacional, com efeitos bastante concretos.<\/p>\n<p>Mas o sinistro, como nos lembra Fisher, tamb\u00e9m tem sua \u00e9tica. Esse car\u00e1ter assombrado n\u00e3o implica resigna\u00e7\u00e3o, muito menos desespero. Ao comentar o filme <em>Stalker<\/em>, de Andrei Tarkovsky, Fisher fala de uma \u201c\u00e9tica do sinistro\u201d: uma \u00e9tica fundada na humildade diante do desconhecido e na dedica\u00e7\u00e3o paciente \u00e0 sua explora\u00e7\u00e3o. N\u00e3o se trata de conquistar o fora, de domestic\u00e1-lo, mas, bem diferente, de aprender a mover-se nele sem fingir controle \u2013 explorar improvisadamente espa\u00e7os que oferecem tanto aberturas, possibilidades, quanto perigos. Uma \u00e9tica do limite: o Real n\u00e3o tem nenhuma obriga\u00e7\u00e3o de cooperar com nossas expectativas. \u00c0 sua maneira, o livro acaba encarnando tamb\u00e9m uma estranha pedagogia: ensina por exposi\u00e7\u00e3o est\u00e9tica, por treinamento da sensibilidade mais do que por doutrina expl\u00edcita, a suportar a exterioridade sem pressa de assimila\u00e7\u00e3o, a navegar sem dominar. Trata-se de uma fidelidade ao alien\u00edgena enquanto tal, em sua indomestic\u00e1vel irredutibilidade \u2013 uma recusa obstinada de reduzir o fora ao familiar perturbado, de aquecer o mundo com provid\u00eancias f\u00e1ceis.<\/p>\n<p>Construir uma teoria da \u201cprovid\u00eancia material\u201d, ali\u00e1s, era algo que Fisher estava tateando nos seus \u00faltimos anos. A obsess\u00e3o por destino e dobras temporais fica evidente nas p\u00e1ginas que se seguem. Ao lembrar que o sentido arcaico de <em>weird<\/em> \u00e9 \u201cdestino\u201d [<em>fate<\/em>], Fisher comenta que o conceito de destino \u00e9 \u201cestranho\u201d porque envolve formas distorcidas de tempo e causalidade (al\u00e7as estranhas, paradoxos, retroa\u00e7\u00e3o do futuro sobre o passado), mas tamb\u00e9m \u00e9 \u201csinistro\u201d porque suscita a quest\u00e3o da ag\u00eancia, sem contudo resolv\u00ea-la \u2013 quem, afinal, \u00e9 o sujeito que tece a trama do destino? A provid\u00eancia material de Fisher n\u00e3o promete reden\u00e7\u00e3o, nem sentido \u00faltimo. Ou seja, n\u00e3o garante nada, mas rompe com uma concep\u00e7\u00e3o linear de tempo para manter aberto o campo do poss\u00edvel, mesmo em um mundo governado por sistemas maqu\u00ednicos impessoais e sujeitos autom\u00e1ticos. Politicamente, inclui a recusa tanto do fatalismo quanto do voluntarismo: agir n\u00e3o \u00e9 cumprir um destino j\u00e1 tra\u00e7ado, mas intervir em circuitos temporais incertos, produzindo as condi\u00e7\u00f5es pelas quais outros futuros possam tornar-se causalmente eficazes no presente. Em outras palavras, destino n\u00e3o \u00e9 o que simplesmente acontecer\u00e1, mas aquilo que s\u00f3 pode acontecer na medida em que j\u00e1 come\u00e7ou \u2013 de forma virtual, espectral \u2013 a operar.<\/p>\n<p>Um livro anti-populista, portanto. Politicamente desconcertante: n\u00e3o oferece estrat\u00e9gias, n\u00e3o personaliza o poder, n\u00e3o aquece antagonismos. Quem quiser uma teoria que funcione como abrigo, se decepcionar\u00e1. Certamente, n\u00e3o se sentir\u00e1 em casa. Sua interven\u00e7\u00e3o \u00e9, mais que nada, negativa: coloca em quest\u00e3o qualquer pol\u00edtica que precise reduzir a complexidade Impessoal do mundo a narrativas reconfortantes. O estranhamento que ele produz n\u00e3o paralisa, ou, pelo menos, n\u00e3o deveria; sinaliza, e isso sim \u00e9 crucial, que velhas f\u00f3rmulas falharam e que novas formas de organiza\u00e7\u00e3o exigem um pensamento capaz de permanecer no inc\u00f4modo, atur\u00e1-lo, alimentar-se dele. Em suma, o que temos \u00e9 um escrito com apar\u00eancia de inacabado, que aceita n\u00e3o concluir, como se tivesse sido interrompido no meio, sem s\u00edntese, suspenso num espa\u00e7o liminar \u2013 e convidando o leitor a fazer o mesmo.<\/p>\n<p><strong>Refer\u00eancias<\/strong><br \/>Badiou, Alain. 2018. <em>Lacan: anti-philosophy 3<\/em>. Nova York: Columbia University Press.<br \/>Colquhoun, Matt. 2020. <em>Egress: On Mourning, Melancholy and the Fisher-Function<\/em>. Londres: Repeater.<br \/>Fisher, Mark. 2018. <em>Flatline Constructs: Gothic Materialism and Cybernetic Theory-Fiction<\/em>. Nova York: Exmilitary Press.<br \/>Fisher, Mark. 2020. <em>Realismo Capitalista<\/em>. S\u00e3o Paulo: Autonomia Liter\u00e1ria.<br \/>Danto, Elizabeth. 2018. <em>As cl\u00ednicas p\u00fablicas de Freud: Psican\u00e1lise e Justi\u00e7a Social<\/em>, <em>1918-1938<\/em>. S\u00e3o Paulo: Editora Perspectiva.<br \/>Dunker, Christian. Nova York: \u201cAnimismo e Indetermina\u00e7\u00e3o em \u201cDas Unheimliche\u201d\u201d em <em>Obras Incompletas de Sigmund Freud: O Infamiliar<\/em>. Belo Horizonte: Editora Aut\u00eantica, 2019, pp. 199-2018.<br \/>Freud, Sigmund. 2019 [1919] <em>O infamiliar<\/em>. Minas Gerais: Editora Aut\u00eantica.<br \/>Gonsalves, Rodrigo. (2021b). Groundwork for Monstrous Materialism: (in)humanity and the uncanniness of our everyday life.<br \/>Tese de doutoramento em Filosofia pela European Graduate School [no prelo para publica\u00e7\u00e3o pela Editora Routledge em 2025].<br \/>Lacan, Jacques. 1986. <em>Semin\u00e1rio : os escritos t\u00e9cnicos de Freud (1953-1954)<\/em>. Rio de Janeiro: Editora Jorge Zahar.<br \/>Marques, Victor; Gonsalves, Rodrigo. 2020. Contra o cancelamento do futuro: a atualidade de Mark Fisher na crise do neoliberalismo em <em>Capitalismo Realista<\/em>. S\u00e3o Paulo: Autonomia Liter\u00e1ria.<br \/>Parker, Ian; Pav\u00f3n-Cu\u00e9llar, David. 2024. Psican\u00e1lise e Revolu\u00e7\u00e3o. Minas Gerais: Editora Aut\u00eantica.<br \/>Safatle, Vladimir. 2020. <em>Maneiras de inventar mundos<\/em>. Belo Horizonte: Editora Aut\u00eantica.<br \/>Schelling, Friedrich. 1841. Philosophie der Mythologie, in Ausgew\u00e4hlte Schriften, hg. v. Manfred Frank (Frankfurt\/Main: Suhrkamp, 1985), VI, S. 661.<\/p>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<\/p>\n<ol>\n<li>O <em>unheimlich <\/em>\u00e9 um operador psicanal\u00edtico profundamente prof\u00edcuo ao pensamento cr\u00edtico. Optamos por n\u00e3o traduzir o termo em alem\u00e3o ao longo do livro \u2013 n\u00e3o por um elitismo academicista, mas para<br \/>sustentar o texto original de Fisher, que o mant\u00e9m tamb\u00e9m em sua forma original, e em respeito \u00e0s muitas tradu\u00e7\u00f5es j\u00e1 consagradas em portugu\u00eas. Em 1919, Freud escreve <em>Das Unheimliche<\/em>, dedicado<br \/>ao sentimento de \u201cinc\u00f4modo\u201d (2020), \u201cinfamiliaridade\u201d (2019), \u201cinquieta\u00e7\u00e3o\u201d (2010), \u201cestranheza\u201d, entre outras vers\u00f5es em l\u00edngua portuguesa. Para al\u00e9m da falta de consenso tradut\u00f3rio claro, o operador <em>unheimlich <\/em>atua na psican\u00e1lise como contribui\u00e7\u00e3o metodol\u00f3gica, versando sobre as dimens\u00f5es dial\u00e9ticas dentro\/fora, escondido\/revelado, p\u00fablico\/privado (entre tantas outras modalidades de sua express\u00e3o) nas experi\u00eancias humanas, que incidem em variadas dimens\u00f5es e variados graus de ang\u00fastia. O <em>unheimlich <\/em>\u00e9 um m\u00e9todo de organiza\u00e7\u00e3o da escuta cl\u00ednica diante do que carece de simboliza\u00e7\u00e3o (Dunker, C. I. L. Animismo e indetermina\u00e7\u00e3o em \u201cDas Unheimliche\u201d. Em: <em>Obras incompletas de Sigmund Freud: o infamiliar<\/em>. Belo Horizonte: Editora Aut\u00eantica, 2019, p. 199\u2013218; Gonsalves, R. Os desdobramentos do infamiliar em Freud e Lacan. Disserta\u00e7\u00e3o (Mestrado em Psicologia Cl\u00ednica) \u2013 Universidade de S\u00e3o Paulo, S\u00e3o Paulo, 2021; Gonsalves, R. Groundwork for monstrous materialism: (in)humanity and the uncanniness of our everyday life. Tese (Doutorado em Filosofia) \u2013 European Graduate School, SaasFee, Su\u00ed\u00e7a, 2021). Ver mais em: Gonsalves, R. O unheimlich e o paradigma est\u00e9tico-pol\u00edtico contempor\u00e2neo: metodologia e reflex\u00f5es acerca das implica\u00e7\u00f5es inumanas da vida cotidiana: the unheimlich and the contemporary aesthetic-political paradigm: methodology and thoughts on the inhuman implications of our everyday life.<br \/>Simbi\u00f3tica: Revista Eletr\u00f4nica, v. 11, n. 1, p. 92\u2013110, 2024. Dispon\u00edvel em: https:\/\/doi.org\/10.47456\/simbiotica.v11i.144758. \ufe0e<\/li>\n<\/ol>\n<div>\n<div>\n<p><span><em>Outras Palavras \u00e9 feito por muitas m\u00e3os. Se voc\u00ea valoriza nossa produ\u00e7\u00e3o, contribua com um PIX para <strong>outrosquinhentos@outraspalavras.net<\/strong> e fortale\u00e7a o jornalismo cr\u00edtico.<\/em><\/span><\/p>\n<\/div>\n<\/div>\n<p>The post Mark Fisher contra a dorm\u00eancia perceptiva appeared first on Outras Palavras.<\/p>\n<!-- Begin Yuzo --><div class='yuzo_related_post style-1'  data-version='5.12.89'><!-- without result --><div class='yuzo_clearfixed yuzo__title yuzo__title'><h3>Related Post<\/h3><\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/tailandia-intensifica-ataques-contra-camboja-em-meio-as-negociacoes-para-tregua\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.com.br\/blogosfera\/wp-content\/uploads\/2025\/12\/03_prasat_preah_vihear-nx-06491-150x150.jpg') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Tail\u00e2ndia intensifica ataques contra Camboja em me...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/em-genebra-forum-da-onu-recoloca-o-combate-ao-racismo-estrutural-no-centro-da-agenda-global\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Em Genebra, F\u00f3rum da ONU recoloca o combate ao rac...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/padilha-avalia-ir-a-nova-york-para-assembleias-da-onu-e-opas\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Padilha avalia ir a Nova York para assembleias da ...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t  <div class=\"relatedthumb \" style=\"width:125px;float:left;overflow:hidden;\">  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <a  href=\"https:\/\/redept.com.br\/blogosfera\/paises-amazonicos-nao-precisam-de-intervencoes-estrangeiras-diz-lula\/\"  >\n\t\t\t\t\t\t\t\t\t  <div class=\"yuzo-img-wrap \" style=\"width: 125px;height:90px;\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"yuzo-img\" style=\"background:url('https:\/\/redept.org\/blogosfera\/wp-content\/plugins\/yuzo-related-post\/assets\/images\/default.png') 50% 50% no-repeat;width: 125px;height:90px;margin-bottom: 5px;background-size: cover; \"><\/div>\n\t\t\t\t\t\t\t\t\t  <\/div>\n\t\t\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t\t   <span class=\"yuzo__text--title\" style=\"font-size:13px;\">Pa\u00edses amaz\u00f4nicos n\u00e3o precisam de interven\u00e7\u00f5es est...<\/span>\n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  \n\t\t\t\t\t\t\t  <\/a>\n\n\t\t\t\t\t\t  <\/div>\n<\/div> <script>\n\t\t\t\t\t\t  jQuery(document).ready(function( $ ){\n\t\t\t\t\t\t\t\/\/jQuery('.yuzo_related_post').equalizer({ overflow : 'relatedthumb' });\n\t\t\t\t\t\t\tjQuery('.yuzo_related_post .yuzo_wraps').equalizer({ columns : '> div' });\n\t\t\t\t\t\t   })\n\t\t\t\t\t\t  <\/script> <!-- End Yuzo :) -->","protected":false},"excerpt":{"rendered":"<p>Em sua \u00faltima obra, agora lan\u00e7ada no Brasil, autor busca conectar filosofia e cultura pop. Navegando entre o cinema de Kubrick e as p\u00e1ginas de Lovecraft, livro transforma os subg\u00eaneros de fic\u00e7\u00e3o cient\u00edfica e horror em ricas fontes de an\u00e1lise para pensar o estado de apatia social<\/p>\n<p>The post <a href=\"https:\/\/outraspalavras.net\/crise-civilizatoria\/mark-fisher-contra-a-dormencia-perceptiva\/\">Mark Fisher contra a dorm\u00eancia perceptiva<\/a> appeared first on <a href=\"https:\/\/outraspalavras.net\/\">Outras Palavras<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"fifu_image_url":"","fifu_image_alt":"","footnotes":""},"categories":[62923,2687,17059,15826,309,73872,74532,6799,8247],"tags":[],"class_list":["post-95278","post","type-post","status-publish","format-standard","hentry","category-abordagens-culturais","category-crise-civilizatoria","category-critica","category-critica-cultural","category-cultura","category-cultura-pop","category-fisher","category-mark-fisher","category-realismo-capitalista"],"_links":{"self":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/95278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/comments?post=95278"}],"version-history":[{"count":0,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/posts\/95278\/revisions"}],"wp:attachment":[{"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/media?parent=95278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/categories?post=95278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/redept.com.br\/blogosfera\/wp-json\/wp\/v2\/tags?post=95278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}